{"id":198771,"date":"2019-01-07T07:30:40","date_gmt":"2019-01-07T09:30:40","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=198771"},"modified":"2019-01-07T11:57:55","modified_gmt":"2019-01-07T13:57:55","slug":"lobby-aberto-com-bolsonaro-quer-o-que-e-em-que-condicoes","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/lobby-aberto-com-bolsonaro-quer-o-que-e-em-que-condicoes\/","title":{"rendered":"Lobby aberto com Bolsonaro. Quer o que e em que condi\u00e7\u00f5es"},"content":{"rendered":"<p>Na semana em que o ministro da Casa Civil, Onyx Lorenzoni, exonerou 320 servidores em cargos de confian\u00e7a com o argumento de que seria preciso &#8220;despetizar&#8221; o governo, o ministro da Transpar\u00eancia e Controladoria-Geral da Uni\u00e3o, Wagner Ros\u00e1rio, apresentou ao presidente Jair Bolsonaro uma proposta de decreto para fixar crit\u00e9rios m\u00ednimos para a ocupa\u00e7\u00e3o de cargos comissionados. Os requisitos incluem experi\u00eancia na \u00e1rea, tempo de atua\u00e7\u00e3o no servi\u00e7o p\u00fablico e forma\u00e7\u00e3o acad\u00eamica. Al\u00e9m disso, o profissional n\u00e3o poderia estar em situa\u00e7\u00e3o de inelegibilidade ou de conflito de interesses.<\/p>\n<p>Essa \u00e9 uma das medidas que a CGU defende para os 100 primeiros dias do governo Bolsonaro &#8211; os ministros t\u00eam encaminhado as prioridades de suas pastas ao Pal\u00e1cio do Planalto. A regulamenta\u00e7\u00e3o do lobby no Executivo \u00e9 outra proposta elaborada por Ros\u00e1rio, mas que ainda ser\u00e1 analisada pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, antes de ser enviada ao Planalto (mais informa\u00e7\u00f5es nesta p\u00e1gina).<\/p>\n<p>O texto que trata dos comissionados, j\u00e1 encaminhado para a Secretaria de Assuntos Jur\u00eddicos da Casa Civil, estabelece exig\u00eancias que variam de acordo com o n\u00edvel do cargo de Dire\u00e7\u00e3o e Assessoramento Superior (DAS) e da Fun\u00e7\u00e3o Comissionada do Poder Executivo (FCPE). Se aceito, o decreto s\u00f3 ter\u00e1 validade a partir da publica\u00e7\u00e3o no Di\u00e1rio Oficial da Uni\u00e3o, por isso, n\u00e3o abrangeria assessores nomeados antes disso para o governo.<\/p>\n<p>Para os cargos de DAS mais elevados (n\u00edveis 5 e 6), com sal\u00e1rios que chegam a R$ 16,2 mil, \u00e9 preciso cumprir pelo menos um desses requisitos: ter quatro anos de experi\u00eancia na \u00e1rea, j\u00e1 ter ocupado cargo em comiss\u00e3o por, no m\u00ednimo, tr\u00eas anos ou possuir t\u00edtulo de especialista, mestre ou doutor na \u00e1rea.<\/p>\n<p>Nos cargos de DAS 1, 2 e 3, os crit\u00e9rios s\u00e3o aprova\u00e7\u00e3o em concurso p\u00fablico, tr\u00eas anos de experi\u00eancia m\u00ednima na \u00e1rea de atua\u00e7\u00e3o ou ocupa\u00e7\u00e3o de outro cargo em comiss\u00e3o por no m\u00ednimo dois anos. Uma outra op\u00e7\u00e3o \u00e9 possuir o t\u00edtulo de especialista, mestre ou doutor.<\/p>\n<p>Mesmo antes da posse, integrantes do governo j\u00e1 diziam que 30% dos cargos em comiss\u00e3o seriam cortados. Questionado se a m\u00e1quina p\u00fablica n\u00e3o pararia com esse enxugamento, Onyx tem afirmado que houve aparelhamento do Estado nos quase 14 anos em que o PT comandou o Pa\u00eds. Mas ele nega que haver\u00e1 uma esp\u00e9cie de &#8220;ca\u00e7a \u00e0s bruxas&#8221;.<\/p>\n<p>Os 23 mil cargos comissionados da Presid\u00eancia da Rep\u00fablica e dos minist\u00e9rios custam cerca 0,4% da folha de pagamento de servidores ativos e inativos do governo federal. Entre os ocupantes dos cargos de confian\u00e7a, est\u00e3o presidentes, diretores, coordenadores, chefes e assessores dos principais \u00f3rg\u00e3os e programas do governo federal.<\/p>\n<p>Hip\u00f3teses enquadradas pela lei de conflito de interesses tamb\u00e9m levariam \u00e0 proibi\u00e7\u00e3o para assumir cargo de confian\u00e7a no governo federal. Um exemplo \u00e9 a nomea\u00e7\u00e3o de parentes de at\u00e9 terceiro grau. &#8220;Eu, por exemplo, n\u00e3o posso colocar minha m\u00e3e ou meu pai em um cargo ligado a mim&#8221;, disse Ros\u00e1rio ao jornal.<\/p>\n<p>Haveria uma brecha para indica\u00e7\u00e3o a cargos de secret\u00e1rios ou de ministros. &#8220;\u00c9 uma coisa que n\u00e3o existia at\u00e9 hoje. Vai trazer crit\u00e9rios mais t\u00e9cnicos e melhorar a qualidade do servidor p\u00fablico que ocupa cargos na administra\u00e7\u00e3o p\u00fablica, trazendo maior efici\u00eancia. Isso est\u00e1 completamente aderente ao que o presidente Bolsonaro est\u00e1 propondo&#8221;, afirmou Ros\u00e1rio.<\/p>\n<p>O ministro disse que apresentar\u00e1 a proposta tamb\u00e9m aos outros colegas na reuni\u00e3o ministerial desta ter\u00e7a-feira, dia 8, no Planalto. A &#8220;Agenda de Governo&#8221;, divulgada por Bolsonaro ainda no per\u00edodo de transi\u00e7\u00e3o, prev\u00ea todas as ter\u00e7as-feiras, \u00e0s 10h, reuni\u00e3o do Conselho de Governo &#8211; composto pelos ministros, presidente e vice-presidente.<\/p>\n<p>J\u00e1 existem regras que priorizam a ocupa\u00e7\u00e3o de cargos de DAS por servidores que ingressaram na carreira por meio de concurso p\u00fablico. No m\u00ednimo, 50% das vagas comissionadas devem ir para servidores efetivos. O porcentual aumenta para 60% se o cargo \u00e9 de DAS 5 ou 6, mais elevados e mais bem remunerados.<\/p>\n<p>O ministro Wagner Ros\u00e1rio pretende apresentar decreto para regulamentar e fiscalizar o lobby no Executivo. Segundo ele, a ideia \u00e9 que a representa\u00e7\u00e3o de interesses institucionais e governamentais traga regras claras para divulga\u00e7\u00e3o de informa\u00e7\u00f5es oficiais. O texto estabelece pontos que dever\u00e3o constar da divulga\u00e7\u00e3o dos dados, como com quem o agente p\u00fablico se reuniu, qual o objetivo e sobre quais temas conversaram.<\/p>\n<p>Segundo ele, foram observados os normativos internacionais que recomendam a regulamenta\u00e7\u00e3o do lobby e um dos modelos estudados foi a experi\u00eancia do Chile. &#8220;Estamos fazendo uma norma que traz mais transpar\u00eancia a essas informa\u00e7\u00f5es e regras para a rela\u00e7\u00e3o entre o p\u00fablico e privado.&#8221;<\/p>\n<p>Tamb\u00e9m ser\u00e3o estabelecidas regras para recebimento de presentes. Como exemplo, Ros\u00e1rio diz que um servidor respons\u00e1vel por assinatura de contratos com uma empresa n\u00e3o pode receber um presente dela, exceto se tiver valores m\u00f3dicos, como um calend\u00e1rio.<\/p>\n<p>Embora esteja pronto, o texto foi encaminhado ao ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, para sugest\u00f5es. Em recente declara\u00e7\u00e3o, Moro se mostrou a favor da regulamenta\u00e7\u00e3o do lobby, como uma medida de combate \u00e0 corrup\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na semana em que o ministro da Casa Civil, Onyx Lorenzoni, exonerou 320 servidores em cargos de confian\u00e7a com o argumento de que seria preciso &#8220;despetizar&#8221; o governo, o ministro da Transpar\u00eancia e Controladoria-Geral da Uni\u00e3o, Wagner Ros\u00e1rio, apresentou ao presidente Jair Bolsonaro uma proposta de decreto para fixar crit\u00e9rios m\u00ednimos para a ocupa\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-198771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=198771"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198771\/revisions"}],"predecessor-version":[{"id":198774,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198771\/revisions\/198774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198772"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=198771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=198771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=198771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}