{"id":198817,"date":"2019-01-07T12:50:11","date_gmt":"2019-01-07T14:50:11","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=198817"},"modified":"2019-01-07T16:48:04","modified_gmt":"2019-01-07T18:48:04","slug":"acabou-o-amigo-do-rei-chegou-a-vez-dos-suditos-diz-bolsonaro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/acabou-o-amigo-do-rei-chegou-a-vez-dos-suditos-diz-bolsonaro\/","title":{"rendered":"Acabou o amigo do rei; chegou a vez dos s\u00faditos, diz Bolsonaro"},"content":{"rendered":"<p>O presidente Jair Bolsonaro disse que a transpar\u00eancia ser\u00e1 marca de seu governo e refor\u00e7ou a miss\u00e3o aos novos dirigentes de bancos estatais que assumiram nesta segunda (7) o comando do Banco do Brasil, da Caixa Econ\u00f4mica e do BNDES. Segundo ele, essa tarefa ter\u00e1 que abranger inclusive atos do passado promovidos pelos \u201camigos do rei\u201d dentro destas institui\u00e7\u00f5es.<\/p>\n<p>\u201cTranspar\u00eancia acima de tudo. Todos os nossos atos ter\u00e3o que ser abertos para o p\u00fablico. E o que aconteceu no passado tamb\u00e9m. N\u00e3o podemos admitir qualquer cl\u00e1usula de confidencialidade pret\u00e9rita. Esses atos e a\u00e7\u00f5es tornar-se-\u00e3o p\u00fablicos\u201d, afirmou.<\/p>\n<p>Bolsonaro destacou que a escolha dos tr\u00eas novos presidentes de bancos foi feita exclusivamente pelo ministro da Economia, Paulo Guedes. Segundo ele, essa liberdade dada a todos os ministros de seu governo inaugura um novo modelo de gest\u00e3o.<\/p>\n<p>\u201cH\u00e1 pouco, o que mais se ouvia era uma verdadeira briga para definir qual partido ficaria com esta ou aquela diretoria de banco\u201d, afirmou o presidente, destacando que essa era uma sinaliza\u00e7\u00e3o clara de que a economia n\u00e3o iria bem. O presidente voltou a alertar sua equipe da responsabilidade de sua administra\u00e7\u00e3o e reiterou: \u201cN\u00f3s n\u00e3o podemos errar\u201d.<\/p>\n<p>Ao retomar a orienta\u00e7\u00e3o para que todo seu governo trabalhe com transpar\u00eancia, Bolsonaro aproveitou o discurso de posse na solenidade, que ocorreu no Pal\u00e1cio do Planalto, para anunciar a democratiza\u00e7\u00e3o de verbas publicit\u00e1rias. O assunto, segundo ele, foi tratado com a equipe econ\u00f4mica.<\/p>\n<p>\u201cNenhum \u00f3rg\u00e3o de imprensa ter\u00e1 direito a mais ou menos daquilo que n\u00f3s viermos a gastar com nossa imprensa. Queremos que cada vez uma imprensa mais fortes e isenta. A imprensa livre \u00e9 a garantia da nossa democracia. Vamos acreditar em voc\u00eas, mas estas verbas n\u00e3o ser\u00e3o mais privilegiadas para a empresa A, B ou C\u201d, disse.<\/p>\n<p>O recado tamb\u00e9m foi transmitido para as organiza\u00e7\u00f5es n\u00e3o governamentais (ONGs) que, de acordo com Bolsonaro, ter\u00e3o o repasse de recursos submetido a um \u201cr\u00edgido controle, para que possamos fazer com que recursos p\u00fablicos sejam melhor utilizados\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro disse que a transpar\u00eancia ser\u00e1 marca de seu governo e refor\u00e7ou a miss\u00e3o aos novos dirigentes de bancos estatais que assumiram nesta segunda (7) o comando do Banco do Brasil, da Caixa Econ\u00f4mica e do BNDES. Segundo ele, essa tarefa ter\u00e1 que abranger inclusive atos do passado promovidos pelos \u201camigos do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-198817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=198817"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198817\/revisions"}],"predecessor-version":[{"id":198820,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198817\/revisions\/198820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198818"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=198817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=198817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=198817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}