{"id":198825,"date":"2019-01-07T16:46:20","date_gmt":"2019-01-07T18:46:20","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=198825"},"modified":"2019-01-08T07:27:15","modified_gmt":"2019-01-08T09:27:15","slug":"leo-pinheiro-entrega-lula-e-quer-da-justica-beneficios-da-lava-jato","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/leo-pinheiro-entrega-lula-e-quer-da-justica-beneficios-da-lava-jato\/","title":{"rendered":"L\u00e9o Pinheiro entrega Lula e quer da Justi\u00e7a benef\u00edcios da Lava Jato"},"content":{"rendered":"<p>O ex-presidente da OAS L\u00e9o Pinheiro pediu em alega\u00e7\u00f5es finais, no \u00e2mbito do processo que envolve as reformas do s\u00edtio de Atibaia, no interior de S\u00e3o Paulo, que sua colabora\u00e7\u00e3o seja reconhecida e que sejam aplicados, &#8216;em grau m\u00e1ximo&#8217;, os benef\u00edcios de delator. No documento, entregue por meio de seus advogados \u00e0 ju\u00edza Gabriela Hardt, da 13.\u00aa Vara Federal de Curitiba, nesta segunda-feira, 7, o empreiteiro reitera que bancou reformas no im\u00f3vel como suposta propina ao ex-presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n<p>O caso envolvendo o s\u00edtio representa a terceira den\u00fancia contra Lula no \u00e2mbito da Opera\u00e7\u00e3o Lava Jato. A entrega das alega\u00e7\u00f5es finais representa a fase final da a\u00e7\u00e3o penal. Ap\u00f3s as manifesta\u00e7\u00f5es derradeiras dos r\u00e9us e do Minist\u00e9rio P\u00fablico Federal, Gabriela Hardt poder\u00e1 sentenciar os r\u00e9us.<\/p>\n<p>Ao longo da a\u00e7\u00e3o e, principalmente, em seu interrogat\u00f3rio, L\u00e9o Pinheiro entregou Lula. Nas alega\u00e7\u00f5es finais, seus advogados afirmam que ele narrou que \u2018todas as despesas da OAS com as reformas no s\u00edtio, tal como ocorreu com os gastos do triplex, seriam abatidas de uma conta corrente de propinas mantida com Jo\u00e3o Vaccari, que agia como representante do Partido dos Trabalhadores\u2019.<\/p>\n<p>\u201cA colabora\u00e7\u00e3o do acusado L\u00e9o Pinheiro foi revestida de espontaneidade. Os esclarecimentos e provas por ele apresentados conduzem a apura\u00e7\u00e3o das infra\u00e7\u00f5es penais descritas na den\u00fancia e revelam aspectos at\u00e9 ent\u00e3o desconhecidos da atua\u00e7\u00e3o e divis\u00e3o de tarefas dos coacusados\u201d, afirmam os advogados Daniel Laufer e Maria Francisca Accioly.<\/p>\n<p>Ainda reiteram que \u2018o ex-presidente Lula n\u00e3o apenas solicitou sigilo sobre as reformas executadas no s\u00edtio em Atibaia\/SP, como tamb\u00e9m sabia que os valores gastos com tais benfeitorias seriam abatidos de uma conta corrente de propinas mantida com Jo\u00e3o Vaccari por for\u00e7a dos contratos com a Petrobr\u00e1s\u2019.<\/p>\n<div id=\"attachment_198827\" style=\"width: 684px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-198827\" class=\" wp-image-198827\" src=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/reforma-sitio-300x162.png\" alt=\"\" width=\"674\" height=\"364\" srcset=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/reforma-sitio-300x162.png 300w, https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/reforma-sitio.png 620w\" sizes=\"auto, (max-width: 674px) 100vw, 674px\" \/><p id=\"caption-attachment-198827\" class=\"wp-caption-text\">Uma das planilhas entregues \u00e0 Justi\u00e7a pelo ex-presidente da OAS<\/p><\/div>\n<p>Os advogados ainda argumentam que o ex-presidente da OAS \u2018ainda juntou provas que atestam a veracidade de seus relatos sobre a conta corrente\u2019. Entre os elementos de corrobora\u00e7\u00e3o apresentados por L\u00e9o Pinheiro, est\u00e3o mensagens referentes a reformas no s\u00edtio.<\/p>\n<p>Segundo a defesa, \u2018outra prova de que os gastos da OAS eram abatidos desta conta corrente de propinas, adv\u00e9m do fato de que as despesas eram devidamente registradas para posterior compensa\u00e7\u00e3o, como se v\u00ea no documento juntado por L\u00e9o Pinheiro, no qual consta como justificativas para os desvios as reformas em Atibaia\/SP\u2019.<\/p>\n<p>Segundo a acusa\u00e7\u00e3o, a Odebrecht, a OAS e tamb\u00e9m a empreiteira Schahin, com o pecuarista Jos\u00e9 Carlos Bumlai, gastaram R$ 1,02 milh\u00e3o em obras de melhorias no s\u00edtio em troca de contratos com a Petrobr\u00e1s. A den\u00fancia inclui ao todo 13 acusados, entre eles executivos da empreiteira e aliados do ex-presidente, at\u00e9 seu compadre, o advogado Roberto Teixeira.<\/p>\n<p>O im\u00f3vel foi comprado no final de 2010, quando Lula deixava a Presid\u00eancia, e est\u00e1 registrado em nome de dois s\u00f3cios dos filhos do ex-presidente, Fernando Bittar \u2013 filho do amigo e ex-prefeito petista de Campinas Jac\u00f3 Bittar \u2013 e Jonas Suassuna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-presidente da OAS L\u00e9o Pinheiro pediu em alega\u00e7\u00f5es finais, no \u00e2mbito do processo que envolve as reformas do s\u00edtio de Atibaia, no interior de S\u00e3o Paulo, que sua colabora\u00e7\u00e3o seja reconhecida e que sejam aplicados, &#8216;em grau m\u00e1ximo&#8217;, os benef\u00edcios de delator. No documento, entregue por meio de seus advogados \u00e0 ju\u00edza Gabriela Hardt, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-198825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=198825"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198825\/revisions"}],"predecessor-version":[{"id":198829,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198825\/revisions\/198829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198826"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=198825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=198825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=198825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}