{"id":198976,"date":"2019-01-09T07:29:55","date_gmt":"2019-01-09T09:29:55","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=198976"},"modified":"2019-01-09T08:31:20","modified_gmt":"2019-01-09T10:31:20","slug":"posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/","title":{"rendered":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro"},"content":{"rendered":"<p>Promessa de campanha do presidente Jair Bolsonaro, a flexibiliza\u00e7\u00e3o das regras para a posse de armas deve ser estabelecida por decreto presidencial na pr\u00f3xima semana, segundo afirmou nesta ter\u00e7a-feira, 8, o ministro da Casa Civil, Onyx Lorenzoni.<\/p>\n<p>A minuta de decreto elaborada e encaminhada ao Pal\u00e1cio do Planalto pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, prev\u00ea esclarecer o que \u00e9 a &#8220;efetiva necessidade&#8221; para posse, que consta na lei como requisito.<\/p>\n<p>Conforme membros do governo que participaram da elabora\u00e7\u00e3o da minuta, a legisla\u00e7\u00e3o atual deixa espa\u00e7o para &#8220;subjetividades&#8221; na hora de avaliar uma solicita\u00e7\u00e3o de posse. A ideia \u00e9 fixar crit\u00e9rios mais objetivos.<\/p>\n<p>Pelo texto do Minist\u00e9rio da Justi\u00e7a, o porte de armas fica de fora do decreto, porque depende de altera\u00e7\u00e3o legislativa, o que teria de passar pelo Congresso para poder vigorar. Na posse, a arma s\u00f3 pode ser mantida em casa ou dentro de estabelecimento comercial. J\u00e1 com o porte, o cidad\u00e3o poderia circular armado nas ruas. Ele tamb\u00e9m defendeu aumentar o limite de armas por cidad\u00e3o<\/p>\n<p>Um dos pontos que j\u00e1 t\u00eam a aprova\u00e7\u00e3o de Moro e do governo, segundo a reportagem apurou, \u00e9 o aumento do prazo de validade da autoriza\u00e7\u00e3o da posse de armas, dos atuais 5 para 10 anos.<\/p>\n<p>Em reuni\u00e3o nesta ter\u00e7a no Planalto, outros ministros apresentaram sugest\u00f5es para o decreto. Entre elas, foi citada a possibilidade de facilitar a posse de armas em zonas rurais para uso pessoal e para defesa em \u00e1reas isoladas. Moro fez uma apresenta\u00e7\u00e3o sobre o texto ao conselho e a costura da vers\u00e3o final ser\u00e1 feita na Secretaria de Assuntos Jur\u00eddicos da Casa Civil.<\/p>\n<p>&#8220;Na reuni\u00e3o, o presidente Bolsonaro chamou a aten\u00e7\u00e3o para todos os compromissos de campanha que ele assumiu e disse que os ministros t\u00eam a tarefa de materializar essas promessas. A posse de armas \u00e9 a primeira delas&#8221;, disse Onyx Lorenzoni.<\/p>\n<p>Na elabora\u00e7\u00e3o da minuta no Minist\u00e9rio da Justi\u00e7a, Moro levou em conta n\u00e3o s\u00f3 os assessores da pasta como tamb\u00e9m um parecer da Pol\u00edcia Federal. O \u00f3rg\u00e3o desempenha o papel de emitir parecer concordando ou n\u00e3o com a concess\u00e3o da licen\u00e7a para ter o equipamento.<\/p>\n<p>Ter a ficha criminal limpa e uma certid\u00e3o de habilita\u00e7\u00e3o t\u00e9cnica para atirar, bem como apresentar exame psicol\u00f3gico, s\u00e3o alguns dos pontos enfatizados no texto. N\u00e3o ser\u00e1 inclu\u00edda nenhuma exig\u00eancia al\u00e9m do que j\u00e1 est\u00e1 previsto na lei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promessa de campanha do presidente Jair Bolsonaro, a flexibiliza\u00e7\u00e3o das regras para a posse de armas deve ser estabelecida por decreto presidencial na pr\u00f3xima semana, segundo afirmou nesta ter\u00e7a-feira, 8, o ministro da Casa Civil, Onyx Lorenzoni. A minuta de decreto elaborada e encaminhada ao Pal\u00e1cio do Planalto pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"tmauthors":[],"class_list":["post-198976","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras\" \/>\n<meta property=\"og:description\" content=\"Promessa de campanha do presidente Jair Bolsonaro, a flexibiliza\u00e7\u00e3o das regras para a posse de armas deve ser estabelecida por decreto presidencial na pr\u00f3xima semana, segundo afirmou nesta ter\u00e7a-feira, 8, o ministro da Casa Civil, Onyx Lorenzoni. A minuta de decreto elaborada e encaminhada ao Pal\u00e1cio do Planalto pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-09T09:29:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-09T10:31:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro\",\"datePublished\":\"2019-01-09T09:29:55+00:00\",\"dateModified\":\"2019-01-09T10:31:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/\"},\"wordCount\":447,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/moro-foto-helvio-romero.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/\",\"name\":\"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/moro-foto-helvio-romero.jpg\",\"datePublished\":\"2019-01-09T09:29:55+00:00\",\"dateModified\":\"2019-01-09T10:31:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/moro-foto-helvio-romero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/moro-foto-helvio-romero.jpg\",\"width\":710,\"height\":473,\"caption\":\"Foto: H\u00e9lvio Romero\\\/Estad\u00e3oConte\u00fado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/","og_locale":"pt_BR","og_type":"article","og_title":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras","og_description":"Promessa de campanha do presidente Jair Bolsonaro, a flexibiliza\u00e7\u00e3o das regras para a posse de armas deve ser estabelecida por decreto presidencial na pr\u00f3xima semana, segundo afirmou nesta ter\u00e7a-feira, 8, o ministro da Casa Civil, Onyx Lorenzoni. A minuta de decreto elaborada e encaminhada ao Pal\u00e1cio do Planalto pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-01-09T09:29:55+00:00","article_modified_time":"2019-01-09T10:31:20+00:00","og_image":[{"width":710,"height":473,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro","datePublished":"2019-01-09T09:29:55+00:00","dateModified":"2019-01-09T10:31:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/"},"wordCount":447,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg","articleSection":["Brasil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/","url":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/","name":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg","datePublished":"2019-01-09T09:29:55+00:00","dateModified":"2019-01-09T10:31:20+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/01\/moro-foto-helvio-romero.jpg","width":710,"height":473,"caption":"Foto: H\u00e9lvio Romero\/Estad\u00e3oConte\u00fado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/posse-de-arma-so-vai-sair-para-quem-justificar-necessidade-diz-moro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Posse de arma s\u00f3 vai sair para quem justificar necessidade, diz Moro"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=198976"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198976\/revisions"}],"predecessor-version":[{"id":198977,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/198976\/revisions\/198977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198372"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=198976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=198976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=198976"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=198976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}