{"id":199132,"date":"2019-01-10T12:15:15","date_gmt":"2019-01-10T14:15:15","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199132"},"modified":"2019-01-10T13:16:59","modified_gmt":"2019-01-10T15:16:59","slug":"marcos-pontes-alfineta-damares-por-misturar-ciencia-com-religiao","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/marcos-pontes-alfineta-damares-por-misturar-ciencia-com-religiao\/","title":{"rendered":"Marcos Pontes alfineta Damares por misturar ci\u00eancia com religi\u00e3o"},"content":{"rendered":"<p>O ministro de Ci\u00eancia e Tecnologia Marcos Pontes rebateu, nesta quinta. 10, as declara\u00e7\u00f5es a ministra da Mulher, Fam\u00edlia e Direitos Humanos, Damares Alves, que aparece em v\u00eddeo afirmando que a igreja evang\u00e9lica perdeu espa\u00e7o na Hist\u00f3ria ao &#8220;deixar&#8221; a Teoria da Evolu\u00e7\u00e3o entrar nas escolas sem ser questionada.<\/p>\n<p>&#8220;Ela deve ter falado isso em algum tipo de contexto que eu n\u00e3o sei exatamente&#8221;, disse Pontes, em entrevista \u00e0 CBN. &#8220;Mas, do ponto de vista da ci\u00eancia, s\u00e3o muitas d\u00e9cadas de estudo para formar a teoria da evolu\u00e7\u00e3o desde o in\u00edcio. Ou seja, n\u00e3o se deve misturar ci\u00eancia com religi\u00e3o.&#8221;<\/p>\n<p>No v\u00eddeo, sem data de identifica\u00e7\u00e3o, Damares fala: &#8220;A Igreja Evang\u00e9lica perdeu espa\u00e7o na Hist\u00f3ria. N\u00f3s perdemos o espa\u00e7o na ci\u00eancia quando n\u00f3s deixamos a teoria da evolu\u00e7\u00e3o entrar nas escolas, quando n\u00f3s n\u00e3o questionamos. E a\u00ed os cientistas tomaram conta dessa \u00e1rea.&#8221;<\/p>\n<p>Em nota enviada \u00e0 TV Globo, a pasta comandada por Damares informou que &#8220;o Minist\u00e9rio da Mulher, Fam\u00edlia e dos Direitos Humanos informa que a declara\u00e7\u00e3o ocorreu no contexto de uma exposi\u00e7\u00e3o teol\u00f3gica e n\u00e3o tem qualquer rela\u00e7\u00e3o com as pol\u00edticas p\u00fablicas que ser\u00e3o fomentadas por este minist\u00e9rio. N\u00e3o h\u00e1 rela\u00e7\u00e3o entre a atua\u00e7\u00e3o da titular desta pasta como l\u00edder religiosa e suas fun\u00e7\u00f5es como gestora p\u00fablica.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro de Ci\u00eancia e Tecnologia Marcos Pontes rebateu, nesta quinta. 10, as declara\u00e7\u00f5es a ministra da Mulher, Fam\u00edlia e Direitos Humanos, Damares Alves, que aparece em v\u00eddeo afirmando que a igreja evang\u00e9lica perdeu espa\u00e7o na Hist\u00f3ria ao &#8220;deixar&#8221; a Teoria da Evolu\u00e7\u00e3o entrar nas escolas sem ser questionada. &#8220;Ela deve ter falado isso em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199132"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199132\/revisions"}],"predecessor-version":[{"id":199134,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199132\/revisions\/199134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199133"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}