{"id":199356,"date":"2019-01-13T09:34:25","date_gmt":"2019-01-13T11:34:25","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199356"},"modified":"2019-01-13T12:13:44","modified_gmt":"2019-01-13T14:13:44","slug":"sitio-ape-e-terreno-podem-render-mais-36-anos-de-cadeia-para-lula","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/sitio-ape-e-terreno-podem-render-mais-36-anos-de-cadeia-para-lula\/","title":{"rendered":"S\u00edtio, ap\u00ea e terreno podem render mais 36 anos de cadeia para Lula"},"content":{"rendered":"<p>Na mesa da ju\u00edza federal Gabriela Hardt &#8211; substituta de S\u00e9rgio Moro na 13.\u00aa Vara Federal de Curitiba &#8211; est\u00e3o dois processos da Opera\u00e7\u00e3o Lava Jato contra o ex-presidente Luiz In\u00e1cio Lula da Silva que podem ter senten\u00e7as at\u00e9 abril, quando o petista completa um ano de pris\u00e3o.<\/p>\n<p>Em caso de condena\u00e7\u00f5es, os dois processos que podem, segundo investigadores e advogados, triplicar a pena de pris\u00e3o de Lula s\u00e3o o da compra de um terreno para o Instituto Lula em S\u00e3o Paulo, e de um apartamento em S\u00e3o Bernardo do Campo e o do s\u00edtio em Atibaia (SP). Em ambos, o petista \u00e9 acusado de receber propina de empreiteiras por meio dos im\u00f3veis em troca de contratos da Petrobr\u00e1s.<\/p>\n<p>O caso do terreno deve ser o primeiro a ser julgado. Est\u00e1 conclu\u00eddo para senten\u00e7a desde 12 de dezembro. A a\u00e7\u00e3o do s\u00edtio chegou para a ju\u00edza substituta na semana passada e pode ser julgada pelo magistrado que ocupar\u00e1 a vaga de titular deixada por Moro.<\/p>\n<p>Investigadores da Lava Jato e advogados que atuam nos processos consideram o acervo de provas dessas a\u00e7\u00f5es mais robusto que o da primeira senten\u00e7a, em que Lula foi condenado por Moro em julho de 2017, no caso do triplex do Guaruj\u00e1 (SP). O ent\u00e3o juiz sentenciou o ex-presidente a 9 anos e 6 meses de pris\u00e3o &#8211; posteriormente, a pena foi aumentada na segunda inst\u00e2ncia para 12 anos e 1 m\u00eas.<\/p>\n<p>Uma das provas desse acervo \u00e9 a dela\u00e7\u00e3o da Odebrecht, que ser\u00e1 usada pela primeira vez na Justi\u00e7a contra Lula. O material re\u00fane e-mails do empres\u00e1rio Marcelo Odebrecht, planilhas &#8211; entre elas a &#8220;Italiano&#8221;, referente a uma conta &#8220;gerenciada&#8221; pelo ex-ministro e delator Antonio Palocci -, registros cont\u00e1beis do Setor de Opera\u00e7\u00f5es Estruturadas da Odebrecht, como era chamado o &#8220;departamento de propinas&#8221; da empreiteira, e as confiss\u00f5es dos 77 executivos e ex-executivos da empresa.<\/p>\n<p>Nos arquivos do MyWebDay e Drousys &#8211; programas de computador que serviram para controle cont\u00e1bil e de comunica\u00e7\u00e3o de despesas il\u00edcitas da Odebrecht &#8211; est\u00e3o boa parte das transa\u00e7\u00f5es que teriam Lula &#8211; identificado como &#8220;Amigo&#8221; nos registros da empresa &#8211; como benefici\u00e1rio de corrup\u00e7\u00e3o.<\/p>\n<p>Outro material apontado como prova contra Lula nos processos s\u00e3o os registros de custeio e montagem da cozinha do s\u00edtio de Atibaia pela OAS. S\u00e3o notas fiscais, projetos, e-mails e presta\u00e7\u00f5es de contas os envolvidos. Esse mesmo tipo de material foi usado na senten\u00e7a do ex-presidente no caso do tr\u00edplex.<\/p>\n<p>O acervo, segundo investigadores, conta ainda com contratos e recibos &#8220;simulados&#8221;, lan\u00e7amentos cont\u00e1beis de pagamentos que teriam ocultado propinas, e-mails, anota\u00e7\u00f5es, liga\u00e7\u00f5es telef\u00f4nicas, confiss\u00f5es de colaboradores, laudos periciais, entre outros, que comprovariam o envolvimento de Lula na corrup\u00e7\u00e3o na Petrobr\u00e1s.<\/p>\n<p>Nas alega\u00e7\u00f5es finais dos dois processos em que pede a condena\u00e7\u00e3o de Lula, o Minist\u00e9rio P\u00fablico Federal disse ter apresentado &#8220;vasto, s\u00f3lido e coeso acervo probat\u00f3rio&#8221;. Lista &#8220;provas documentais, testemunhais e periciais, inclusive obtidas em dilig\u00eancias de busca e apreens\u00e3o ou afastamento de sigilo banc\u00e1rio, fiscal e telem\u00e1tico&#8221;.<\/p>\n<p>Os procuradores anexaram ainda documentos que, segundo a for\u00e7a-tarefa, indicam que Lula atuou em 2009 para garantir a &#8220;perpetua\u00e7\u00e3o (do esquema), deixando de adotar qualquer provid\u00eancia para faz\u00ea-lo cessar&#8221;. Os processos apontam acerto de cerca de R$ 230 milh\u00f5es em propinas da Odebrecht e da OAS com pol\u00edticos e agentes p\u00fablicos ligados ao PT.<\/p>\n<p>A defesa de Lula sustenta que a indica\u00e7\u00e3o de diretores da Petrobr\u00e1s estava relacionada ao papel de Lula como presidente, n\u00e3o de &#8220;l\u00edder ou sequer participante de um esquema criminoso&#8221;. Segundo os advogados, n\u00e3o h\u00e1 provas de que ele \u00e9 o dono do s\u00edtio e o im\u00f3vel, comprovadamente, pertence a Fernando Bittar e Jonas Suassuna.<\/p>\n<p>&#8220;N\u00e3o sendo dono, n\u00e3o \u00e9 o benefici\u00e1rio das benfeitorias &#8221; Contesta ainda provas de que o petista teve envolvimento direto com a compra do terreno destinado ao instituto.<\/p>\n<p>Os advogados apontam supostas nulidades do processo e pedem a absolvi\u00e7\u00e3o do petista. Nas alega\u00e7\u00f5es finais do processo do s\u00edtio, a defesa dedica um cap\u00edtulo \u00e0 parte ao aceite de Moro para chefiar o Minist\u00e9rio da Justi\u00e7a do governo Jair Bolsonaro. Para os defensores, nem o ex-juiz nem Gabriela Hardt t\u00eam imparcialidade para julgar o petista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na mesa da ju\u00edza federal Gabriela Hardt &#8211; substituta de S\u00e9rgio Moro na 13.\u00aa Vara Federal de Curitiba &#8211; est\u00e3o dois processos da Opera\u00e7\u00e3o Lava Jato contra o ex-presidente Luiz In\u00e1cio Lula da Silva que podem ter senten\u00e7as at\u00e9 abril, quando o petista completa um ano de pris\u00e3o. Em caso de condena\u00e7\u00f5es, os dois processos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":183310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199356"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199356\/revisions"}],"predecessor-version":[{"id":199359,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199356\/revisions\/199359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/183310"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}