{"id":199421,"date":"2019-01-14T13:45:05","date_gmt":"2019-01-14T15:45:05","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199421"},"modified":"2019-01-14T18:45:44","modified_gmt":"2019-01-14T20:45:44","slug":"bolsonaro-cancela-atos-de-temer-e-esvazia-os-poderes-do-senado","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-cancela-atos-de-temer-e-esvazia-os-poderes-do-senado\/","title":{"rendered":"Bolsonaro cancela atos de Temer e esvazia os poderes do Senado"},"content":{"rendered":"<p>O presidente Jair Bolsonaro revogou, por meio de medida provis\u00f3ria publicada no Di\u00e1rio Oficial da Uni\u00e3o (DOU)desta segunda-feira, 14, a exig\u00eancia de o Senado sabatinar os diretores do Departamento Nacional de Infraestrutura de Transportes (DNIT). Em ato cont\u00ednuo, Bolsonaro ainda revogou quatro nomea\u00e7\u00f5es do ex-presidente Michel Temer e nomeou seus novos diretores, que n\u00e3o precisar\u00e3o de escrut\u00ednio dos senadores.<\/p>\n<p>A revoga\u00e7\u00e3o da sabatina dos diretores est\u00e1 no art. 85, II, c, que revoga o art. 88, par\u00e1grafo \u00fanico, da Lei 10.233. \u201cOs diretores dever\u00e3o ser brasileiros, ter idoneidade moral e reputa\u00e7\u00e3o ilibada, forma\u00e7\u00e3o universit\u00e1ria, experi\u00eancia profissional compat\u00edvel com os objetivos, atribui\u00e7\u00f5es e compet\u00eancias do DNIT e elevado conceito no campo de suas especialidades, e ser\u00e3o indicados pelo ministro de estado dos Transportes e nomeados pelo presidente da Rep\u00fablica\u201d, diz o texto.<\/p>\n<p>Assim, o Senado perde a prerrogativa de sabatinar tais indica\u00e7\u00f5es. H\u00e1 apenas cinco meses no cargo, o diretor-geral Jos\u00e9 da Silva Tiago foi substitu\u00eddo pelo general Ant\u00f4nio Leite dos Santos Filho. Na diretoria-executiva, sai Halpher Luiggi M\u00f4nico Rosa e entra Andre Kuhn. Para a \u00e1rea de administra\u00e7\u00e3o e finan\u00e7as, o ent\u00e3o diretor Mauro de Moura Magalh\u00e3es passa a cadeira para Marcio Lima Medeiros. J\u00e1 a diretoria de Infraestrutura Aquavi\u00e1ria sai das m\u00e3o de Erick Moura de Medeiros para Karoline Brasileiro Quirino Lemos.<\/p>\n<p>As diretorias de Infraestrutura Rodovi\u00e1ria, de Infraestrutura Ferrovi\u00e1ria e de Planejamento e Pesquisa n\u00e3o tiveram seus comandos alterados<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro revogou, por meio de medida provis\u00f3ria publicada no Di\u00e1rio Oficial da Uni\u00e3o (DOU)desta segunda-feira, 14, a exig\u00eancia de o Senado sabatinar os diretores do Departamento Nacional de Infraestrutura de Transportes (DNIT). Em ato cont\u00ednuo, Bolsonaro ainda revogou quatro nomea\u00e7\u00f5es do ex-presidente Michel Temer e nomeou seus novos diretores, que n\u00e3o precisar\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199421"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199421\/revisions"}],"predecessor-version":[{"id":199423,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199421\/revisions\/199423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198597"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}