{"id":199452,"date":"2019-01-14T16:24:29","date_gmt":"2019-01-14T18:24:29","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199452"},"modified":"2019-01-14T23:26:37","modified_gmt":"2019-01-15T01:26:37","slug":"vicente-pires-e-outras-satelites-recebem-forca-tarefa-da-novacap","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/vicente-pires-e-outras-satelites-recebem-forca-tarefa-da-novacap\/","title":{"rendered":"Vicente Pires e outras sat\u00e9lites recebem for\u00e7a-tarefa da Novacap"},"content":{"rendered":"<p>Vicente Pires, Sol Nascente e P\u00f4r do Sol, regi\u00f5es que mais t\u00eam sofrido com as fortes dos \u00faltimos dias, est\u00e3o recebendo uma for\u00e7a-tarefa da Novacap para apressarem obras de drenagem, recupera\u00e7\u00e3o de base e recapeamento asf\u00e1ltico.<\/p>\n<p>Vicente Pires, que quase entrou em estado de calamidade p\u00fablica, tem recebido aten\u00e7\u00e3o especial. Os trabalhos foram iniciados no domingo, 13, com as equipes avan\u00e7ando na conclus\u00e3o dos trabalhos.<\/p>\n<p>A urg\u00eancia, como o governador Ibaneis Rocha j\u00e1 afirmou, \u00e9 para acabar com os transtornos provocados pela chuva aos moradores e comerciantes dessas regi\u00f5es administrativas.<\/p>\n<p>A Rua 8, em Vicente Pires, era uma das mais atingidos quando chovia. O local se transformava em um rio de lama, impedindo inclusive o tr\u00e2nsito de ve\u00edculos.<\/p>\n<p>\u201cAqui t\u00ednhamos um problema cr\u00edtico e a orienta\u00e7\u00e3o \u00e9 para a Novacap trabalhar at\u00e9 no domingo e entregar o trabalho pronto aos moradores e comerciantes o quanto antes\u201d, disse o governador durante visita \u00e0s obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vicente Pires, Sol Nascente e P\u00f4r do Sol, regi\u00f5es que mais t\u00eam sofrido com as fortes dos \u00faltimos dias, est\u00e3o recebendo uma for\u00e7a-tarefa da Novacap para apressarem obras de drenagem, recupera\u00e7\u00e3o de base e recapeamento asf\u00e1ltico. Vicente Pires, que quase entrou em estado de calamidade p\u00fablica, tem recebido aten\u00e7\u00e3o especial. Os trabalhos foram iniciados no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199453,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-199452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199452"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199452\/revisions"}],"predecessor-version":[{"id":199454,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199452\/revisions\/199454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199453"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}