{"id":199553,"date":"2019-01-15T18:24:24","date_gmt":"2019-01-15T20:24:24","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199553"},"modified":"2019-01-15T21:28:31","modified_gmt":"2019-01-15T23:28:31","slug":"militares-nao-fogem-da-reforma-mas-quem-colocar-pontos-nos-ii","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/militares-nao-fogem-da-reforma-mas-quem-colocar-pontos-nos-ii\/","title":{"rendered":"&#8216;Militares n\u00e3o fogem da reforma, mas querem colocar pontos nos ii&#8217;"},"content":{"rendered":"<p>O ministro da Defesa, general Fernando Azevedo e Silva, disse, em entrevista, ap\u00f3s cerim\u00f4nia de transmiss\u00e3o de cargo no Clube da Aeron\u00e1utica, que os militares nunca se furtaram de discutir a reforma da Previd\u00eancia e participar dos esfor\u00e7os governamentais &#8220;em prol do Pa\u00eds&#8221;, como aconteceu em 2001. Ressalvou, no entanto, que as discuss\u00f5es t\u00eam de respeitar as especificidades da carreira militar e do regime de prote\u00e7\u00e3o social deles, que prev\u00ea transfer\u00eancia para reserva e n\u00e3o aposentadoria deles, conforme prev\u00ea a Constitui\u00e7\u00e3o.<\/p>\n<p>&#8220;Participamos do esfor\u00e7o governamental sempre. Foi assim em 2001, quando perdemos diversos direitos adquiridos, em prol do Pa\u00eds&#8221;, declarou o general. &#8220;N\u00e3o nos furtamos a discutir a nossa parte em rela\u00e7\u00e3o a lei&#8221;, afirmou o general, lembrando que este tema n\u00e3o est\u00e1 previsto na Constitui\u00e7\u00e3o e que este tema est\u00e1 contemplado apenas no artigo 142 da Carta que cita que &#8220;uma lei espec\u00edfica&#8221; tratar\u00e1 desta quest\u00e3o, &#8220;respeitando as peculiaridades da atividade militar&#8221;.<\/p>\n<p>Com o debate sobre a reforma da Previd\u00eancia, os militares t\u00eam sido muito cobrados a entrarem com a sua cota. Eles reiteram sempre que s\u00e3o consultados e que, em 2001 j\u00e1 perderam v\u00e1rios dos benef\u00edcios que tinham, quando nenhuma outra carreira deu a sua contribui\u00e7\u00e3o e ainda ganharam vantagens que eles tinham e perderam com a ent\u00e3o reforma. Agora, nas discuss\u00f5es realizadas nas For\u00e7as Armadas, os militares se mostraram dispostos a ceder com aumento do tempo m\u00ednimo de servi\u00e7o de 30 para 35 anos e com o in\u00edcio do pagamento de uma cota para os pensionistas do sistema, que hoje s\u00e3o isentos.<\/p>\n<p>Os militares t\u00eam reiterado nas conversas que mant\u00eam com outros integrantes do governo sobre a diferencia\u00e7\u00e3o do sistema de prote\u00e7\u00e3o social da categoria e se surpreenderam, inclusive, com o fato de muitos integrantes da equipe econ\u00f4mica n\u00e3o terem conhecimento das diferencia\u00e7\u00f5es e das especificidades da carreira.<\/p>\n<p>As declara\u00e7\u00f5es do ministro foram dadas na cerim\u00f4nia de despedida do chefe do Estado Maior Conjunto das For\u00e7as Armadas, o almirante Ademir Sobrinho, que listou as in\u00fameras miss\u00f5es para as quais os militares foram convocados nos \u00faltimos anos e atestou que &#8220;chegamos aqui ilesos&#8221;.<\/p>\n<p>Em sua fala, o almirante Sobrinho, que permaneceu por tr\u00eas anos no cargo, comandando opera\u00e7\u00f5es nas quais as tr\u00eas for\u00e7as foram empregadas, se referiu \u00e0s dificuldades pol\u00edticas enfrentadas neste per\u00edodo. &#8220;Atravessamos juntos crises institucionais, sem nunca esquecer que Defesa \u00e9 pol\u00edtica p\u00fablica de Estado e n\u00e3o de governo; sem nunca esquecer a quem somos subordinados, que os governos passam e o Estado, a quem juramos preservar, permanece&#8221;, disse o almirante, em um recado subliminar a governos anteriores que teriam tentado misturar Estado e governo<\/p>\n<p>Ao se referir \u00e0s miss\u00f5es para as quais as tropas do Ex\u00e9rcito, da Marinha e da Aeron\u00e1utica foram convocadas, o almirante Sobrinho citou o emprego das tr\u00eas for\u00e7as como Copa do Mundo, Olimp\u00edada, greves de pol\u00edcias militares e de caminhoneiros, crise em Roraima por conta da chegada de milhares de venezuelanos, al\u00e9m da fal\u00eancia da seguran\u00e7a p\u00fablica em v\u00e1rios Estados. &#8220;Cremos que chegamos aqui ilesos, mais fortalecidos como Estado Maior e com doutrinas mais robustas&#8221;, disse.<\/p>\n<p>O almirante Sobrinho agradeceu ainda aos ex-presidentes Dilma Rousseff e Michel Temer, por, &#8220;em momentos de crise, terem tido confian\u00e7a no trabalho dos militares, lhes delegando tarefas para serem solucionadas&#8221;. O almirante ser\u00e1 substitu\u00eddo pelo brigadeiro Raul Botelho, que falou da import\u00e2ncia de o Pa\u00eds ter uma &#8220;defesa compat\u00edvel&#8221; com o tamanho do Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Defesa, general Fernando Azevedo e Silva, disse, em entrevista, ap\u00f3s cerim\u00f4nia de transmiss\u00e3o de cargo no Clube da Aeron\u00e1utica, que os militares nunca se furtaram de discutir a reforma da Previd\u00eancia e participar dos esfor\u00e7os governamentais &#8220;em prol do Pa\u00eds&#8221;, como aconteceu em 2001. Ressalvou, no entanto, que as discuss\u00f5es t\u00eam de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199553"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199553\/revisions"}],"predecessor-version":[{"id":199556,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199553\/revisions\/199556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199554"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}