{"id":199678,"date":"2019-01-17T06:59:49","date_gmt":"2019-01-17T08:59:49","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199678"},"modified":"2019-01-17T08:03:23","modified_gmt":"2019-01-17T10:03:23","slug":"avianca-corta-voos-internacionais-e-devolve-avioes","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/avianca-corta-voos-internacionais-e-devolve-avioes\/","title":{"rendered":"Avianca corta voos internacionais e devolve avi\u00f5es"},"content":{"rendered":"<p>Em recupera\u00e7\u00e3o judicial desde dezembro e com avi\u00f5es em disputa na Justi\u00e7a, a Avianca encerrar\u00e1 suas rotas entre Guarulhos e Nova York, Miami e Santiago. Com o fim dessas opera\u00e7\u00f5es em 31 de mar\u00e7o, a companhia a\u00e9rea devolver\u00e1 duas aeronaves que hoje fazem voos internacionais \u00e0s empresas de arrendamento. Ao todo, j\u00e1 foram entregues 7 avi\u00f5es.<\/p>\n<p>Das rotas para o exterior operadas pela empresa \u2013 que vinha ampliando sua atua\u00e7\u00e3o nesse segmento \u2013 restar\u00e3o apenas duas: Fortaleza e Bogot\u00e1 e Salvador e Bogot\u00e1.<\/p>\n<p>Em sua reestrutura\u00e7\u00e3o, a Avianca reduzir\u00e1 sua frota em um ter\u00e7o. Eram 57 aeronaves e restar\u00e3o apenas 38 ao fim do processo.<\/p>\n<p>Em nota, a companhia afirmou que o fim dos tr\u00eas voos internacionais ocorre para \u201cadequar sua opera\u00e7\u00e3o \u00e0 atual demanda de passageiros\u201d. A empresa informou que entrar\u00e1 em contato com os passageiros que j\u00e1 compraram passagem para os destinos suspensos.<\/p>\n<p>A companhia a\u00e9rea refor\u00e7ou ainda que os demais 26 destinos \u201cest\u00e3o preservados e que continua operando normalmente, com mais de 240 voos di\u00e1rios\u201d.<\/p>\n<p>Com 13,77% do mercado brasileiro e d\u00edvidas de quase R$ 500 milh\u00f5es \u2013 sem incluir d\u00e9bitos com arrendat\u00e1rios \u2013, a Avianca vem tendo dificuldades para honrar compromissos desde o segundo semestre do ano passado.<\/p>\n<p>Com o atraso no pagamento de contratos, os donos de aeronaves entraram na Justi\u00e7a para retomar os avi\u00f5es em posse da Avianca e conseguiram decis\u00f5es favor\u00e1veis &#8211; que s\u00f3 foram revertidas ap\u00f3s o pedido de recupera\u00e7\u00e3o judicial ser aceito.<\/p>\n<p>Em dezembro, al\u00e9m da manuten\u00e7\u00e3o da frota com a empresa a\u00e9rea, o juiz Tiago Henriques Papaterra Limongi determinou que a Ag\u00eancia Nacional de Avia\u00e7\u00e3o Civil (Anac) preservasse concess\u00f5es e autoriza\u00e7\u00f5es aeroportu\u00e1rias para n\u00e3o que os passageiros n\u00e3o fossem prejudicados. O magistrado tamb\u00e9m definiu que os aeroportos usados pela empresa mantivessem o acesso a toda infraestrutura e servi\u00e7os.<\/p>\n<p>De acordo com a lista de credores, a conta da Avianca apenas com os aeroportos \u00e9 de cerca de R$ 100 milh\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em recupera\u00e7\u00e3o judicial desde dezembro e com avi\u00f5es em disputa na Justi\u00e7a, a Avianca encerrar\u00e1 suas rotas entre Guarulhos e Nova York, Miami e Santiago. Com o fim dessas opera\u00e7\u00f5es em 31 de mar\u00e7o, a companhia a\u00e9rea devolver\u00e1 duas aeronaves que hoje fazem voos internacionais \u00e0s empresas de arrendamento. Ao todo, j\u00e1 foram entregues 7 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199678"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199678\/revisions"}],"predecessor-version":[{"id":199680,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199678\/revisions\/199680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199679"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}