{"id":199689,"date":"2019-01-17T08:27:07","date_gmt":"2019-01-17T10:27:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199689"},"modified":"2019-01-17T08:27:07","modified_gmt":"2019-01-17T10:27:07","slug":"ataque-do-e-i-poe-em-xeque-saida-americana-da-siria","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ataque-do-e-i-poe-em-xeque-saida-americana-da-siria\/","title":{"rendered":"Ataque do E.I. p\u00f5e em xeque sa\u00edda americana da S\u00edria"},"content":{"rendered":"<p>Um ataque suicida ocorrido nesta quarta-feira, 16, no norte da S\u00edria, reivindicado pelo Estado Isl\u00e2mico, matou 15 pessoas, entre elas 2 soldados e 2 civis americanos, segundo o Pent\u00e1gono. A a\u00e7\u00e3o p\u00f4s em xeque a vit\u00f3ria sobre o grupo terrorista anunciada em dezembro pelo presidente Donald Trump, que deu ordens para retirar as tropas americanas do pa\u00eds.<\/p>\n<p>&#8220;Dois militares americanos, um civil do Departamento da Defesa e um (funcion\u00e1rio) terceirizado de apoio ao departamento foram mortos. Tr\u00eas militares ficaram feridos quando realizavam um trabalho em Manbij&#8221;, informou, em comunicado, o Centro de Comando Militar dos EUA. O Observat\u00f3rio S\u00edrio dos Direitos Humanos, que monitora o conflito, informou que havia civis s\u00edrios entre os mortos.<\/p>\n<p>Ap\u00f3s o ataque, o vice-presidente americano, Mike Pence, prometeu que os EUA impedir\u00e3o o ressurgimento do EI, mas manter\u00e3o os planos de retirar suas tropas. &#8220;Vamos ficar na regi\u00e3o e continuar lutando para garantir que o Estado Isl\u00e2mico n\u00e3o surja novamente&#8221;, declarou Pence.<\/p>\n<p>O ataque foi contra um restaurante na cidade de Manbij, onde os soldados americanos costumavam comer. Ap\u00f3s a explos\u00e3o, v\u00e1rios americanos foram retirados de helic\u00f3ptero do local. N\u00e3o est\u00e1 claro quantos militares dos EUA estavam no restaurante na hora do ataque. &#8220;O presidente est\u00e1 recebendo as informa\u00e7\u00f5es e continuar\u00e1 monitorando a situa\u00e7\u00e3o na S\u00edria&#8221;, disse a porta-voz da Casa Branca, Sarah Huckabee Sanders.<\/p>\n<p>Os EUA t\u00eam cerca de 2 mil soldados na S\u00edria, enviados para trabalhar com mil\u00edcias locais para combater o Estado Isl\u00e2mico. No m\u00eas passado, ao declarar que a batalha contra os jihadistas tinha acabado, Trump anunciou a retirada desses soldados em 30 dias.<\/p>\n<p>Passado o prazo para o in\u00edcio da retirada, o governo americano anunciou, na semana passada, que havia come\u00e7ado a retirar alguns equipamentos militares. Mas o plano com os detalhes da sa\u00edda ainda n\u00e3o foi divulgado.<\/p>\n<p>Membros do governo Trump t\u00eam dito publicamente que as for\u00e7as americanas deveriam continuar na S\u00edria como prote\u00e7\u00e3o e garantia nas negocia\u00e7\u00f5es com o presidente Bashar Assad para o fim da guerra, para impedir o Ir\u00e3 de expandir sua influ\u00eancia no territ\u00f3rio s\u00edrio, proteger os curdos &#8211; aliados americanos -, al\u00e9m de coibir o ressurgimento dos jihadistas.<\/p>\n<p>Antes do ataque desta quarta, apenas dois soldados americanos haviam morrido na S\u00edria desde que o primeiro contingente entrou no pa\u00eds, em 2015. Manbij estava sob o controle das For\u00e7as Democr\u00e1ticas da S\u00edria, alian\u00e7a armada liderada por curdos e apoiada pela coaliz\u00e3o internacional, chefiada pelos EUA &#8211; embora os combatentes dessas mil\u00edcias tenham come\u00e7ado a se retirar da cidade depois de chegar a um acordo com o Ex\u00e9rcito s\u00edrio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ataque suicida ocorrido nesta quarta-feira, 16, no norte da S\u00edria, reivindicado pelo Estado Isl\u00e2mico, matou 15 pessoas, entre elas 2 soldados e 2 civis americanos, segundo o Pent\u00e1gono. A a\u00e7\u00e3o p\u00f4s em xeque a vit\u00f3ria sobre o grupo terrorista anunciada em dezembro pelo presidente Donald Trump, que deu ordens para retirar as tropas americanas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-199689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199689"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199689\/revisions"}],"predecessor-version":[{"id":199691,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199689\/revisions\/199691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199690"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}