{"id":199837,"date":"2019-01-18T21:24:08","date_gmt":"2019-01-18T23:24:08","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199837"},"modified":"2019-01-18T21:24:44","modified_gmt":"2019-01-18T23:24:44","slug":"estilo-trator-de-ibaneis-provoca-primeira-crise","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/estilo-trator-de-ibaneis-provoca-primeira-crise\/","title":{"rendered":"Estilo trator de Ibaneis provoca primeira crise"},"content":{"rendered":"<p>Estamos s\u00f3 na terceira semana dos novos mandatos, e acaba de acontecer a primeira queda-de-bra\u00e7o entre o governador Ibaneis Rocha e a C\u00e2mara Legislativa, renovada e mais plural na sua composi\u00e7\u00e3o.<\/p>\n<p>A rela\u00e7\u00e3o come\u00e7ou bem. O Buriti tem um aliado na presid\u00eancia, e a oposi\u00e7\u00e3o \u00e9 reduzida. \u00c9 uma praxe. Raramente os novos governadores n\u00e3o conseguem pelo menos a maioria simples na Casa. \u00c9 que ele tem um poder m\u00e1gico: o de nomear um mont\u00e3o de gente num mont\u00e3o de lugares.<\/p>\n<p>Como os deputados distritais mal sa\u00edram de uma campanha que mobilizou dezenas ou centenas de apoiadores, os pedidos de empregos s\u00e3o numerosos. Ainda mais num Distrital Federal de mais de 300 mil desempregados.<\/p>\n<p>Ibaneis n\u00e3o esperou o fat\u00eddico primeiro de janeiro para vestir o terno de governador. J\u00e1 come\u00e7ou a articular seu secretariado, seus projetos e at\u00e9 suas finan\u00e7as enquanto ainda era s\u00f3 \u201celeito\u201d. No dia em que o Di\u00e1rio Oficial passou a ser seu, n\u00e3o revolucionou, at\u00e9 para a decep\u00e7\u00e3o de alguns de seus admiradores: fez composi\u00e7\u00f5es, recebeu indica\u00e7\u00f5es, agradeceu amigos de longa data e alguns bem mais recentes.<\/p>\n<p>Para as Administra\u00e7\u00f5es Regionais tamb\u00e9m seguiu um roteiro conhecido, mesclando pessoas de sua confian\u00e7a fora da pol\u00edtica partid\u00e1ria, e sugest\u00f5es de distritais. O Buriti indicou ter mandado levantar os candidatos mais votados por cada uma das 31 Regi\u00f5es Administrativas (afinando os resultados oficiais do Tribunal Regional Eleitoral que funciona em 19 Zonas Eleitorais) para avaliar quem podia falar razoavelmente em nome dos habitantes daquele local.<\/p>\n<p>Alguns certamente ficaram frustrados. O governador deve ter invocado a \u201ccota pessoal\u201d e provavelmente negociado contrapartidas em outros \u00f3rg\u00e3os. Tamb\u00e9m \u00e9 a praxe. Mas ap\u00f3s o turbilh\u00e3o do primeiro dia e seu cortejo de encontros e posses, houve um descompasso constitucional entre a fome de governar do advogado, e a Lei Org\u00e2nica do Distrito Federal.<\/p>\n<p>Contrariamente ao Poder central, que instala sua legislatura em fevereiro e come\u00e7a seus trabalhos no mesmo dia, a CLDF j\u00e1 deu posse aos novos mandat\u00e1rios&#8230; que sa\u00edram de f\u00e9rias por 30 dias. Tudo legal, est\u00e1 no artigo 65 de nossa Carta Magna Distrital. Mas n\u00e3o deixa de ser surpreendente gozar de um m\u00eas de descanso remunerado quando mal se entrou no emprego. E que h\u00e1 um outro m\u00eas de fechamento previsto em julho. E que o ano, para eles, termina em 15 de dezembro.<\/p>\n<p>A impaci\u00eancia do novo Buriti que, uma vez investido de fato na administra\u00e7\u00e3o, descobriu alguns esqueletos em arm\u00e1rios, mais uma praxe, se traduziu por um chamamento ao trabalho, pelo menos por um dia, numa convoca\u00e7\u00e3o extraordin\u00e1ria dos deputados. Recebida friamente, a proposta ia sendo empurrada com a barriga de um lado da Pra\u00e7a, e negociado do outro.<\/p>\n<p>O destino da Orla do Lago e o embate com o Minist\u00e9rio P\u00fablico fez divers\u00e3o. V\u00e1rios projetos estariam na pauta desta sess\u00e3o extraordin\u00e1ria, mas o mais comentado \u00e9 aquele que faz passar o estatuto do Hospital de Base de exce\u00e7\u00e3o \u00e0 regra. O que at\u00e9 pegou o contrap\u00e9 de alguns distritais, ainda surpresos com a mudan\u00e7a radical de Ibaneis sobre o assunto. O pequeno grupo que se declarou oposi\u00e7\u00e3o ao governo j\u00e1 tinha o discurso contr\u00e1rio na ponta da l\u00edngua, mas houve constrangimento por parte de integrantes da bancada considerada governista.<\/p>\n<p>Mas o tom subiu na quinta, 17, e sobretudo na sexta-feira, 18. O governador relembrou seus tempos de OAB para considerar que \u201cos deputados escolhem o que querem, a partir da\u00ed eu vou entrar com uma a\u00e7\u00e3o contra cada um pela morte de cada cidad\u00e3o\u201d. Palavras fortes, que causaram rea\u00e7\u00f5es dos parlamentares, em grande parte presentes em Bras\u00edlia apesar do per\u00edodo de f\u00e9rias.<\/p>\n<p>Talvez mais ainda forte, a decis\u00e3o de Ibaneis de \u201ccongelar\u201d as nomea\u00e7\u00f5es no Di\u00e1rio Oficial. Os segundo e terceiro escal\u00f5es ainda est\u00e3o em forma\u00e7\u00e3o, as equipes das administra\u00e7\u00f5es regionais tamb\u00e9m, e alguns dos deputados fizeram chegar ao Buriti no in\u00edcio da semana suas lamenta\u00e7\u00f5es quanto ao ritmo das publica\u00e7\u00f5es nominais no DODF. Foi a gota d\u00b4\u00e1gua. Sentindo-se chantageado, o dono da caneta recolocou a tampa.<\/p>\n<p>A queda-de-bra\u00e7o est\u00e1 instalada. N\u00e3o vai durar, porque n\u00e3o interessa a ningu\u00e9m que continue, mas deve servir para identificar, nestes novos tempos, qual ou quais vestir\u00e3o as roupas de bombeiros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos s\u00f3 na terceira semana dos novos mandatos, e acaba de acontecer a primeira queda-de-bra\u00e7o entre o governador Ibaneis Rocha e a C\u00e2mara Legislativa, renovada e mais plural na sua composi\u00e7\u00e3o. A rela\u00e7\u00e3o come\u00e7ou bem. O Buriti tem um aliado na presid\u00eancia, e a oposi\u00e7\u00e3o \u00e9 reduzida. \u00c9 uma praxe. Raramente os novos governadores n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-199837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199837"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199837\/revisions"}],"predecessor-version":[{"id":199840,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199837\/revisions\/199840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199838"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}