{"id":199858,"date":"2019-01-19T09:15:37","date_gmt":"2019-01-19T11:15:37","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199858"},"modified":"2019-01-19T10:06:17","modified_gmt":"2019-01-19T12:06:17","slug":"furto-de-gasolina-provoca-incendio-e-deixa-20-mortos","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/furto-de-gasolina-provoca-incendio-e-deixa-20-mortos\/","title":{"rendered":"Furto de gasolina provoca inc\u00eandio e deixa 20 mortos"},"content":{"rendered":"<p>Um grande inc\u00eandio foi deflagrado em um duto na regi\u00e3o central do M\u00e9xico no fim da noite de sexta-feira, matando ao menos 20 pessoas e deixando outras 71 com s\u00e9rias queimaduras. Moradores da regi\u00e3o estavam coletando gasolina em baldes e latas de lixo, a partir de um vazamento na tubula\u00e7\u00e3o.<\/p>\n<p>O acidente ocorreu apenas tr\u00eas semanas ap\u00f3s o novo presidente, Andres Manuel Lopez Obrador, lan\u00e7ar uma ofensiva contra gangues de roubo de combust\u00edvel, que j\u00e1 perfuraram torneiras perigosas e ilegais em gasodutos ao menos 12.581 vezes entre janeiro e outubro de 2018, numa m\u00e9dia de cerca de 42 por dia.<\/p>\n<p>Com multid\u00f5es de pessoas da cidade frequentemente envolvidas, ou ajudando ladr\u00f5es ou coletando o combust\u00edvel em recipientes prec\u00e1rios, era apenas uma quest\u00e3o de tempo antes de um fogo ocorrer. Houve inc\u00eandios em casos anteriores, mas raramente na escala e intensidade do ocorrido nesta sexta-feira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grande inc\u00eandio foi deflagrado em um duto na regi\u00e3o central do M\u00e9xico no fim da noite de sexta-feira, matando ao menos 20 pessoas e deixando outras 71 com s\u00e9rias queimaduras. Moradores da regi\u00e3o estavam coletando gasolina em baldes e latas de lixo, a partir de um vazamento na tubula\u00e7\u00e3o. O acidente ocorreu apenas tr\u00eas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-199858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199858"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199858\/revisions"}],"predecessor-version":[{"id":199862,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199858\/revisions\/199862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199861"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}