{"id":199947,"date":"2019-01-20T07:05:56","date_gmt":"2019-01-20T09:05:56","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199947"},"modified":"2019-01-20T08:07:56","modified_gmt":"2019-01-20T10:07:56","slug":"ibaneis-pisa-no-freio-na-ameaca-aos-deputados-distritais","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ibaneis-pisa-no-freio-na-ameaca-aos-deputados-distritais\/","title":{"rendered":"Ibaneis pisa no freio na amea\u00e7a aos deputados distritais"},"content":{"rendered":"<p>\u00c1gua na fervura da crise entre o Pal\u00e1cio do Buriti e a C\u00e2mara Legislativa. Neste s\u00e1bado, 19, o governador Ibaneis Rocha baixou o tom das amea\u00e7as de processar os deputados distritais caso algo de rukm aconte\u00e7a na cidade (como morte de paciente em hospital ou queda de viaduto) se as reformas emergenciais que ele prop\u00f5e n\u00e3o forem aprovadas.<\/p>\n<p>Ibaneis disse que n\u00e3o quer &#8220;radicalizar com ningu\u00e9m&#8221;, e que vai ouvir sugest\u00f5es, por exemplo, de melhorias para o projeto de lei que estende o modelo do Instituto Hospital de Base para UPAs, hospitais regionais e at\u00e9 a gest\u00e3o do Samu.<\/p>\n<p>Mesmo assim, ele sustentou a necessidade de urg\u00eancia na vota\u00e7\u00e3o. &#8220;Dizer que o projeto n\u00e3o precisa tramitar de forma urgente, que d\u00e1 pra esperar 90 dias para ter um amplo debate, com as pessoas morrendo e leitos fechados, a\u00ed eu n\u00e3o consigo entender isso&#8221;, pontuou Ibaneis.<\/p>\n<p>O governador enfatizou que a C\u00e2mara Legislativa \u00e9 independente, tem que ser independente &#8220;mas tem que ser respons\u00e1vel, assim como eu sou, por entregar instrumentos para que a gente possa solucionar os problemas que existem na cidade.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1gua na fervura da crise entre o Pal\u00e1cio do Buriti e a C\u00e2mara Legislativa. Neste s\u00e1bado, 19, o governador Ibaneis Rocha baixou o tom das amea\u00e7as de processar os deputados distritais caso algo de rukm aconte\u00e7a na cidade (como morte de paciente em hospital ou queda de viaduto) se as reformas emergenciais que ele prop\u00f5e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":194431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-199947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199947"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199947\/revisions"}],"predecessor-version":[{"id":199948,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199947\/revisions\/199948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/194431"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}