{"id":199958,"date":"2019-01-20T08:46:51","date_gmt":"2019-01-20T10:46:51","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199958"},"modified":"2019-01-20T08:46:51","modified_gmt":"2019-01-20T10:46:51","slug":"doria-so-aceita-protesto-de-cara-limpa-quem-usar-mascara-cadeia-neles","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/doria-so-aceita-protesto-de-cara-limpa-quem-usar-mascara-cadeia-neles\/","title":{"rendered":"Doria s\u00f3 aceita protesto de cara limpa. Quem usar m\u00e1scara, cadeia neles"},"content":{"rendered":"<p>O governador Jo\u00e3o Doria (PSDB) regulamentou lei que endurece as regras para manifesta\u00e7\u00f5es em S\u00e3o Paulo. Entre as medidas, o decreto, publicado neste s\u00e1bado, 19, no Di\u00e1rio Oficial, pro\u00edbe uso de m\u00e1scara ou de qualquer outra forma de ocultar o rosto em protestos. Segundo a gest\u00e3o, o objetivo seria inibir atua\u00e7\u00e3o de black blocs nos atos.<\/p>\n<p>O decreto regulamento lei de 2014, ainda da gest\u00e3o Geraldo Alckmin (PSDB), e entra em vigor neste s\u00e1bado. A assinatura se d\u00e1 em momento de protestos contra o aumento das tarifas do transporte p\u00fablico de R$ 4 para R$ 4,30 em S\u00e3o Paulo.<\/p>\n<p>Dois atos j\u00e1 foram realizados neste ano &#8211; o \u00faltimo terminou com 14 detidos e um fotojornalista ferido por bala de borracha. O Movimento Passe Livre (MPL) marcou a pr\u00f3xima manifesta\u00e7\u00e3o para ter\u00e7a-feira, 22, na Pra\u00e7a da Se.<\/p>\n<p>&#8220;A medida tem como objetivo coibir a a\u00e7\u00e3o dos black blocs que, cobrindo o rosto com m\u00e1scaras, se infiltram em protestos para ferir pessoas e causar atos de vandalismo e depreda\u00e7\u00e3o de patrim\u00f4nios p\u00fablicos e privados&#8221;, diz o governo, em nota.<\/p>\n<p>A legisla\u00e7\u00e3o prev\u00ea a responsabiliza\u00e7\u00e3o criminal de quem participar de protestos sem se identificar. Ela veta &#8220;uso de m\u00e1scaras ou qualquer outro paramento que possa ocultar o rosto da pessoa, ou que dificulte ou impe\u00e7a sua identifica\u00e7\u00e3o durante o evento&#8221;.<\/p>\n<p>Segundo o texto, a recusa de identifica\u00e7\u00e3o poder\u00e1 ser classificado como crime de desobedi\u00eancia e o manifestante ser\u00e1 conduzido \u00e0 delegacia. Para identificar a pessoa, o decreto de Doria autoriza policiais a fazer contato com familiares, respons\u00e1veis e at\u00e9 com o empregador.<\/p>\n<p>Entre as medidas, a regulamenta\u00e7\u00e3o tamb\u00e9m estabelece que todo ato com previs\u00e3o de mais de 300 participantes dever\u00e1 ser comunicado \u00e0 Pol\u00edcia Militar ou \u00e0 Pol\u00edcia Civil com, no m\u00ednimo, cinco dias de anteced\u00eancia. Os organizadores dever\u00e3o informar &#8220;natureza do evento&#8221;, estimativa de participantes e previs\u00e3o de tempo de dura\u00e7\u00e3o.<\/p>\n<p>O trajeto deve ser decidido em conjunto com o comandante da PM na regi\u00e3o, segundo o decreto. Tamb\u00e9m fica vedado portar &#8220;objetos pontiagudos, tacos, bast\u00f5es, pedras, armamentos que contenham artefatos explosivos e outros instrumentos que possam lesionar pessoas e danificar o patrim\u00f4nio p\u00fablico ou particular&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Jo\u00e3o Doria (PSDB) regulamentou lei que endurece as regras para manifesta\u00e7\u00f5es em S\u00e3o Paulo. Entre as medidas, o decreto, publicado neste s\u00e1bado, 19, no Di\u00e1rio Oficial, pro\u00edbe uso de m\u00e1scara ou de qualquer outra forma de ocultar o rosto em protestos. Segundo a gest\u00e3o, o objetivo seria inibir atua\u00e7\u00e3o de black blocs nos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-199958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199958"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199958\/revisions"}],"predecessor-version":[{"id":199960,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199958\/revisions\/199960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199959"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}