{"id":199988,"date":"2019-01-20T12:00:40","date_gmt":"2019-01-20T14:00:40","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=199988"},"modified":"2019-01-20T12:10:29","modified_gmt":"2019-01-20T14:10:29","slug":"bolsonaro-viaja-e-manda-mourao-deixar-casa-em-ordem","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-viaja-e-manda-mourao-deixar-casa-em-ordem\/","title":{"rendered":"Bolsonaro viaja e manda Mour\u00e3o deixar casa em ordem"},"content":{"rendered":"<p>Ao completar os primeiros vinte dias, o governo Bolsonaro come\u00e7a a revelar os tra\u00e7os b\u00e1sicos de seu perfil. Com as movimenta\u00e7\u00f5es iniciais dos 22 ministros e as nomea\u00e7\u00f5es de boa parte dos ocupantes do segundo e terceiro escal\u00f5es, tornou-se poss\u00edvel identificar algumas marcas do novo governo. \u00c9 um per\u00edodo curto para tirar conclus\u00f5es definitivas, mas j\u00e1 d\u00e1 para ter ao menos uma ideia do que pode vir por a\u00ed.<\/p>\n<p>Em meio a declara\u00e7\u00f5es desencontradas e recuos do presidente e de seus ministros em an\u00fancios de medidas oficiais, ficou clara a exist\u00eancia de uma babel ideol\u00f3gica no governo, que gerou diversos conflitos desde a posse, em 1.\u00ba de janeiro. Mas ao embarcar para a Europa neste domingo, 20, onde abre na segunda, 21, o F\u00f3rum Mundial de Davos, ele deixou com o vice, general Hamilton Mour\u00e3o, a miss\u00e3o de colocar ordem na casa.<\/p>\n<p>Aparentemente, as diverg\u00eancias at\u00e9 agora n\u00e3o deixaram feridas profundas. Mas podem amea\u00e7ar a unidade da grande frente formada para eleger Bolsonaro, refletida no novo Minist\u00e9rio, se os conflitos aumentarem, em vez de diminu\u00edrem, nas pr\u00f3ximas semanas e meses.<\/p>\n<p>A frente inclui seis grandes grupos, com pesos diferentes na administra\u00e7\u00e3o e influ\u00eancia distinta junto ao presidente \u2013 os militares, os liberais, os lavajatistas, os pol\u00edticos, os evang\u00e9licos e os ide\u00f3logos e olavistas, que seguem as teorias do pensador e escritor Olavo de Carvalho<\/p>\n<p>Em paralelo, com forte influ\u00eancia sobre as decis\u00f5es do presidente e uma identidade maior com militares e olavistas, opera o n\u00facleo familiar, composto pelos tr\u00eas filhos de Bolsonaro: Fl\u00e1vio, senador eleito pelo Rio de Janeiro, suspeito de envolvimento em opera\u00e7\u00f5es irregulares com funcion\u00e1rios, Eduardo, deputado federal por S\u00e3o Paulo e talvez o mais influente da troika, e Carlos, vereador no Rio, todos integrantes do PSL, o mesmo partido do pai.<\/p>\n<p><strong>Mosaico ideol\u00f3gico<\/strong> &#8211; Muitas vezes, esses grupos t\u00eam ideias e vis\u00f5es divergentes e contradit\u00f3rias sobre o Pa\u00eds e o mundo. N\u00e3o por acaso alguns analistas est\u00e3o chamando esse processo de \u201cbalcaniza\u00e7\u00e3o\u201d, em refer\u00eancia \u00e0 divis\u00e3o de poder entre grupos conflitantes ocorrida na Pen\u00ednsula Balc\u00e2nica, localizada na regi\u00e3o sudeste da Europa, entre o in\u00edcio dos s\u00e9culos 19 e 20.<\/p>\n<p>De certa forma, o mosaico ideol\u00f3gico montado pelo novo governo tamb\u00e9m existia nas gest\u00f5es do PT e mesmo do PSDB. Agora, por\u00e9m, a fragmenta\u00e7\u00e3o parece mais acentuada, talvez porque os grupos s\u00f3 tenham se aproximado para valer ap\u00f3s as elei\u00e7\u00f5es e, em alguns casos, s\u00f3 depois da posse.<\/p>\n<p>Um exemplo que ilustra com perfei\u00e7\u00e3o o \u201ccabo de guerra\u201d travado dentro do governo \u00e9 a disputa pela Ag\u00eancia Brasileira de Promo\u00e7\u00e3o de Exporta\u00e7\u00f5es e Investimentos (Apex), entre a ala liberal, liderada pelo ministro da Economia, Paulo Guedes, e a ala dos olavistas, representada pelo ministro das Rela\u00e7\u00f5es Exteriores, Ernesto Ara\u00fajo.<\/p>\n<p>Guedes contava com a transfer\u00eancia da Apex para sua \u00f3rbita, com o objetivo de dinamiz\u00e1-la e transform\u00e1-la numa ferramenta poderosa de neg\u00f3cios no exterior. Mas o \u00f3rg\u00e3o, que j\u00e1 foi ligado ao extinto Minist\u00e9rio do Desenvolvimento, Com\u00e9rcio Exterior e Servi\u00e7os, acabou ficando mesmo com o Itamaraty, onde j\u00e1 estava no governo Temer. A decis\u00e3o foi consumada apesar dos sinais emitidos por Ara\u00fajo de que poder\u00e1 levar em conta aspectos ideol\u00f3gicos na atua\u00e7\u00e3o da Apex, em preju\u00edzo de uma filosofia mais pragm\u00e1tica do com\u00e9rcio internacional.<\/p>\n<p><strong>Piv\u00f4 das diverg\u00eancias<\/strong> &#8211; Para completar o quadro, Ara\u00fajo ainda nomeou dois diretores da Apex ligados a Eduardo Bolsonaro \u2013 a empres\u00e1ria Let\u00edcia Catelani e o advogado M\u00e1rcio Coimbra, ex-assessor parlamentar do Senado, que acompanhou o filho do presidente em sua recente viagem aos Estados Unidos. Let\u00edcia teria sido respons\u00e1vel pela tumultuada sa\u00edda do ex-presidente da empresa, Alex Carreiro, substitu\u00eddo pelo diplomata M\u00e1rio Vilalva apenas uma semana depois de nomeado.<\/p>\n<p>Numa outra frente, o grupo dos lavajatistas, capitaneado pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, levou a pior num conflito com a ala dos pol\u00edticos, \u00e0 qual pertence o ministro-chefe da Casa Civil, Onyx Lorenzoni, talvez o grande piv\u00f4 das diverg\u00eancias no governo desde a elei\u00e7\u00e3o de Bolsonaro. Moro, a quem a Funda\u00e7\u00e3o Nacional do \u00cdndio (Funai) era ligada at\u00e9 ser transferida para o Minist\u00e9rio da Mulher, da Fam\u00edlia e dos Direitos Humanos, havia determinado a exonera\u00e7\u00e3o de Azelene In\u00e1cio, diretora de Prote\u00e7\u00e3o Territorial do \u00f3rg\u00e3o. Mas uma semana depois Onyx ainda n\u00e3o havia levado adiante a decis\u00e3o e publicado o desligamento de Azelene no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p>Nas pr\u00f3ximas semanas, novas disputas do g\u00eanero est\u00e3o no radar. No in\u00edcio de fevereiro, com o prov\u00e1vel encaminhamento do projeto de reforma da Previd\u00eancia ao Congresso, tudo indica que as tens\u00f5es v\u00e3o se acentuar entre a ala dos militares, que defende em p\u00fablico a manuten\u00e7\u00e3o dos privil\u00e9gios da categoria \u2013 com a exce\u00e7\u00e3o do vice-presidente, o general Hamilton Mour\u00e3o \u2013, e a dos liberais, que apoia uma mudan\u00e7a ampla, englobando o pessoal da caserna.<\/p>\n<p>O pr\u00f3prio presidente ter\u00e1 de tomar partido nesta quest\u00e3o e pelo que se pode deduzir do que tem dito a tend\u00eancia \u00e9 ele cerrar fileira com os militares e a ala pol\u00edtica representada por Onyx, tamb\u00e9m defensor de uma reforma mais branda, mesmo com o d\u00e9ficit da Previd\u00eancia chegando \u00e0 estratosfera e comprometendo o equil\u00edbrio das contas p\u00fablicas. \u201cA melhor reforma \u00e9 a que passa na C\u00e2mara e no Senado\u201d, disse Bolsonaro, sugerindo que est\u00e1 pouco inclinado a apresentar um projeto mais duro para resolver o problema de vez, como prop\u00f5e a ala liberal.<\/p>\n<p><strong>Vantagem militar<\/strong> &#8211; A avalia\u00e7\u00e3o da for\u00e7a dos grupos n\u00e3o pode ser feita apenas com base no n\u00famero de minist\u00e9rios conquistados por cada um. Ela tem de incluir seus tent\u00e1culos nos escal\u00f5es inferiores em todas as pastas. Depende tamb\u00e9m do or\u00e7amento total controlado por cada ala, do impacto das pastas na economia e do grau de prest\u00edgio de seus representantes junto ao presidente e a seus filhos, cuja participa\u00e7\u00e3o ativa no governo preocupa at\u00e9 os aliados mais pr\u00f3ximos.<\/p>\n<p>Dito isso e levando em conta apenas o primeiro escal\u00e3o, pode-se dizer que os grupos militar e pol\u00edtico, \u00e0 frente de sete minist\u00e9rios cada um, s\u00e3o os que concentram a maior fatia de poder no governo. Depois deles, v\u00eam as alas liberal, com tr\u00eas minist\u00e9rios, incluindo o Banco Central, lavajatista e olavista, com dois cada, e evang\u00e9lica, com apenas um minist\u00e9rio.<\/p>\n<p>Quando se consideram tamb\u00e9m as nomea\u00e7\u00f5es de segundo escal\u00e3o claramente identificadas com uma das alas, o grupo militar leva larga vantagem, com nada menos que 32 representantes, espalhados por 13 minist\u00e9rios, seguido pelos n\u00facleos pol\u00edtico, com 16 integrantes, liberal, com 13, olavista, com 12, lavajatista, com 10, e evang\u00e9lico, com 3.<\/p>\n<p><strong>Cartilha<\/strong> &#8211; Conhecido at\u00e9 pouco tempo atr\u00e1s por um contingente restrito de iniciados e seguidores, entre eles Bolsonaro e seus filhos, Olavo de Carvalho ganhou os holofotes e conquistou trincheiras importantes na nova gest\u00e3o. \u201cVivi para ver um fil\u00f3sofo indicar mais gente para o governo que o MDB\u201d, afirmou na semana passada o cineasta Josias Te\u00f3filo, diretor do filme O Jardim das Afli\u00e7\u00f5es, sobre a vida e a obra de Olavo. No primeiro escal\u00e3o, o MDB amealhou apenas o Minist\u00e9rio da Cidadania, ocupado pelo deputado federal ga\u00facho Osmar Terra.<\/p>\n<p>Al\u00e9m de ter indicado os ministros Ernesto Ara\u00fajo, de Rela\u00e7\u00f5es Exteriores, e Ricardo Velez Rodriguez, da Educa\u00e7\u00e3o, duas \u00e1reas consideradas essenciais pelos seus pupilos para determinar o sucesso do governo, Olavo tamb\u00e9m \u00e9 o \u201cpadrinho\u201d de Filipe Garcia Martins Pereira, assessor internacional de Bolsonaro, instalado no Pal\u00e1cio do Planalto, de Carlos Nadalim, secret\u00e1rio de Alfabetiza\u00e7\u00e3o do Minist\u00e9rio da Educa\u00e7\u00e3o, e de Adolfo Sachsida, secret\u00e1rio de Pol\u00edtica Econ\u00f4mica do Minist\u00e9rio da Economia, um territ\u00f3rio dominado por liberais que n\u00e3o rezam pela sua cartilha.<\/p>\n<p>Como se pode observar, na babel ideol\u00f3gica do governo Bolsonaro, parece complicado os diferentes grupos falarem a mesma l\u00edngua. S\u00f3 o tempo vai dizer se o presidente conseguir\u00e1 administrar as diverg\u00eancias entre as alas e se ele vai enfrentar o problema sem causar grandes solavancos.<\/p>\n<p>Para manter unida a frente heterog\u00eanea que lhe d\u00e1 suporte, Bolsonaro ter\u00e1 de mostrar que est\u00e1 preparado para atuar como um magistrado nos conflitos.<\/p>\n<p><strong>Divisor de \u00e1guas<\/strong> &#8211; Segundo relatos de quem j\u00e1 teve contato com Bolsonaro e por tudo o que se p\u00f4de observar desde a campanha, ele tende a mudar de opini\u00e3o conforme a vis\u00e3o de seu interlocutor sobre uma quest\u00e3o qualquer. Ele tamb\u00e9m j\u00e1 mostrou que costuma falar sobre temas que n\u00e3o domina, antes de formar uma convic\u00e7\u00e3o a respeito do melhor caminho a seguir. Assim, acaba dando a impress\u00e3o de ser uma esp\u00e9cie de biruta, que oscila de acordo com a dire\u00e7\u00e3o do vento, gerando inseguran\u00e7a n\u00e3o s\u00f3 no mundo dos neg\u00f3cios, mas para todos os brasileiros que acompanham seus movimentos e t\u00eam de tomar decis\u00f5es para si mesmos e suas fam\u00edlias.<\/p>\n<p>Como diz a express\u00e3o criada pelo poeta ingl\u00eas John Donne (1572-1631) e imortalizada pelo escritor americano Ernest Hemingway (1899-1961), a grande quest\u00e3o \u00e9 saber por quem dobrar\u00e3o os sinos de Bolsonaro nos pr\u00f3ximos meses e anos.<\/p>\n<p>Aparentemente, nas primeiras semanas de governo, ele se curvou \u00e0s alas pol\u00edtica, militar e olavista nas quest\u00f5es que envolviam a economia, em detrimento da ala liberal, encarregada de conduzir as reformas de que o Brasil precisa para voltar a crescer.<\/p>\n<p>Bolsonaro tamb\u00e9m demonstrou enorme interesse nas quest\u00f5es de costumes e educacionais, caras \u00e0s alas olavista e evang\u00e9lica, e nas de pol\u00edtica externa, uma esp\u00e9cie de fetiche para os seguidores de Olavo. Sua postura em rela\u00e7\u00e3o \u00e0 reforma da Previd\u00eancia pode ser um \u201cdivisor de \u00e1guas\u201d ou confirmar as previs\u00f5es mais sombrias. Logo mais, se o envio da reforma previdenci\u00e1ria ao Congresso no in\u00edcio de fevereiro se confirmar, a gente saber\u00e1 a resposta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao completar os primeiros vinte dias, o governo Bolsonaro come\u00e7a a revelar os tra\u00e7os b\u00e1sicos de seu perfil. Com as movimenta\u00e7\u00f5es iniciais dos 22 ministros e as nomea\u00e7\u00f5es de boa parte dos ocupantes do segundo e terceiro escal\u00f5es, tornou-se poss\u00edvel identificar algumas marcas do novo governo. \u00c9 um per\u00edodo curto para tirar conclus\u00f5es definitivas, mas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-199988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=199988"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199988\/revisions"}],"predecessor-version":[{"id":199992,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/199988\/revisions\/199992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199989"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=199988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=199988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=199988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}