{"id":200127,"date":"2019-01-21T17:04:17","date_gmt":"2019-01-21T19:04:17","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200127"},"modified":"2019-01-21T17:04:17","modified_gmt":"2019-01-21T19:04:17","slug":"empresarios-admitem-investir-no-brasil-mas-sem-muita-empolgacao","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/empresarios-admitem-investir-no-brasil-mas-sem-muita-empolgacao\/","title":{"rendered":"Empres\u00e1rios admitem investir no Brasil, mas sem muita empolga\u00e7\u00e3o"},"content":{"rendered":"<p>Ap\u00f3s o humor despencar em 2017 em rela\u00e7\u00e3o ao Brasil e mostrar alguma recupera\u00e7\u00e3o no ano passado, executivos melhoraram suas percep\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 retomada econ\u00f4mica do Pa\u00eds nos pr\u00f3ximos 12 meses, conforme uma pesquisa da PwC divulgada nesta segunda-feira, 21, em Davos, na v\u00e9spera da abertura oficial do F\u00f3rum Econ\u00f4mico Mundial de 2019.<\/p>\n<p>Na 22\u00aa Pesquisa Global com os CEOs da PwC, 43% dos entrevistados brasileiros projetaram crescimento de suas empresas em 2019. O otimismo dos profissionais dom\u00e9sticos supera a m\u00e9dia global e \u00e9 maior do que os 39% registrados um ano antes.<\/p>\n<p>A melhora, no entanto, est\u00e1 muito longe de ser empolgante. No levantamento geral, realizado com 1.378 CEOs de 91 pa\u00edses dos cinco continentes, de setembro a outubro passado, o Brasil \u00e9 apontado como o sexto destino potencial para novos investimentos no curto prazo. A sondagem identificou que, em um momento de muitas incertezas globais, os profissionais est\u00e3o preferindo focar as atividades &#8211; e o dinheiro &#8211; em seus pr\u00f3prios pa\u00edses.<\/p>\n<p>Os entrevistados foram solicitados a identificar os tr\u00eas mercados mais atraentes para investimento fora de seu territ\u00f3rio, e, em meio a essas incertezas dos \u00faltimos meses, uma fatia nada desprez\u00edvel, de 15%, respondeu &#8220;n\u00e3o saber&#8221; &#8211; no levantamento anterior era uma parcela de apenas 8%. Esse n\u00e3o comprometimento dos l\u00edderes ficou na terceira posi\u00e7\u00e3o, atr\u00e1s de Estados Unidos (27%) e China (24%).<\/p>\n<p>Apesar de as duas maiores pot\u00eancias econ\u00f4micas do globo ainda atra\u00edrem a aten\u00e7\u00e3o de investidores, sentiram o baque da diminui\u00e7\u00e3o do interesse, uma vez que, no ano passado, tinham fatias de, respectivamente, 46% e 33%.<\/p>\n<p>Na terceira posi\u00e7\u00e3o entre os pa\u00edses est\u00e1 a Alemanha, que passou de 20% para 13%, e, na quinta, a \u00cdndia, de 9% para 8%. Antes de qualquer outro pa\u00eds, figurou &#8220;nenhum outro territ\u00f3rio&#8221;, que disparou de 1% para 8% de 2018 para 2019, revelando que esses CEOs n\u00e3o conseguiram nomear tr\u00eas pa\u00edses separadamente al\u00e9m do lugar onde atuam.<\/p>\n<p>&#8220;Dado o n\u00edvel de incerteza em torno das quest\u00f5es comerciais e pol\u00edticas, n\u00e3o \u00e9 de surpreender que os CEOs estejam se concentrando em casa&#8221;, observou a PwC, acrescentando que os governos podem ver isso como uma oportunidade para lembrar \u00e0s empresas que seus pa\u00edses est\u00e3o abertos para neg\u00f3cios.<\/p>\n<p>O Reino Unido, por sua vez, passou de 15% para 8% e o Brasil, de 7% para 6%, exatamente como ocorreu com a Fran\u00e7a. &#8220;Apesar da retra\u00e7\u00e3o econ\u00f4mica dos \u00faltimos anos, a pesquisa mostra que o Brasil segue em destaque no cen\u00e1rio global: o Pa\u00eds ocupa o sexto lugar entre os mais citados pelos CEOs globais como poss\u00edveis focos de investimentos ao longo de 2019, atr\u00e1s de EUA, China, Alemanha, \u00cdndia e Reino Unido&#8221;, considerou a PwC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s o humor despencar em 2017 em rela\u00e7\u00e3o ao Brasil e mostrar alguma recupera\u00e7\u00e3o no ano passado, executivos melhoraram suas percep\u00e7\u00f5es em rela\u00e7\u00e3o \u00e0 retomada econ\u00f4mica do Pa\u00eds nos pr\u00f3ximos 12 meses, conforme uma pesquisa da PwC divulgada nesta segunda-feira, 21, em Davos, na v\u00e9spera da abertura oficial do F\u00f3rum Econ\u00f4mico Mundial de 2019. Na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-200127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200127"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200127\/revisions"}],"predecessor-version":[{"id":200129,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200127\/revisions\/200129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200128"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}