{"id":200434,"date":"2019-01-25T00:08:36","date_gmt":"2019-01-25T02:08:36","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200434"},"modified":"2019-01-25T05:14:19","modified_gmt":"2019-01-25T07:14:19","slug":"ibaneis-atropela-oposicao-e-ganha-apoio-para-tirar-saude-publica-da-uti","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ibaneis-atropela-oposicao-e-ganha-apoio-para-tirar-saude-publica-da-uti\/","title":{"rendered":"Ibaneis atropela oposi\u00e7\u00e3o e ganha apoio para tirar sa\u00fade p\u00fablica da UTI"},"content":{"rendered":"<p>Os aliados do governador Ibaneis Rocha na C\u00e2mara Legislativa deram demonstra\u00e7\u00e3o de for\u00e7a nesta quinta, 24, ao aprovarem em sess\u00e3o extraordin\u00e1ria a extens\u00e3o do modelo do Instituto Hospital de Base para outras unidades da Secretaria de Sa\u00fade. Dos 22 distritais presentes, 14 disseram sim ao Pal\u00e1cio do Buriti. Os oito opositores, que marcharam ao lado de sindicalistas ligados \u00e0 CUT, foram atropelados literalmente.<\/p>\n<p>O placar representa &#8216;um voto de confian\u00e7a&#8217;, segundo interpreta\u00e7\u00e3o de Ibaneis Rocha. &#8220;Agora vamos avan\u00e7ar para dar servi\u00e7os de sa\u00fade de melhor qualidade \u00e0 popula\u00e7\u00e3o&#8221;, disse. A sess\u00e3o foi longa. Arrasou-se das 15 \u00e0s 22 horas. Os trabalhos foram presididos por Rafael Prudente.<\/p>\n<p>Os dias que antecederam a vota\u00e7\u00e3o do projeto foram de muita negocia\u00e7\u00e3o pol\u00edtica. O texto original previa a inclus\u00e3o de todos os hospitais da rede p\u00fablica. As seis UPA&#8217;s e o Hospital Regional de Santa Maria v\u00e3o virar uma esp\u00e9cie de ap\u00eandice do IHB. O de Taguatinga foi retirado da lista.<\/p>\n<p>O secret\u00e1rio de Sa\u00fade, Osnei Okumoto, garantiu que o sistema de sa\u00fade p\u00fablica n\u00e3o ser\u00e1 privatizado. \u201cHaver\u00e1 manuten\u00e7\u00e3o do \u00f3rg\u00e3o p\u00fablico, de tal forma que possamos contratar a maioria dos profissionais que precisamos por concurso p\u00fablico\u201d, ressaltou.<\/p>\n<p>Rafael Prudente reafirmou por diversas vezes no plen\u00e1rio a convic\u00e7\u00e3o de que o modelo impactar\u00e1 positivamente na vida da popula\u00e7\u00e3o. \u201cO Hospital de Base est\u00e1 funcionando muito melhor, mas o texto tamb\u00e9m recebeu limita\u00e7\u00f5es. Os dirigentes do setor sa\u00fade ser\u00e3o submetidos \u00e0 sabatina da C\u00e2mara para garantir a maior transpar\u00eancia poss\u00edvel\u201d, disse o presidente da Casa legislativa. Ele ainda ressaltou que o projeto garantir\u00e1 todos os direitos dos servidores p\u00fablicos da pasta.<\/p>\n<p>Os deputados Agaciel Maia (PTC) e Rodrigo Delmasso (PRB) estiveram ausentes da vota\u00e7\u00e3o. Votaram favoravelmente ao Buriti Cl\u00e1udio Abrantes (PDT), Daniel Donizet (PRP), Eduardo Pedrosa (PTC), Hermeto (PHS), Iolando Almeida (PSC), Jaqueline Silva (PTB), Jos\u00e9 Gomes (PSB), Martins Machado (PRB), Rafael Prudente (MDB), Reginaldo Sardinha (Avante), Rob\u00e9rio Negreiros (PSD), Roosevelt Vilela (PSB), Telma Rufino (Pros) e Valdelino Barcelos (PP).<\/p>\n<p>A &#8216;turma do contra&#8217; foi representada por Arlete Sampaio (PT), Chico Vigilante (PT), F\u00e1bio Felix (PSol), Jo\u00e3o Cardoso (Avante), Jorge Vianna (Podemos), J\u00falia Lucy (Novo), Leandro Grass (Rede) e Prof. Reginaldo Veras (PDT).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os aliados do governador Ibaneis Rocha na C\u00e2mara Legislativa deram demonstra\u00e7\u00e3o de for\u00e7a nesta quinta, 24, ao aprovarem em sess\u00e3o extraordin\u00e1ria a extens\u00e3o do modelo do Instituto Hospital de Base para outras unidades da Secretaria de Sa\u00fade. Dos 22 distritais presentes, 14 disseram sim ao Pal\u00e1cio do Buriti. Os oito opositores, que marcharam ao lado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-200434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200434"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200434\/revisions"}],"predecessor-version":[{"id":200438,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200434\/revisions\/200438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200435"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}