{"id":200454,"date":"2019-01-25T00:06:40","date_gmt":"2019-01-25T02:06:40","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200454"},"modified":"2019-01-25T06:26:38","modified_gmt":"2019-01-25T08:26:38","slug":"transparencia-internacional-ve-abuso-do-governo-no-sigilo-de-documentos","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/transparencia-internacional-ve-abuso-do-governo-no-sigilo-de-documentos\/","title":{"rendered":"Transpar\u00eancia Internacional v\u00ea abuso do governo no sigilo de documentos"},"content":{"rendered":"<p>O diretor-executivo da Transpar\u00eancia Internacional Brasil, Bruno Brand\u00e3o, disse nesta quinta, 24, que o decreto que modificou as regras para a aplica\u00e7\u00e3o da Lei de Acesso \u00e0 Informa\u00e7\u00e3o (LAI) \u00e9 preocupante e contraria o princ\u00edpio da publicidade na administra\u00e7\u00e3o p\u00fablica. A cr\u00edtica dele se dirige \u00e0 amplia\u00e7\u00e3o no n\u00famero de servidores que podem decretar sigilo sobre documentos p\u00fablicos.<\/p>\n<p>&#8220;H\u00e1 preocupa\u00e7\u00f5es no direcionamento dessa nova regulamenta\u00e7\u00e3o. A Lei de Acesso \u00e0 Informa\u00e7\u00e3o vem para criar uma cultura nova no Brasil. Uma cultura de que a informa\u00e7\u00e3o p\u00fablica, a publicidade, a transpar\u00eancia, isso \u00e9 a regra, a norma, e o sigilo \u00e9 exce\u00e7\u00e3o. E que a informa\u00e7\u00e3o p\u00fablica \u00e9 um direito. E, portanto, as exce\u00e7\u00f5es a esse direito tem de ser muito criteriosas e muito bem fundamentadas. Por isso, a necessidade de isso ser feito em uma al\u00e7ada elevada, porque a classifica\u00e7\u00e3o como sigiloso \u00e9 algo que restringe o direito \u00e0 informa\u00e7\u00e3o&#8221;, afirmou.<\/p>\n<p>Brand\u00e3o disse tamb\u00e9m que faltou di\u00e1logo com a sociedade para a elabora\u00e7\u00e3o do decreto.<\/p>\n<p>&#8220;Tem um erro de procedimento de origem, porque o di\u00e1logo \u00e9 sempre saud\u00e1vel para a sociedade. Foi feito de maneira unilateral, sem debate, e no m\u00ednimo gera problema de mensagem e de compreens\u00e3o&#8221;, afirmou o diretor-executivo da Transpar\u00eancia Internacional.<\/p>\n<p>O sigilo em documentos pode se dar em tr\u00eas n\u00edveis, com diferentes prazos m\u00e1ximos de restri\u00e7\u00e3o ao acesso a partir de sua elabora\u00e7\u00e3o. A primeira classifica\u00e7\u00e3o \u00e9 &#8220;reservada&#8221;, com prazo de 5 anos. A segunda \u00e9 a &#8220;secreta&#8221;, indispon\u00edvel por 15 anos. A terceira \u00e9 a e a &#8220;ultrassecreta&#8221;, que s\u00f3 depois de 25 anos pode ser acessada.<\/p>\n<p>Antes, s\u00f3 cargos como presidente, vice, ministros e comandantes das For\u00e7as Armadas &#8211; a alta administra\u00e7\u00e3o &#8211; podiam classificar informa\u00e7\u00f5es como ultrassecretas. Agora, comissionados do Grupo-DAS de n\u00edvel 101.6 (Dire\u00e7\u00e3o e Assessoramento Superiores, com remunera\u00e7\u00e3o de R$ 16.944,90), tamb\u00e9m t\u00eam a permiss\u00e3o, assim como chefes de autarquias, de funda\u00e7\u00f5es, de empresas p\u00fablicas e de sociedades de economia mista.<\/p>\n<p>No caso dos documentos secretos, passa a ser permitido que DAS-5 promova essa classifica\u00e7\u00e3o &#8211; antes s\u00f3 os DAS-6 podiam. Para definir que um documento \u00e9 de acesso &#8220;reservado&#8221;, \u00e9 preciso apenas ser agente p\u00fablico que exer\u00e7a fun\u00e7\u00e3o de dire\u00e7\u00e3o, comando ou chefia &#8211; seja qual for o DAS que tenha. Segundo dados de dezembro fornecidos pelo Minist\u00e9rio do Planejamento, h\u00e1 12 mil cargos de DAS no pa\u00eds.<\/p>\n<p>O governo tem destacado que, apesar da amplia\u00e7\u00e3o do rol de cargos, ser\u00e1 necess\u00e1rio delegar para servidores a fun\u00e7\u00e3o de classificar documentos como sigilosos. O argumento \u00e9 que um ministro, por exemplo, n\u00e3o deixar\u00e1 de ter controle e poder\u00e1, por exemplo, escolher n\u00e3o delegar a fun\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O diretor-executivo da Transpar\u00eancia Internacional Brasil, Bruno Brand\u00e3o, disse nesta quinta, 24, que o decreto que modificou as regras para a aplica\u00e7\u00e3o da Lei de Acesso \u00e0 Informa\u00e7\u00e3o (LAI) \u00e9 preocupante e contraria o princ\u00edpio da publicidade na administra\u00e7\u00e3o p\u00fablica. A cr\u00edtica dele se dirige \u00e0 amplia\u00e7\u00e3o no n\u00famero de servidores que podem decretar sigilo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200455,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-200454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200454"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200454\/revisions"}],"predecessor-version":[{"id":200456,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200454\/revisions\/200456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200455"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}