{"id":200744,"date":"2019-01-27T22:54:25","date_gmt":"2019-01-28T00:54:25","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200744"},"modified":"2019-01-28T05:23:27","modified_gmt":"2019-01-28T07:23:27","slug":"pousada-foi-riscada-do-mapa-e-levou-cristina-crioula-lais-robinho","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/pousada-foi-riscada-do-mapa-e-levou-cristina-crioula-lais-robinho\/","title":{"rendered":"Pousada foi riscada do mapa. E levou Cristina, Crioula, La\u00eds, Heitor&#8230;"},"content":{"rendered":"<p>Cristina, Crioula, Jussara, La\u00eds, Robinho, Camila, Heitor, P\u00e2mela, Reinaldo. Esses nomes est\u00e3o no centro de coment\u00e1rios e preocupa\u00e7\u00f5es dos moradores de C\u00f3rrego do Feij\u00e3o, localidade mais atingida pelo rompimento da barragem da Vale em Brumadinho. Todos trabalhavam na Pousada Fazenda Nova Est\u00e2ncia e est\u00e3o desaparecidos desde que a enxurrada de lama a varreu do local. Neste domingo, 27, o ambiente era de consterna\u00e7\u00e3o com o desaparecimento dos amigos, muito conhecidos e queridos no lugarejo. Em rela\u00e7\u00e3o aos h\u00f3spedes, n\u00e3o havia nenhuma informa\u00e7\u00e3o &#8211; nem mesmo nomes.<\/p>\n<p>&#8220;N\u00e3o era hor\u00e1rio em que a pousada estivesse cheia&#8221;, informou N\u00fabia Maia, que j\u00e1 trabalhou na pousada. Ela explicou que a hora em que chegou a enxurrada de lama era a mesma em que a maioria dos h\u00f3spedes est\u00e1 fora, em passeios, ou fazendo seu check-in ou check-out. Assim , \u00e9 poss\u00edvel que muita gente n\u00e3o estivesse l\u00e1 quando ocorreu a trag\u00e9dia.<\/p>\n<p>N\u00e3o h\u00e1 mais nada no lugar da pousada, a n\u00e3o ser lama e restos de \u00e1rvores destru\u00eddas. Por causa do lama\u00e7al, s\u00f3 foi poss\u00edvel chegar a cerca de mil metros do ponto onde ficava a sede da Nova Est\u00e2ncia. O cen\u00e1rio de destrui\u00e7\u00e3o contrasta com imagens do local anteriores \u00e0 trag\u00e9dia, dispon\u00edveis na internet. S\u00e3o fotos da piscina, do lago, das su\u00edtes, do restaurante, de lojas. O site da fazenda informa que havia 15 quartos, com ar condicionado. Tamb\u00e9m oferecia aos h\u00f3spedes assist\u00eancia para excurs\u00f5es e ingressos. Era comum que h\u00f3spedes a usassem como base para visitar o museu de Inhotim.<\/p>\n<p>Nas imedia\u00e7\u00f5es, a apar\u00eancia \u00e9 de cidade-fantasma. Mesmo casas que n\u00e3o foram atingidas pela lama est\u00e3o vazias. Animais &#8211; c\u00e3es, cavalos, galinhas &#8211; est\u00e3o soltos. Funcion\u00e1rios da Cemig trabalhavam para restabelecer uma linha de transmiss\u00e3o de energia derrubada pela torrente de rejeitos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristina, Crioula, Jussara, La\u00eds, Robinho, Camila, Heitor, P\u00e2mela, Reinaldo. Esses nomes est\u00e3o no centro de coment\u00e1rios e preocupa\u00e7\u00f5es dos moradores de C\u00f3rrego do Feij\u00e3o, localidade mais atingida pelo rompimento da barragem da Vale em Brumadinho. Todos trabalhavam na Pousada Fazenda Nova Est\u00e2ncia e est\u00e3o desaparecidos desde que a enxurrada de lama a varreu do local. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-200744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200744"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200744\/revisions"}],"predecessor-version":[{"id":200775,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200744\/revisions\/200775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200745"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}