{"id":200754,"date":"2019-01-27T20:39:09","date_gmt":"2019-01-27T22:39:09","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200754"},"modified":"2019-01-27T21:13:08","modified_gmt":"2019-01-27T23:13:08","slug":"janaina-paschoal-compara-reacao-de-flavio-bolsonaro-aos-gestos-de-aecio-e-lula","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/janaina-paschoal-compara-reacao-de-flavio-bolsonaro-aos-gestos-de-aecio-e-lula\/","title":{"rendered":"Jana\u00edna Paschoal compara rea\u00e7\u00e3o de Fl\u00e1vio Bolsonaro aos gestos de A\u00e9cio e Lula"},"content":{"rendered":"<p>A advogada, professora universit\u00e1ria e deputada estadual do PSL Jana\u00edna Concei\u00e7\u00e3o Paschoal, eleita com mais de dois milh\u00f5es de votos, disse ao Estado, em entrevista na \u00faltima segunda, que o senador eleito Fl\u00e1vio Bolsonaro (PSL-RJ), filho do presidente Jair Bolsonaro, &#8220;tem todo o direito \u00e0 defesa, a entrar com todas as medidas, mas me parece complicado ver uma rea\u00e7\u00e3o parecida com a que foi a do A\u00e9cio (Neves) e com a que \u00e9 a do Lula at\u00e9 hoje&#8221;.<\/p>\n<p>Disse, ainda, que &#8220;foi um erro&#8221; o senador ter concordado com o pedido ao Supremo Tribunal Federal para que suspendesse a investiga\u00e7\u00e3o, pelo Minist\u00e9rio P\u00fablico do Rio, concedido em liminar do ministro Luiz Fux. &#8220;Foi um erro, porque, ainda que n\u00e3o tenha nada errado, isso gerou uma situa\u00e7\u00e3o, um sentimento, &#8216;poxa, por que ele n\u00e3o explica logo?&#8217;. E \u00e9 um sentimento leg\u00edtimo&#8221;, explicou.<\/p>\n<p>A deputada tamb\u00e9m falou sobre o momento do caso do filho do vice Hamilton Mour\u00e3o promovido com o triplo do sal\u00e1rio no Banco do Brasil, que j\u00e1 havia criticado no Twitter. &#8220;Fiquei chocada&#8221;, disse na entrevista. &#8220;N\u00e3o pela promo\u00e7\u00e3o em si, porque n\u00e3o \u00e9 il\u00edcito, mas porque \u00e9 incompat\u00edvel com o que a gente quer. Mostra mais permeabilidade do que deveria haver. N\u00e3o deveria nem passar pela cabe\u00e7a do general.&#8221;<\/p>\n<p>A parlamentar mais votada para o Legislativo estadual contou ao Estado que viu &#8220;muita vaidade, muita disputa de poder&#8221; na montagem do novo governo. &#8220;Assustador&#8221;, definiu. Sobre os deputados do PSL e de outros partidos da base que foram recentemente \u00e0 China, disse, sem especificar nomes, que &#8220;esse pessoal est\u00e1 com palha\u00e7ada&#8221;.<\/p>\n<p>&#8220;Ainda tenho d\u00favida se o mundo pol\u00edtico partid\u00e1rio \u00e9 para mim&#8221;, afirmou. Com a posse na Assembleia Legislativa marcada para 15 de mar\u00e7o, \u00e9 uma das anunciadas candidatas \u00e0 presid\u00eancia da Casa. &#8220;Ser\u00e1 muito dif\u00edcil ganhar&#8221;, disse, apontando que vai disputar. Contou, mesmo assim, que no passado fim de semana, o pai, de 65 anos, incomodado com as primeiras semanas do novo governo, perguntou a ela se n\u00e3o iria sair do PSL. A deputada foi consultar a legisla\u00e7\u00e3o, o que continua fazendo.<\/p>\n<p>Veja trechos da entrevista:<\/p>\n<p><strong>Como \u00e9 que a sra. est\u00e1 vendo o cen\u00e1rio pol\u00edtico do momento?<\/strong><\/p>\n<p>Voc\u00ea sonhar um pa\u00eds, e ver esses acontecimentos todos. Sabe o que \u00e9 jogarem um balde de \u00e1gua gelada em cima de voc\u00ea?<\/p>\n<p><strong>Quais acontecimentos?<\/strong><\/p>\n<p>Tudo. Investiga\u00e7\u00e3o, den\u00fancia, que pode ser, pode n\u00e3o ser, colegas viajando para China, xingando eleitor na internet. Acho isso tudo t\u00e3o surreal, que me pergunto: ser\u00e1 que eu ajudo mais dentro ou se eu fico fora? Essa d\u00favida eu confesso que eu tenho<\/p>\n<p><strong>Qual \u00e9 o problema com os que foram \u00e0 China, ou parte deles?<\/strong><\/p>\n<p>\u00c9 diferente ser um ativista e ser um parlamentar.<\/p>\n<p><strong>Para quem \u00e9 o recado?<\/strong><\/p>\n<p>Para todos. Estou muito preocupada, porque estou observando muitas pessoas eleitas que n\u00e3o est\u00e3o conseguindo fazer a transi\u00e7\u00e3o entre o ativismo e o cargo.<\/p>\n<p><strong>O sra. j\u00e1 criticou, na rede social, um deputado que gravou v\u00eddeos agressivos&#8230;<\/strong><\/p>\n<p>Isso n\u00e3o pode ocorrer.<\/p>\n<p><strong>O que \u00e9 que n\u00e3o pode ocorrer?<\/strong><\/p>\n<p>N\u00e3o foi uma elei\u00e7\u00e3o como outra qualquer. Foi uma elei\u00e7\u00e3o que veio depois de um sofrimento. E esse pessoal est\u00e1 com palha\u00e7ada. \u00c9 muito grave. Eu n\u00e3o tenho como dizer que n\u00e3o estou preocupada.<\/p>\n<p><strong>Quem \u00e9 esse pessoal que est\u00e1 com palha\u00e7ada?<\/strong><\/p>\n<p>Se esse pessoal que entrou, todos n\u00f3s, n\u00e3o mostrar diferen\u00e7a, n\u00e3o mostrar o comprometimento com o futuro do Pa\u00eds, o resultado catastr\u00f3fico que isso pode ter \u00e9 muito grande.<\/p>\n<p><strong>A sra. fez cr\u00edticas a epis\u00f3dios como os da promo\u00e7\u00e3o do filho do vice-presidente Hamilton Mour\u00e3o e as complica\u00e7\u00f5es do senador Fl\u00e1vio Bolsonaro.<\/strong><\/p>\n<p>Eu acho que a gente n\u00e3o pode fazer acusa\u00e7\u00f5es precipitadas contra ningu\u00e9m. Tem de dar a chance para a pessoa se manifestar. Agora, n\u00e3o acho que a gente possa minorar as situa\u00e7\u00f5es.<\/p>\n<p><strong>No caso do senador Fl\u00e1vio, o que \u00e9 que a sra. est\u00e1 achando?<\/strong><\/p>\n<p>Ele j\u00e1 explicou a situa\u00e7\u00e3o dos tais dep\u00f3sitos. \u00c9 fact\u00edvel? \u00c9 fact\u00edvel. N\u00e3o \u00e9 il\u00edcito. \u00c9 diferente. Tanto \u00e9 que o Coaf indicou uma movimenta\u00e7\u00e3o at\u00edpica, n\u00e3o necessariamente il\u00edcita.<\/p>\n<p><strong>A sra. criticou o ministro Luiz Fux, do Supremo, por ter dado a liminar em que o senador pedia suspens\u00e3o da investiga\u00e7\u00e3o.<\/strong><\/p>\n<p>A decis\u00e3o do ministro est\u00e1 errada, juridicamente errada. Porque eles, Supremo, acabaram de decidir que, se n\u00e3o fosse fato ocorrido no curso do mandato, e inerente ao mandato, n\u00e3o ficaria com foro privilegiado.<\/p>\n<p><strong>O que a sra. achou do senador concordar e defender o pedido?<\/strong><\/p>\n<p>Foi um erro. Porque, ainda que n\u00e3o tenha nada errado, isso gerou uma situa\u00e7\u00e3o, um sentimento, &#8220;poxa, mas por que n\u00e3o explica logo?&#8221;. E \u00e9 um sentimento leg\u00edtimo.<\/p>\n<p><strong>O que \u00e9 que est\u00e1 lhe incomodando especificamente no caso do senador Fl\u00e1vio Bolsonaro?<\/strong><\/p>\n<p>Ele tem todo o direito \u00e0 defesa, a entrar com todas as medidas, mas me parece complicado ver uma rea\u00e7\u00e3o parecida com a que foi a do A\u00e9cio (Neves), com a que \u00e9 a do Lula at\u00e9 hoje. Eu n\u00e3o endeuso ningu\u00e9m. &#8216;\u00c9 s\u00f3 porque eu sou filho do presidente.&#8217; N\u00e3o \u00e9 s\u00f3, p\u00f4. Teve l\u00e1 um apontamento.<\/p>\n<p><strong>O que a sra. quer saber, ent\u00e3o?<\/strong><\/p>\n<p>Se tem fundamento ou n\u00e3o tem fundamento. O sigilo sobre a investiga\u00e7\u00e3o n\u00e3o pode haver. Vamos imaginar que haja alguma coisa errada com o senador. Se isso tivesse aparecido antes da elei\u00e7\u00e3o, ele provavelmente n\u00e3o teria sido eleito.<\/p>\n<p><strong>A sra. disse que tamb\u00e9m devem ser investigados deputados de outros partidos.<\/strong><\/p>\n<p>Tem o deputado do PT, que vai ser presidente da Alerj (Assembleia Legislativa do Rio). \u00c9 um direito da popula\u00e7\u00e3o ter acesso a isso. A minha abordagem \u00e9: vamos pegar todo mundo. Se pegar todo mundo, vamos fechar e come\u00e7ar de novo.<\/p>\n<p><strong>A diferen\u00e7a no caso do senador \u00e9 que ele \u00e9 filho do presidente.<\/strong><\/p>\n<p>N\u00e3o estou antecipando culpa de ningu\u00e9m. Mas eu n\u00e3o gosto deste tom: &#8216;\u00c9 um absurdo&#8217;, &#8216;N\u00e3o vou falar&#8217;, &#8216;S\u00f3 vou falar para autoridade&#8217;. Isso relembra o passado. Para mim, foi uma coisa muito triste. Quando eu era pequena, tinha a hist\u00f3ria de um vereador que pedia dinheiro para funcion\u00e1rios. Na minha cabe\u00e7a isso era um neg\u00f3cio do passado. Essa fala do vice-presidente, &#8216;Temos de ver at\u00e9 onde \u00e9 corrup\u00e7\u00e3o, e at\u00e9 onde \u00e9 Rachid, rachadinha&#8217;. A rachadinha \u00e9 crime! Ser\u00e1 que ele falou isso mesmo?<\/p>\n<p><strong>A sra. se manifestou no epis\u00f3dio em que o filho do general Hamilton Mour\u00e3o, vice-presidente, foi beneficiado com uma promo\u00e7\u00e3o no Banco do Brasil.<\/strong><\/p>\n<p>Fiquei chocada. N\u00e3o pela promo\u00e7\u00e3o em si, porque n\u00e3o \u00e9 il\u00edcito, mas porque \u00e9 incompat\u00edvel com o que a gente quer. Mostra mais permeabilidade do que deveria haver. N\u00e3o deveria nem passar pela cabe\u00e7a do general.<\/p>\n<p><strong>Qual \u00e9 a sua preocupa\u00e7\u00e3o?<\/strong><\/p>\n<p>Meu temor \u00e9 que, se come\u00e7ar a ter epis\u00f3dios de muita permissividade, a gente vai perder for\u00e7a.<\/p>\n<p><strong>No caso do filho do general n\u00e3o caberia ao presidente Jair Bolsonaro uma manifesta\u00e7\u00e3o?<\/strong><\/p>\n<p>Eu acho que ele parou, refletiu e decidiu n\u00e3o dar uma de capit\u00e3o, e dizer: &#8216;Olha, o menino n\u00e3o vai ficar no cargo&#8217;. Teria sido melhor se o presidente tivesse se posicionado.<\/p>\n<p><strong>No dia da posse, a sra. escreveu no Twitter desejando bom governo e vida longa ao presidente. E tamb\u00e9m: &#8216;Desejo muita lealdade por parte dos membros da sua equipe&#8217;. Por que a preocupa\u00e7\u00e3o com a lealdade da equipe?<\/strong><\/p>\n<p>Muita vaidade, muita disputa de poder. Eu vivi um pouco aquilo ali (na montagem do governo). \u00c9 assustador. Se ele n\u00e3o tiver esse grupo leal, n\u00e3o a ele, mas aos princ\u00edpios que fizeram toda essa mudan\u00e7a, estamos perdidos. Isso me preocupa muito.<\/p>\n<p><strong>Por qu\u00ea?<\/strong><\/p>\n<p>Nas conversas com a equipe, as pessoas me trataram muito bem. O que era presidente do partido e agora \u00e9 ministro (Gustavo Bebianno, secret\u00e1rio-geral da Presid\u00eancia), com o qual eu tive um excelente trato, ele e o deputado Julian (Lemos, do PSL-PB) me perguntavam muito: &#8216;Voc\u00ea \u00e9 fiel ao Jair Bolsonaro? Ele \u00e9 o seu l\u00edder?&#8217; Eu disse para eles: &#8216;Voc\u00eas querem que eu minta?&#8217; Por que uma pergunta dessas para uma pessoa que acabou de conhecer a outra?<\/p>\n<p><strong>O que a sra. respondeu?<\/strong><\/p>\n<p>Que eu sou fiel ao meu Pa\u00eds, acho que ele gosta do meu Pa\u00eds, vejo nele hoje a pessoa que tem condi\u00e7\u00e3o de fazer frente ao PT. Mas quero que fique claro que eu sou fiel ao Pa\u00eds.<\/p>\n<p><strong>E como eles reagiram?<\/strong><\/p>\n<p>Disseram que achavam que eu era uma pessoa muito boa. A maneira que eles tinham de me dizer que eu n\u00e3o servia muito era me elogiando, e eu n\u00e3o sentia que era sincero. &#8216;Voc\u00ea \u00e9 uma pessoa muito boa, muito idealista&#8230;&#8217;<\/p>\n<p><strong>A sra. j\u00e1 pressente que pode virar um problema para o governo no curto, m\u00e9dio prazo?<\/strong><\/p>\n<p>Esse fim de semana meu pai me chamou e perguntou: &#8216;Filha, voc\u00ea vai se desfiliar?&#8217; Eu pensei: &#8216;Ser\u00e1 que \u00e9 uma pergunta ou uma ordem?&#8217; Eu falei: &#8216;Por que, pai?&#8217; Ele disse: &#8216;Por causa dessas coisas todas&#8217;. Eu respondi, depois de conferir a legisla\u00e7\u00e3o: &#8216;Pai, a quest\u00e3o \u00e9 a seguinte: se eu me desfilio, eu perco o mandato&#8217;.<\/p>\n<p><strong>A sra. n\u00e3o pode sair e ficar sem mandato?<\/strong><\/p>\n<p>N\u00e3o mais. A jurisprud\u00eancia mudou. Mas estou pesquisando.<\/p>\n<p><strong>Isso pouco antes de sua posse, porque n\u00e3o est\u00e1 gostando do filme.<\/strong><\/p>\n<p>Mas quem \u00e9 que est\u00e1 gostando? Eu n\u00e3o imaginava esse tipo de problema no n\u00facleo duro.<\/p>\n<p><strong>Que tipo de problema?<\/strong><\/p>\n<p>Poss\u00edveis ilicitudes. N\u00e3o estava no meu radar. Estou rezando para que esses documentos (do caso Fl\u00e1vio) venham, para que mostrem que est\u00e1 tudo correto. Tem gente que diz que \u00e9 uma guerra, que n\u00e3o pode criticar, que n\u00e3o pode nos enfraquecer. Mas isso \u00e9 PT. J\u00e1 mostrei que n\u00e3o vou deixar de fazer cr\u00edticas por uma fidelidade pessoal ao presidente. Esse governo foi eleito por causa de um n\u00facleo duro de valores, e n\u00e3o de um n\u00facleo duro de pessoas. A popula\u00e7\u00e3o votou em valores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A advogada, professora universit\u00e1ria e deputada estadual do PSL Jana\u00edna Concei\u00e7\u00e3o Paschoal, eleita com mais de dois milh\u00f5es de votos, disse ao Estado, em entrevista na \u00faltima segunda, que o senador eleito Fl\u00e1vio Bolsonaro (PSL-RJ), filho do presidente Jair Bolsonaro, &#8220;tem todo o direito \u00e0 defesa, a entrar com todas as medidas, mas me parece [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":185784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-200754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200754"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200754\/revisions"}],"predecessor-version":[{"id":200756,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200754\/revisions\/200756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/185784"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}