{"id":200776,"date":"2019-01-28T00:37:12","date_gmt":"2019-01-28T02:37:12","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200776"},"modified":"2019-01-28T05:44:37","modified_gmt":"2019-01-28T07:44:37","slug":"greve-do-caminhoneiro-ainda-da-pano-pra-manga-e-agu-pressiona-justica","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/greve-do-caminhoneiro-ainda-da-pano-pra-manga-e-agu-pressiona-justica\/","title":{"rendered":"Greve de caminhoneiro ainda d\u00e1 pano pra manga. E AGU pressiona justi\u00e7a"},"content":{"rendered":"<p>A Advocacia-Geral da Uni\u00e3o (AGU) pediu ao Supremo Tribunal Federal (STF) um esclarecimento sobre a vig\u00eancia da liminar que suspende a tramita\u00e7\u00e3o de todos os processos que questionam a tabela que fixa pre\u00e7os m\u00ednimos para o transporte de cargas no Pa\u00eds. A AGU argumenta que, ap\u00f3s a convers\u00e3o da Medida Provis\u00f3ria 832\/2018 na Lei 13.703\/2018, ju\u00edzes de inst\u00e2ncias inferiores come\u00e7aram a deferir liminares em favor de empresas e entidades para suspender os efeitos da medida, desobedecendo decis\u00e3o do ministro Luiz Fux em junho de 2018 que interrompeu a tramita\u00e7\u00e3o de todos os processos relacionados a esse tema at\u00e9 o julgamento de uma A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) pela Corte.<\/p>\n<p>De acordo com o \u00f3rg\u00e3o de advocacia da Uni\u00e3o, esses ju\u00edzes est\u00e3o tomando essas decis\u00f5es com base em interpreta\u00e7\u00e3o de que a liminar de Fux valia para a MP, e que, com a convers\u00e3o da medida em lei, caberia a retomada dos processos. A AGU cita ainda que permanece a necessidade de manter vigentes os efeitos da lei que cria a tabela de frete \u201cpara manter um contexto de estabilidade durante as tratativas das categorias envolvidas com o novo governo\u201d.<\/p>\n<p>A manifesta\u00e7\u00e3o da AGU ocorre dias depois de dois servidores do Minist\u00e9rio da Economia enviarem documento ao STF chamando caminhoneiros grevistas de \u201cconspiradores\u201d, com cr\u00edticas \u00e0 medida que estabeleceu a tabela do frete. Como mostrou o Broadcast, esses servidores \u2013 que elaboraram o parecer ainda sob o governo Michel Temer \u2013 devem ser exonerados, e a Secretaria Especial de Produtividade, Emprego e Competitividade (Sepec) informou que o tema ser\u00e1 reavaliado pelo governo de Jair Bolsonaro.<\/p>\n<p>A AGU pede que o STF preste o esclarecimento e, para n\u00e3o restarem d\u00favidas, estenda o alcance da liminar a todos os processos que envolvam a Lei 13.703\/2018. \u201cEpis\u00f3dios decis\u00f3rios como esses parecem contornar n\u00e3o s\u00f3 a autoridade das liminares concedidas na presente a\u00e7\u00e3o direta, como, de certa maneira, a pr\u00f3pria compet\u00eancia do Supremo Tribunal Federal para o julgamento de a\u00e7\u00f5es diretas de inconstitucionalidade, j\u00e1 que muitas decis\u00f5es s\u00e3o proferidas em a\u00e7\u00f5es coletivas cujo objeto \u00e9 basicamente o mesmo de um processo objetivo\u201d, argumenta a AGU.<\/p>\n<p>O \u00f3rg\u00e3o listou uma s\u00e9rie de a\u00e7\u00f5es individuais e coletivas que est\u00e3o tendo deferidos seus pedidos de liminares, a despeito do comando do STF para que os processos ficassem paralisados. \u201cFato \u00e9 que esse levantamento demonstra a exist\u00eancia de alguma margem de incompreens\u00e3o sobre a subsist\u00eancia ou n\u00e3o do conte\u00fado das decis\u00f5es proferidas pelo Ministro Relator em junho de 2018, bem como sobre seu alcance, j\u00e1 que ainda n\u00e3o havia se configurado, naquele momento, a convers\u00e3o da MP n\u00ba 832\/2018 na Lei n\u00ba 13.703\/2018\u201d, diz o documento, assinado em 25 de janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Advocacia-Geral da Uni\u00e3o (AGU) pediu ao Supremo Tribunal Federal (STF) um esclarecimento sobre a vig\u00eancia da liminar que suspende a tramita\u00e7\u00e3o de todos os processos que questionam a tabela que fixa pre\u00e7os m\u00ednimos para o transporte de cargas no Pa\u00eds. A AGU argumenta que, ap\u00f3s a convers\u00e3o da Medida Provis\u00f3ria 832\/2018 na Lei 13.703\/2018, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":189840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-200776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200776"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200776\/revisions"}],"predecessor-version":[{"id":200779,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200776\/revisions\/200779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/189840"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}