{"id":200899,"date":"2019-01-29T10:09:52","date_gmt":"2019-01-29T12:09:52","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=200899"},"modified":"2019-01-29T10:09:52","modified_gmt":"2019-01-29T12:09:52","slug":"contra-o-calor-ar-condicionado-e-ha-a-vantagem-de-matar-bacterias","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/contra-o-calor-ar-condicionado-e-ha-a-vantagem-de-matar-bacterias\/","title":{"rendered":"Contra o calor, ar-condicionado. E h\u00e1 a vantagem de matar bact\u00e9rias"},"content":{"rendered":"<p>Com um calor de mais de 30\u00baC, \u00e9 muito dif\u00edcil resistir \u00e0 tenta\u00e7\u00e3o de ficar em um ambiente com um ar-condicionado e, de prefer\u00eancia, com uma temperatura bem baixa. O entra e sai de lugares mais frescos para outros mais quentes pode causar problemas de sa\u00fade. Mas quais as consequ\u00eancias do uso excessivo do ar-condicionado?<\/p>\n<p>N\u00e3o existe um tempo m\u00ednimo ou m\u00e1ximo para a exposi\u00e7\u00e3o ao ar fresco, por\u00e9m, a manuten\u00e7\u00e3o peri\u00f3dica do equipamento \u00e9 recomendada. Para pessoas que j\u00e1 t\u00eam doen\u00e7as como rinite, sinusite, asma ou bronquite, o ideal \u00e9 manter a hidrata\u00e7\u00e3o. &#8220;Os problemas s\u00e3o pequenos e relacionados ao ressecamento das vias respirat\u00f3rias, ou seja, nada muito grave se a pessoa repuser os l\u00edquidos. Mas o ar-condicionado precisa estar com a manuten\u00e7\u00e3o em dia&#8221;, ressalta o m\u00e9dico Marcelo Vivolo Aun, diretor da Associa\u00e7\u00e3o Brasileira de Alergia e Imunologia.<\/p>\n<p>Para fazer a hidrata\u00e7\u00e3o adequada, \u00e9 necess\u00e1rio ingerir uma boa quantidade de l\u00edquidos ao longo do dia e a umidifica\u00e7\u00e3o das vias a\u00e9reas, com soro fisiol\u00f3gico nasal, por exemplo. Algumas pessoas pensam que os pacientes que s\u00e3o al\u00e9rgicos n\u00e3o podem ficar expostos ao ar-condicionado, mas essa informa\u00e7\u00e3o \u00e9 falsa.<\/p>\n<p>De acordo com o m\u00e9dico Marcelo Vivolo Aun, &#8220;\u00e1caros e fungos, importantes causadores de alergias respirat\u00f3rias, n\u00e3o sobrevivem em ambientes com ar frio e seco, que \u00e9 o que ocorre pelo uso de ar-condicionado. Isso quer dizer que o aparelho pode ser ben\u00e9fico no controle da quantidade desses al\u00e9rgenos&#8221;.<\/p>\n<p>O diretor da Associa\u00e7\u00e3o Brasileira de Alergia e Imunologia acrescenta que, nos Estados Unidos, \u00e9 recomend\u00e1vel que pacientes com alergias tenham ar-condicionado em casa para diminuir o contato com \u00e1caros e fungos. &#8220;Por\u00e9m, se for um aparelho n\u00e3o limpo adequadamente, na periodicidade correta, os dutos ficam repletos desses agentes, que podem voltar ao ambiente e serem inalados a cada novo uso&#8221;, afirma.<\/p>\n<p>A periodicidade de limpeza do ar-condicionado vai depender a instru\u00e7\u00e3o de cada fabricante do aparelho. Em todos os casos, se houver algum desconforto respirat\u00f3rio, o mais aconselhado \u00e9 consultar um especialista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com um calor de mais de 30\u00baC, \u00e9 muito dif\u00edcil resistir \u00e0 tenta\u00e7\u00e3o de ficar em um ambiente com um ar-condicionado e, de prefer\u00eancia, com uma temperatura bem baixa. O entra e sai de lugares mais frescos para outros mais quentes pode causar problemas de sa\u00fade. Mas quais as consequ\u00eancias do uso excessivo do ar-condicionado? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-200899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=200899"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200899\/revisions"}],"predecessor-version":[{"id":200901,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/200899\/revisions\/200901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200900"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=200899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=200899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=200899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}