{"id":201060,"date":"2019-01-30T20:25:42","date_gmt":"2019-01-30T22:25:42","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201060"},"modified":"2019-01-30T23:27:44","modified_gmt":"2019-01-31T01:27:44","slug":"ninguem-acerta-dezenas-e-premio-da-mega-acumula-em-25-milhoes-de-reais","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ninguem-acerta-dezenas-e-premio-da-mega-acumula-em-25-milhoes-de-reais\/","title":{"rendered":"Ningu\u00e9m acerta dezenas e pr\u00eamio da Mega acumula em 25 milh\u00f5es de reais"},"content":{"rendered":"<p>O pr\u00eamio da Mega-Sena sorteado na noite desta quarta-feira (30) acumulou. As dezenas do concurso 2.120 sorteadas foram: 13 \u2013 20 \u2013 24 \u2013 25 \u2013 38 &#8211; 41. O pr\u00eamio estimado para o pr\u00f3ximo sorteio, no s\u00e1bado (2), \u00e9 de R$ 25 milh\u00f5es.<\/p>\n<p>A quina teve 61 apostas ganhadoras; cada uma levar\u00e1 R$ 34.732,22. Outras 3.897 apostas acertaram a quadra; cada uma receber\u00e1 R$ 776,66.<\/p>\n<p>As apostas podem ser feitas at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia) nas lojas lot\u00e9ricas credenciadas pela Caixa em todo o pa\u00eds ou pela internet, no site Loterias Online.<\/p>\n<p>A aposta m\u00ednima, de seis n\u00fameros, custa R$ 3,50. Quanto mais n\u00fameros forem marcados, maior o pre\u00e7o da aposta.<\/p>\n<p>Os sorteios da Mega-Sena s\u00e3o realizados duas vezes por semana, \u00e0s quartas e aos s\u00e1bados. N\u00e3o havendo acertador em qualquer faixa, o valor acumula para o concurso seguinte, na respectiva faixa de premia\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pr\u00eamio da Mega-Sena sorteado na noite desta quarta-feira (30) acumulou. As dezenas do concurso 2.120 sorteadas foram: 13 \u2013 20 \u2013 24 \u2013 25 \u2013 38 &#8211; 41. O pr\u00eamio estimado para o pr\u00f3ximo sorteio, no s\u00e1bado (2), \u00e9 de R$ 25 milh\u00f5es. A quina teve 61 apostas ganhadoras; cada uma levar\u00e1 R$ 34.732,22. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-201060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201060"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201060\/revisions"}],"predecessor-version":[{"id":201062,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201060\/revisions\/201062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201061"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}