{"id":201067,"date":"2019-01-30T14:46:25","date_gmt":"2019-01-30T16:46:25","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201067"},"modified":"2019-01-30T23:52:26","modified_gmt":"2019-01-31T01:52:26","slug":"estudantes-tem-ate-segunda-4-para-se-matricularem-nas-faculdades","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/estudantes-tem-ate-segunda-4-para-se-matricularem-nas-faculdades\/","title":{"rendered":"Estudantes t\u00eam at\u00e9 segunda, 4, para se matricularem nas faculdades"},"content":{"rendered":"<p>J\u00e1 est\u00e1 correndo o prazo de matr\u00edcula dos selecionados no Sistema de Sele\u00e7\u00e3o Unificada (Sisu). Os estudantes t\u00eam at\u00e9 o dia 4 de fevereiro para comparecerem \u00e0s institui\u00e7\u00f5es de ensino. Os estudantes devem estar atentos aos dias, hor\u00e1rios e locais de atendimento definidos por cada institui\u00e7\u00e3o em seu edital pr\u00f3prio.<\/p>\n<p>Quem tiver o interesse e preencher os requisitos pode pleitear assist\u00eancia estudantil para cobrir custos como transporte e moradia. Segundo o MEC, os programas de assist\u00eancia estudantil s\u00e3o implementados diretamente pelas institui\u00e7\u00f5es, por isso os candidatos devem buscar informa\u00e7\u00f5es sobre os programas existentes na pr\u00f3pria institui\u00e7\u00e3o de ensino.<\/p>\n<p>Os estudantes que n\u00e3o foram aprovados em nenhuma das op\u00e7\u00f5es de curso podem integrar a lista de espera do programa. O prazo para que isso seja feito vai at\u00e9 o dia 5 de fevereiro.<\/p>\n<p>A ades\u00e3o pode ser feita na p\u00e1gina do Sisu. Os candidatos podem escolher entrar na lista de espera para a primeira ou para a segunda op\u00e7\u00e3o de curso feita na hora da inscri\u00e7\u00e3o.<\/p>\n<p>Os alunos na lista ser\u00e3o convocados pelas pr\u00f3prias institui\u00e7\u00f5es de ensino a partir do dia 7 de fevereiro.<\/p>\n<p>A partir desta edi\u00e7\u00e3o do Sisu, os estudantes que forem selecionados em qualquer uma das duas op\u00e7\u00f5es n\u00e3o poder\u00e3o participar da lista de espera. At\u00e9 o ano passado, aqueles que eram selecionados na segunda podiam ainda participar da lista e ter a chance de ser escolhido na primeira op\u00e7\u00e3o.<\/p>\n<p>Ao todo, o Sisu oferece, nesta edi\u00e7\u00e3o, 235.461 vagas em 129 institui\u00e7\u00f5es p\u00fablicas de todo o pa\u00eds. Puderam se inscrever no programa os estudantes que fizeram o Enem 2018 e obtiveram nota acima de zero na prova de reda\u00e7\u00e3o. Segundo o MEC, mais de 1,8 milh\u00e3o de candidatos se inscreveram.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 est\u00e1 correndo o prazo de matr\u00edcula dos selecionados no Sistema de Sele\u00e7\u00e3o Unificada (Sisu). Os estudantes t\u00eam at\u00e9 o dia 4 de fevereiro para comparecerem \u00e0s institui\u00e7\u00f5es de ensino. Os estudantes devem estar atentos aos dias, hor\u00e1rios e locais de atendimento definidos por cada institui\u00e7\u00e3o em seu edital pr\u00f3prio. Quem tiver o interesse e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":52514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-201067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201067"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201067\/revisions"}],"predecessor-version":[{"id":201068,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201067\/revisions\/201068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/52514"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}