{"id":201268,"date":"2019-02-02T09:04:38","date_gmt":"2019-02-02T11:04:38","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201268"},"modified":"2019-02-02T09:05:19","modified_gmt":"2019-02-02T11:05:19","slug":"feira-dos-importados-em-festa-com-ano-novo-chines","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/feira-dos-importados-em-festa-com-ano-novo-chines\/","title":{"rendered":"Feira dos Importados em festa com a chegada do Ano Novo chin\u00eas"},"content":{"rendered":"<p>A Feira dos Importados, que j\u00e1 foi chamada de Feira do Paraguai, embora os chineses mandem em quase tudo, est\u00e1 em festa. Justamente por conta da presen\u00e7a maci\u00e7a do povo chin\u00eas, que comemora a chegada do seu Ano Novo.<\/p>\n<p>Na sexta, 1, o embaixador da China no Brasil, Yang Wanming, ofereceu uma recep\u00e7\u00e3o para alguns convidados em celebra\u00e7\u00e3o ao ano novo chin\u00eas. A festa maior ser\u00e1 na ter\u00e7a, 5, quando haver\u00e1 a &#8216;virada do ano&#8217; deles.<\/p>\n<p>Os chineses s\u00e3o diferentes em quase tudo. Com um calend\u00e1rio distinto do mundo ocidental, a chegada do ano novo tamb\u00e9m tem data diferente e leva em considera\u00e7\u00e3o as fases da Lua e a posi\u00e7\u00e3o do Sol.<\/p>\n<p>Na China, o ano \u00e9 relacionado aos 12 animais que, segundo a lenda, teriam atendido ao chamado de Buda para uma reuni\u00e3o e, em agradecimento, foram transformados em signos. Este ano \u00e9 do porco. Tamb\u00e9m comp\u00f5em a lista rato, b\u00fafalo, cobra, cavalo, carneiro, macaco, galo, drag\u00e3o, tigre, touro e cachorro.<\/p>\n<p>O ano novo chin\u00eas \u00e9 a festa mais aguardada no pa\u00eds e dura cerca de duas semanas. H\u00e1 rituais, festas e muita comemora\u00e7\u00e3o. Na v\u00e9spera, os chineses limpam e arrumam a casa, cortam o cabelo, fecham as contas, presenteiam os deuses que protegem a casa, preparam as roupas, organizam a empresa e o com\u00e9rcio.<\/p>\n<p>A cor vermelha predomina, pois simboliza a transforma\u00e7\u00e3o e o movimento e a vida. O amarelo, roxo e o dourado tamb\u00e9m, pois, segundo as tradi\u00e7\u00f5es, atraem a riqueza e a prosperidade. Por tradi\u00e7\u00e3o, os chineses escrevem, neste per\u00edodo, os desejos com tinta preta em tiras de papel vermelho e penduram na porta de entrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Feira dos Importados, que j\u00e1 foi chamada de Feira do Paraguai, embora os chineses mandem em quase tudo, est\u00e1 em festa. Justamente por conta da presen\u00e7a maci\u00e7a do povo chin\u00eas, que comemora a chegada do seu Ano Novo. Na sexta, 1, o embaixador da China no Brasil, Yang Wanming, ofereceu uma recep\u00e7\u00e3o para alguns [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-201268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201268"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201268\/revisions"}],"predecessor-version":[{"id":201271,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201268\/revisions\/201271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201269"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}