{"id":201275,"date":"2019-02-02T09:22:52","date_gmt":"2019-02-02T11:22:52","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201275"},"modified":"2019-02-02T09:22:52","modified_gmt":"2019-02-02T11:22:52","slug":"definida-mesa-da-camara-briga-agora-e-pelo-comando-das-comissoes-permanentes","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/definida-mesa-da-camara-briga-agora-e-pelo-comando-das-comissoes-permanentes\/","title":{"rendered":"Definida Mesa da C\u00e2mara, briga agora \u00e9 pelo comando das Comiss\u00f5es Permanentes"},"content":{"rendered":"<p>O bloco parlamentar que inclui o PSL, partido do presidente Jair Bolsonaro, conseguiu isolar as esquerdas e vai comandar 15 das 25 comiss\u00f5es tem\u00e1ticas da C\u00e2mara, inclusive as poderosas comiss\u00f5es de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) e de Finan\u00e7as. Essa manobra articulada pelo presidente da Casa, Rodrigo Maia (DEM-RJ), foi al\u00e9m: o PT foi empurrado para comiss\u00f5es secund\u00e1rias e ficar\u00e1 at\u00e9 mesmo sem a lideran\u00e7a das oposi\u00e7\u00f5es.<\/p>\n<p>Apesar de o foco da sociedade ficar nas decis\u00f5es do plen\u00e1rio, que re\u00fane todos os 513 deputados, as comiss\u00f5es s\u00e3o fundamentais para o processo parlamentar porque todos os projetos de lei e emendas constitucionais s\u00e3o submetidas, primeiro, ao crivo desses colegiados. Pela CCJ, passam todas as propostas.<\/p>\n<p>A presid\u00eancia dessas comiss\u00f5es \u00e9 muito disputada entre os partidos e entre os pr\u00f3prios parlamentares, porque \u00e9 o presidente quem define as pautas de vota\u00e7\u00e3o, define os relatores de cada proposta e garante o cronograma e o ritmo dos trabalhos. Al\u00e9m disso, ele ganha protagonismo na rela\u00e7\u00e3o com o Pal\u00e1cio do Planalto e tem holofotes garantidos, quando se trata de comiss\u00e3o importante.<\/p>\n<p>As comiss\u00f5es t\u00eam poder, tamb\u00e9m, para convocar eventualmente ministros e autoridades para prestar esclarecimentos sobre um determinado assunto e, n\u00e3o raro, usam esse poder para pressionar o governo. Um presidente aliado ao Planalto pode evitar o constrangimento. Um que seja advers\u00e1rio pode, ao contr\u00e1rio, aprovar um requerimento de convoca\u00e7\u00e3o atr\u00e1s do outro.<\/p>\n<p>A Comiss\u00e3o de Finan\u00e7as, por exemplo, \u00e9 alvo de disputa ferrenha entre PSL e MDB, ambos do mesmo bloco. A deputada em primeiro mandato Joice Hasselmann (PSL-SP) est\u00e1 de olho na vaga, que o MDB d\u00e1 como certa que ser\u00e1 de S\u00e9rgio Souza (PR).<\/p>\n<p>Nos bastidores, Joice afirma que Rodrigo Maia &#8211; reeleito presidente da C\u00e2mara &#8211; lhe garantiu que comandaria o colegiado e que o MDB ficar\u00e1 com Minas e Energia, o que o partido diz n\u00e3o aceitar.<\/p>\n<p>A Comiss\u00e3o de Rela\u00e7\u00f5es Exteriores e de Defesa Nacional tamb\u00e9m est\u00e1 indefinida. Filho do presidente da Rep\u00fablica, Eduardo Bolsonaro (PSL-SP) trabalha para ocupar a vaga, mas outros integrantes do bloco afirmam n\u00e3o haver um acordo quanto a isso. O tema \u00e9 caro a Eduardo, que tem atuado como uma esp\u00e9cie de &#8220;chanceler informal&#8221; do governo.<\/p>\n<p>O PP tenta ocupar Minas e Energia, Rela\u00e7\u00f5es Exteriores e Agricultura, mas as negocia\u00e7\u00f5es est\u00e3o pendentes.<\/p>\n<p>A divis\u00e3o das comiss\u00f5es dentro do bloco governista ainda est\u00e1 em discuss\u00e3o e tem potencial de causar mais atritos entre os partidos que o comp\u00f5em. Al\u00e9m de PSL e MDB, est\u00e3o no mesmo grupo DEM, PSDB, PP, PSD, PR, PRB, PTB, PSC e PMN.<\/p>\n<p>O PP, por exemplo, quer a Comiss\u00e3o de Agricultura porque costuma tratar de interesses dos ruralistas. A sigla, envolvida na Lava Jato, comandou o Minist\u00e9rio da Agricultura durante o governo de Michel Temer.<\/p>\n<p>Os presidentes das comiss\u00f5es da C\u00e2mara s\u00e3o eleitos por seus integrantes, mas \u00e9 um jogo de cartas marcadas. Esse processo deve come\u00e7ar a partir da pr\u00f3xima semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O bloco parlamentar que inclui o PSL, partido do presidente Jair Bolsonaro, conseguiu isolar as esquerdas e vai comandar 15 das 25 comiss\u00f5es tem\u00e1ticas da C\u00e2mara, inclusive as poderosas comiss\u00f5es de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ) e de Finan\u00e7as. Essa manobra articulada pelo presidente da Casa, Rodrigo Maia (DEM-RJ), foi al\u00e9m: o PT foi empurrado para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201276,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-201275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201275"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201275\/revisions"}],"predecessor-version":[{"id":201277,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201275\/revisions\/201277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201276"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}