{"id":201666,"date":"2019-02-06T15:11:05","date_gmt":"2019-02-06T17:11:05","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201666"},"modified":"2019-02-06T16:15:05","modified_gmt":"2019-02-06T18:15:05","slug":"marco-aurelio-descre-de-projeto-do-ministro-sergio-moro-para-combater-o-crime","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/marco-aurelio-descre-de-projeto-do-ministro-sergio-moro-para-combater-o-crime\/","title":{"rendered":"Marco Aur\u00e9lio descr\u00ea de projeto do ministro S\u00e9rgio Moro para combater o crime"},"content":{"rendered":"<p>O ministro Marco Aur\u00e9lio Mello, do Supremo Tribunal Federal (STF), avaliou nesta quarta-feira (6) que o projeto anticrime do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, n\u00e3o necessariamente ir\u00e1 melhorar os \u00edndices de criminalidade, se aprovado, embora seja uma tentativa de impor &#8220;rigor maior&#8221; nas normas. &#8220;O aspecto formal n\u00e3o se sobrep\u00f5e \u00e0 realidade. E o endurecimento das normas penais n\u00e3o des\u00e1gua necessariamente na aus\u00eancia da pr\u00e1tica criminosa&#8221;, disse o ministro a jornalistas antes da sess\u00e3o plen\u00e1ria do STF.<\/p>\n<p>O coment\u00e1rio de Marco Aur\u00e9lio refor\u00e7a a onda de cr\u00edticas levantadas por ministros do STF desde que Moro apresentou o pacote na segunda-feira, 4. Conforme informou na \u00faltima ter\u00e7a-feira, 5, o Broadcast, sistema de not\u00edcias em tempo real do Grupo Estado, dois ministros acreditam que o projeto ser\u00e1 judicializado e que em algum momento ser\u00e1 contestado na Suprema Corte. H\u00e1 cr\u00edticas sobre a possibilidade de redu\u00e7\u00e3o ou isen\u00e7\u00e3o de pena de policial que causar morte em servi\u00e7o.<\/p>\n<p>Para Marco Aur\u00e9lio, a diminui\u00e7\u00e3o efetiva da viol\u00eancia demanda um olhar para suas causas, como o desemprego e os problemas na educa\u00e7\u00e3o, citou o ministro. &#8220;N\u00f3s precisamos buscar as causas da viol\u00eancia, precisamos ter presente o desequil\u00edbrio no mercado de trabalho, oferta excessiva de m\u00e3o de obra, escassez de emprego, precisamos cuidar da educa\u00e7\u00e3o. \u00c9 isso que realmente implicar\u00e1 a diminui\u00e7\u00e3o da delinqu\u00eancia&#8221;, pontuou.<\/p>\n<p>Assunto que tem julgamento com data marcada no STF, a execu\u00e7\u00e3o antecipada da pena tamb\u00e9m \u00e9 tratada no pacote de Moro, que tenta, atrav\u00e9s do Congresso, deixar expresso que o r\u00e9u come\u00e7a a cumprir a pena ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia. Atualmente, essa possibilidade \u00e9 autorizada por entendimento da Suprema Corte. Em abril, os ministros ir\u00e3o se debru\u00e7ar novamente sobre o tema, para julgar a quest\u00e3o definitivamente &#8211; quando poder\u00e3o alterar ou manter a jurisprud\u00eancia em vigor.<\/p>\n<p>Ao avaliar a proposta do ministro, Marco Aur\u00e9lio (contr\u00e1rio \u00e0 execu\u00e7\u00e3o antecipada da pena), afirmou que, apesar da tentativa de Moro, o &#8220;impasse continua&#8221;, j\u00e1 que a Constitui\u00e7\u00e3o Federal institui o princ\u00edpio da presun\u00e7\u00e3o da inoc\u00eancia. Na hierarquia, a Constitui\u00e7\u00e3o Federal est\u00e1 acima das leis ordin\u00e1rias, onde o ministro da Justi\u00e7a prop\u00f5e altera\u00e7\u00f5es, destacou Marco Aur\u00e9lio.<\/p>\n<p>&#8220;Vi (o projeto) de forma geral, mas o impasse continua. Porque acima da lei ordin\u00e1ria est\u00e1 a Constitui\u00e7\u00e3o, no mais visa um rigor maior quanto a glosa penal. O problema \u00e9 o conflito com o cumprimento da decis\u00e3o em segunda inst\u00e2ncia, um conflito com a Constitui\u00e7\u00e3o federal e o princ\u00edpio da n\u00e3o culpabilidade. E, mais ainda, a mat\u00e9ria est\u00e1 na pauta para o Supremo julgar&#8221;, lembrou o ministro.<\/p>\n<p>Questionado se considerava a inclus\u00e3o do tema no pacote uma tentativa de press\u00e3o no julgamento que ocorrer\u00e1 em abril, Marco Aur\u00e9lio respondeu que o STF n\u00e3o est\u00e1 &#8220;sujeito a press\u00f5es&#8221;, e que presume um &#8220;procedimento digno por parte&#8221; de Moro. &#8220;O Supremo n\u00e3o est\u00e1 sujeito a press\u00f5es, e eu julgo as pessoas por mim, eu presumo um procedimento digno da parte do ministro da Justi\u00e7a&#8221;, afirmou o ministro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Marco Aur\u00e9lio Mello, do Supremo Tribunal Federal (STF), avaliou nesta quarta-feira (6) que o projeto anticrime do ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, n\u00e3o necessariamente ir\u00e1 melhorar os \u00edndices de criminalidade, se aprovado, embora seja uma tentativa de impor &#8220;rigor maior&#8221; nas normas. &#8220;O aspecto formal n\u00e3o se sobrep\u00f5e \u00e0 realidade. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-201666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201666"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201666\/revisions"}],"predecessor-version":[{"id":201668,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201666\/revisions\/201668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201667"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}