{"id":201921,"date":"2019-02-08T15:41:51","date_gmt":"2019-02-08T17:41:51","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201921"},"modified":"2019-02-08T19:45:41","modified_gmt":"2019-02-08T21:45:41","slug":"nova-investigacao-mira-flavio-e-ele-insiste-em-perseguicao","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/nova-investigacao-mira-flavio-e-ele-insiste-em-perseguicao\/","title":{"rendered":"Nova a\u00e7\u00e3o mira Fl\u00e1vio. \u00c9 persegui\u00e7\u00e3o, diz ele"},"content":{"rendered":"<p>Uma nova investiga\u00e7\u00e3o sobre o senador Fl\u00e1vio Bolsonaro (PSL-RJ) foi aberta, desta vez no N\u00facleo de Combate \u00e0 Corrup\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF). Neste procedimento, o \u00f3rg\u00e3o vai analisar a evolu\u00e7\u00e3o patrimonial do senador. A investiga\u00e7\u00e3o foi aberta depois de um advogado ter enviado uma den\u00fancia contra o parlamentar.<\/p>\n<p>O denunciante anexou ao MPF reportagens que analisavam as transa\u00e7\u00f5es imobili\u00e1rias do ent\u00e3o deputado estadual do Rio. O procedimento foi revelado pela Rede Globo na noite da quinta-feira, 7.<\/p>\n<p>A procuradora da Rep\u00fablica Maria Helena de Paula, ent\u00e3o coordenadora criminal, determinou que o caso fosse analisado pelo N\u00facleo Criminal de Combate \u00e0 Corrup\u00e7\u00e3o. A assessoria do senador Fl\u00e1vio Bolsonaro afirmou, em nota, que ele &#8221; \u00e9 v\u00edtima de persegui\u00e7\u00e3o pol\u00edtica e que ele repudia a tentativa de imputar irregularidades e crimes onde n\u00e3o h\u00e1&#8221;.<\/p>\n<p>Esta \u00e9 a segunda investiga\u00e7\u00e3o contra o senador na Procuradoria Regional no Rio de Janeiro abordando os im\u00f3veis do parlamentar. A primeira foi aberta pela Procuradoria Regional Eleitoral (PRE), para analisar se houve crime eleitoral nas declara\u00e7\u00f5es de bens apresentadas pelo senador \u00e0 Justi\u00e7a Eleitoral.<\/p>\n<p>O caso tramitava desde mar\u00e7o de 2018 na Procuradoria Regional Eleitoral do Rio de Janeiro (PRE-RJ) e apurava poss\u00edvel crime eleitoral praticado por Fl\u00e1vio Bolsonaro ao declarar im\u00f3veis comprados por meio de \u201cnegocia\u00e7\u00f5es rel\u00e2mpago\u201d ao Tribunal Superior Eleitoral (TSE) com valores supostamente abaixo do real. No inqu\u00e9rito, h\u00e1 ainda a cita\u00e7\u00e3o de que as negocia\u00e7\u00f5es teriam resultado em aumento do patrim\u00f4nio do atual senador. H\u00e1 no inqu\u00e9rito cita\u00e7\u00e3o a poss\u00edvel lavagem de dinheiro.<\/p>\n<p>Investigadores que cuidam do caso disseram que, previamente, n\u00e3o vislumbraram ilicitude nessa quest\u00e3o. Segundo o entendimento dessas fontes, n\u00e3o seria crime eleitoral declarar ao Tribunal Regional Eleitoral im\u00f3veis com valores incompat\u00edveis com os avaliados pelo mercado.<\/p>\n<p>Tamb\u00e9m n\u00e3o seria irregular, do ponto de vista eleitoral, informar \u00e0 Justi\u00e7a Eleitoral uma quantidade de im\u00f3veis abaixo dos que verdadeiramente o candidato tem. O argumento \u00e9 que a jurisprud\u00eancia sobre casos parecidos com o de Fl\u00e1vio estabeleceu que essas informa\u00e7\u00f5es podem ser prestadas pelo candidato de forma apenas superficial e protocolar.<\/p>\n<p>A Procuradoria recebeu, ainda durante a campanha, a den\u00fancia por suposta falsifica\u00e7\u00e3o de documento p\u00fablico de Fl\u00e1vio para fins eleitorais. Depois que Fl\u00e1vio Bolsonaro, que era deputado estadual, foi eleito senador, a Procuradoria Regional Eleitoral consultou a Procuradoria Geral de Justi\u00e7a. O objetivo era saber se o caso deveria ir para Bras\u00edlia, por causa de suposto direito do senador a foro privilegiado, mas o \u00f3rg\u00e3o entendeu que n\u00e3o era o caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma nova investiga\u00e7\u00e3o sobre o senador Fl\u00e1vio Bolsonaro (PSL-RJ) foi aberta, desta vez no N\u00facleo de Combate \u00e0 Corrup\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Federal (MPF). Neste procedimento, o \u00f3rg\u00e3o vai analisar a evolu\u00e7\u00e3o patrimonial do senador. A investiga\u00e7\u00e3o foi aberta depois de um advogado ter enviado uma den\u00fancia contra o parlamentar. O denunciante anexou ao MPF [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":197091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-201921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201921"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201921\/revisions"}],"predecessor-version":[{"id":201925,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201921\/revisions\/201925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/197091"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}