{"id":201938,"date":"2019-02-08T20:25:51","date_gmt":"2019-02-08T22:25:51","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=201938"},"modified":"2019-02-08T20:26:49","modified_gmt":"2019-02-08T22:26:49","slug":"governo-aciona-termeletricas-e-conta-de-luz-pode-vir-com-surpresa-desagradavel","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/governo-aciona-termeletricas-e-conta-de-luz-pode-vir-com-surpresa-desagradavel\/","title":{"rendered":"Governo aciona usinas termel\u00e9tricas e conta de luz pode ter surpresa"},"content":{"rendered":"<p>O Comit\u00ea de Monitoramento do Setor El\u00e9trico (CMSE) decidiu nesta sexta (8), em reuni\u00e3o extraordin\u00e1ria, liberar o funcionamento de usinas termel\u00e9tricas mais caras, a chamada fora da ordem de m\u00e9rito. De acordo com o comit\u00ea, a medida foi tomada por causa da escassez de chuvas, dos n\u00edveis dos reservat\u00f3rios das hidrel\u00e9tricas que se encontram abaixo da m\u00e9dia hist\u00f3rica para o per\u00edodo e levando em considera\u00e7\u00e3o &#8220;as previs\u00f5es meteorol\u00f3gicas para os pr\u00f3ximos dias&#8221;.<\/p>\n<p>A ordem de despacho das usinas, feita pelo Operador Nacional do Sistema (ONS), \u00e9 definida pela energia de menor custo, em geral, as hidrel\u00e9tricas, at\u00e9 as t\u00e9rmicas de maior custo, fora da ordem de m\u00e9rito de custo econ\u00f4mico. Com a decis\u00e3o desta sexta-feira, ser\u00e3o despachadas as usinas cujo custo para a gera\u00e7\u00e3o de energia apresenta valores superiores aos indicados pelos modelos computacionais do setor.<\/p>\n<p>&#8220;Assim, ser\u00e3o despachadas as usinas termel\u00e9tricas at\u00e9 o limite de Custo Vari\u00e1vel Unit\u00e1rio \u2013 CVU de R$ 588,75\/MWh nos subsistemas Sudeste-Centro-Oeste e Sul, a partir de 9 de fevereiro de 2019&#8221;, disse o CMSE em nota.<\/p>\n<p>O comit\u00ea, respons\u00e1vel pelo monitoramento das condi\u00e7\u00f5es de abastecimento e pelo atendimento ao mercado de energia el\u00e9trica do pa\u00eds, decidiu ainda que o ONS deve considerar a libera\u00e7\u00e3o da importa\u00e7\u00e3o de energia do Uruguai e da Argentina, tamb\u00e9m a partir de amanh\u00e3, como recurso adicional, mas mantendo a gera\u00e7\u00e3o de usinas termel\u00e9tricas.<\/p>\n<p>Dados meteorol\u00f3gicos mostram que, em janeiro, predominou no pa\u00eds cen\u00e1rio de pouca chuva, especialmente nas regi\u00f5es Sudeste e Centro-Oeste. Com isso, a quantidade de \u00e1gua que chegou aos reservat\u00f3rios das hidrel\u00e9tricas, respons\u00e1veis por 64% do parque gerador nacional, ficou abaixo da m\u00e9dia hist\u00f3rica em todos os subsistemas.<\/p>\n<p>As informa\u00e7\u00f5es, apresentadas na reuni\u00e3o do comit\u00ea, na quarta-feira (6), mostram que o armazenamento nos reservat\u00f3rios do Subsistema Sudeste\/Centro-Oeste ficou em 26,5%; no Sul, em 44,5%; no Nordeste, em 42,1% e no Norte, em 30,6%.<\/p>\n<p>De acordo com o comit\u00ea, para este m\u00eas, h\u00e1 possibilidade de melhoria dessas condi\u00e7\u00f5es no Sudeste\/Centro-Oeste e no Norte, com a possibilidade de os armazenamentos fecharem o m\u00eas em 27,9% e 45,8%, respectivamente. As previs\u00f5es indicam piora com os reservat\u00f3rios no t\u00e9rmino do m\u00eas em 41,4%, no Sul e em 40,9%, no Nordeste.<\/p>\n<p>De acordo com o CMSE, mesmo com o cen\u00e1rio de baixa nos reservat\u00f3rios das usinas hidrel\u00e9tricas, respons\u00e1veis por dois ter\u00e7os da gera\u00e7\u00e3o de energia do pa\u00eds, est\u00e1 garantido o suprimento neste ano. O comit\u00ea ressalta, por\u00e9m, que permanecer\u00e1 acompanhando permanentemente as condi\u00e7\u00f5es de suprimento do Sistema El\u00e9trico Brasileiro, principalmente no que se refere ao n\u00edvel dos reservat\u00f3rios, e as condi\u00e7\u00f5es de atendimento ser\u00e3o reavaliadas semanalmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Comit\u00ea de Monitoramento do Setor El\u00e9trico (CMSE) decidiu nesta sexta (8), em reuni\u00e3o extraordin\u00e1ria, liberar o funcionamento de usinas termel\u00e9tricas mais caras, a chamada fora da ordem de m\u00e9rito. De acordo com o comit\u00ea, a medida foi tomada por causa da escassez de chuvas, dos n\u00edveis dos reservat\u00f3rios das hidrel\u00e9tricas que se encontram abaixo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-201938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=201938"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201938\/revisions"}],"predecessor-version":[{"id":201941,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/201938\/revisions\/201941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201939"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=201938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=201938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=201938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}