{"id":202027,"date":"2019-02-09T14:02:38","date_gmt":"2019-02-09T16:02:38","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202027"},"modified":"2019-02-14T14:26:10","modified_gmt":"2019-02-14T16:26:10","slug":"monica-pega-sansao-expulsa-mickey-e-procura-um-cantinho-para-ficar-em-sobradinho","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/monica-pega-sansao-expulsa-mickey-e-procura-um-cantinho-para-ficar-em-sobradinho\/","title":{"rendered":"M\u00f4nica pega Sans\u00e3o e expulsa Mickey para ficar em Sobradinho"},"content":{"rendered":"<p>&#8220;Esta terra \u00e9 minha. Pode ir embora&#8221;. Foi assim, em tom amea\u00e7ador, com seu coelhinho Sans\u00e3o na m\u00e3o, que M\u00f4nica resolveu expulsar de Bras\u00edlia Mickey e sua turma. Agora a a menina emburrada de Maur\u00edcio de Sousa procura um cantinho para se acomodar na capital da Rep\u00fablica. E deve ser l\u00e1 para os lados de Sobradinho.<\/p>\n<p>A ira de M\u00f4nica veio \u00e0 tona ap\u00f3s Ibaneis Rocha tentar, sem sucesso, um contato telef\u00f4nico com Mickey. Deu linha cruzada. E a turma toda &#8211; incluindo Pateta, Donald, Minie, Bafo de On\u00e7a, Peninha, Urtig\u00e3o etc &#8211; preferiu ficar pela Disney mesmo. Sucursal tupiniquim, portanto, nem pensar.<\/p>\n<p>Mas, como pretende montar um parque tem\u00e1tico em Bras\u00edlia, o governador decidiu conversar com grupos brasileiros. O objetivo \u00e9 atrair investimentos externos, gerar empregos e aquecer a economia local.<\/p>\n<p>\u201cTemos um dos maiores aeroportos do Brasil com duas pistas de pouso e capacidade de expans\u00e3o, uma rede hoteleira em crescimento, o projeto para constru\u00e7\u00e3o de um aeroporto privado em S\u00e3o Sebasti\u00e3o, al\u00e9m de infraestrutura capazes de dar sustenta\u00e7\u00e3o a um grande empreendimento\u201d, justificou Ibaneis.<\/p>\n<p>E temendo receber uma coelhadas da M\u00f4nica, Ibaneis pediu e a primeira proposta de um grupo empresarial disposto a empreender na capital. O grupo \u00e9 encabe\u00e7ado por Alain Baldacci. Ele vai discutir o futuro de um parque, nos moldes do sonhado pelo governador, com um grupo de trabalho formado pelos secret\u00e1rios de Projetos Especiais, Everardo Gueiros; de Fazenda, Andr\u00e9 Clemente; de Turismo, Vanessa Mendon\u00e7a; e de Cultura, Ad\u00e3o C\u00e2ndido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Esta terra \u00e9 minha. Pode ir embora&#8221;. Foi assim, em tom amea\u00e7ador, com seu coelhinho Sans\u00e3o na m\u00e3o, que M\u00f4nica resolveu expulsar de Bras\u00edlia Mickey e sua turma. Agora a a menina emburrada de Maur\u00edcio de Sousa procura um cantinho para se acomodar na capital da Rep\u00fablica. E deve ser l\u00e1 para os lados de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-202027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202027"}],"version-history":[{"count":5,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202027\/revisions"}],"predecessor-version":[{"id":202506,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202027\/revisions\/202506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202028"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}