{"id":202106,"date":"2019-02-10T07:47:43","date_gmt":"2019-02-10T09:47:43","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202106"},"modified":"2019-02-10T07:47:43","modified_gmt":"2019-02-10T09:47:43","slug":"apesar-de-seguras-barragens-de-brasilia-serao-vistoriadas","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/apesar-de-seguras-barragens-de-brasilia-serao-vistoriadas\/","title":{"rendered":"Apesar de seguras, barragens de Bras\u00edlia ser\u00e3o vistoriadas"},"content":{"rendered":"<p>As barragens de Bras\u00edlia n\u00e3o correm riscos de provocar uma trag\u00e9dia iminente, como acaba de acontecer em Brumadinho, Minas Gerais. Muito menos a do Parano\u00e1.<\/p>\n<p>Mas, por medida de precau\u00e7\u00e3o, a Ag\u00eancia Nacional de \u00c1guas far\u00e1 uma inspe\u00e7\u00e3o nas de Santa Maria e do Torto. O trabalho faz parte do plano priorit\u00e1rio de fiscaliza\u00e7\u00e3o para os pr\u00f3ximos 90 dias.<\/p>\n<p>Nenhuma das duas, por\u00e9m, tem situa\u00e7\u00e3o considerada cr\u00edtica. S\u00e3o vistas apenas como de m\u00e9dio risco. A Caesb, respons\u00e1vel pelas duas barragens, avalia que a seguran\u00e7a \u00e9 total.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As barragens de Bras\u00edlia n\u00e3o correm riscos de provocar uma trag\u00e9dia iminente, como acaba de acontecer em Brumadinho, Minas Gerais. Muito menos a do Parano\u00e1. Mas, por medida de precau\u00e7\u00e3o, a Ag\u00eancia Nacional de \u00c1guas far\u00e1 uma inspe\u00e7\u00e3o nas de Santa Maria e do Torto. O trabalho faz parte do plano priorit\u00e1rio de fiscaliza\u00e7\u00e3o para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-202106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202106"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202106\/revisions"}],"predecessor-version":[{"id":202108,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202106\/revisions\/202108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202107"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}