{"id":202212,"date":"2019-02-11T07:57:04","date_gmt":"2019-02-11T09:57:04","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202212"},"modified":"2019-02-11T07:58:51","modified_gmt":"2019-02-11T09:58:51","slug":"apos-decadas-no-poder-pt-mdb-e-psdb-vao-sendo-riscados-do-mapa-politico","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/apos-decadas-no-poder-pt-mdb-e-psdb-vao-sendo-riscados-do-mapa-politico\/","title":{"rendered":"Ap\u00f3s d\u00e9cadas no Poder, PT, MDB e PSDB s\u00e3o riscados do mapa"},"content":{"rendered":"<p>Ap\u00f3s tr\u00eas d\u00e9cadas ditando os rumos da pol\u00edtica no Pa\u00eds, MDB, PT e PSDB viram-se apeados n\u00e3o apenas da presid\u00eancia das duas Casas legislativas, mas tamb\u00e9m dos cargos da Mesa Diretora da C\u00e2mara. \u00c9 a primeira vez desde a redemocratiza\u00e7\u00e3o que as tr\u00eas siglas, que concentram o maior n\u00famero de filiados, ficam de fora dos postos de comando da Casa.<\/p>\n<p>As legendas tiveram de se contentar com vagas de supl\u00eancia para que n\u00e3o ficassem totalmente alijadas do arranjo capitaneado por Rodrigo Maia (DEM-RJ). Em outro lance, o PT ainda corre o risco de perder a lideran\u00e7a da minoria na Casa, por for\u00e7a de press\u00e3o de bloco encabe\u00e7ado por PDT e PCdoB.<\/p>\n<p>No Senado, o desenho final costurado por Davi Alcolumbre (DEM-AP) ajudou a atenuar a perda de espa\u00e7o do PSDB, que conquistou a 1.\u00aa vice-presid\u00eancia. O MDB, que mirava a presid\u00eancia com Renan Calheiros, acabou ficando com uma das secretarias. J\u00e1 o PT perdeu a 1.\u00aa secretaria e passou a ter a 3.\u00aa supl\u00eancia da Mesa.<\/p>\n<p>Cabe \u00e0 Mesa Diretora dirigir os trabalhos legislativos. Esses cargos tamb\u00e9m concentram poderes como examinar ressarcimentos de despesas m\u00e9dicas, pedidos de passagens \u00e1reas e emiss\u00e3o de passaportes diplom\u00e1ticos. Al\u00e9m de conferir prest\u00edgio, s\u00e3o vagas importantes para os partidos tendo em vista os cargos de assessoria a que t\u00eam direito.<\/p>\n<p>O ocaso de PT, MDB e PSDB na C\u00e2mara \u00e9 visto como reflexo do desempenho que tiveram nas urnas e de erros de estrat\u00e9gia ap\u00f3s a elei\u00e7\u00e3o, segundo parlamentares ouvidos pelo Estado. \u201cNovas for\u00e7as pol\u00edticas emergiram. Estamos na Legislatura do \u2018se vira nos trinta\u2019, diversas bancadas com cerca de 30 deputados. Isso alterou tamb\u00e9m o peso de cada partido na hora da negocia\u00e7\u00e3o\u201d, diz Marcos Pereira (PRB-SP), deputado em primeiro mandato e que foi eleito 1.\u00ba vice-presidente da C\u00e2mara.<\/p>\n<p>O MDB, que j\u00e1 teve a maior bancada da Casa, foi o que mais minguou na \u00faltima elei\u00e7\u00e3o: saiu de 66 eleitos, em 2014, para 34 em 2018. Hesitou em unir-se ao bloco costurado por Maia, selando o apoio somente \u00e0s v\u00e9speras da elei\u00e7\u00e3o, quando as principais vagas da Mesa j\u00e1 haviam sido negociadas. Ficou com uma supl\u00eancia e ainda disputa nos bastidores a presid\u00eancia de uma comiss\u00e3o importante. Desde a Constituinte, o partido jamais ficara sem um posto na Mesa Diretora. \u201cTinham a fonte a seu lado, n\u00e3o deram bola, e agora ter\u00e3o de se contentar com um copo d\u2019\u00e1gua\u201d, diz o deputado Hugo Leal, do PSD, um dos primeiros partidos a fechar com Maia.<\/p>\n<p><strong>Acordos<\/strong> &#8211; Maia come\u00e7ou a costurar acordos para se manter na presid\u00eancia ainda no ano passado. Entrou em 2019 com acertos adiantados com Gilberto Kassab (PSD) e Valdemar Costa Neto (PR). Sem um nome competitivo, o PSL, partido do presidente Jair Bolsonaro, desistiu de tentar a presid\u00eancia e fechou acordo com Maia em troca de um lugar na mesa e da presid\u00eancia das comiss\u00f5es de maior relevo da Casa. Foi a senha para que outras siglas, como o PRB, se unissem ao bloco.<\/p>\n<p>O PSDB at\u00e9 correu para se acertar com Maia logo nos primeiros dias do ano, mas seu poder de fogo estava limitado. Com 54 deputados e a 3.\u00aa maior bancada na Legislatura passada, os tucanos chegaram em 2019 com 29 parlamentares, a 8.\u00aa maior bancada. \u201cA negocia\u00e7\u00e3o pol\u00edtica permitiu que o PSDB n\u00e3o perdesse tanto espa\u00e7o\u201d, diz Carlos Sampaio, l\u00edder do partido na C\u00e2mara. Segundo ele, o PSDB ter\u00e1 nomes em comiss\u00f5es e outros cargos da Casa. Desde sua funda\u00e7\u00e3o, em 1988, o PSDB s\u00f3 ficara uma vez sem cargo na mesa, na presid\u00eancia de Ibsen Pinheiro, em 1991.<\/p>\n<p>Mesmo tendo eleito a maior bancada no ano passado, com 56 deputados, o PT ficou apenas com uma vaga de suplente na mesa e deve ter o comando de uma comiss\u00e3o de menor import\u00e2ncia. Manteve, assim, situa\u00e7\u00e3o da Legislatura passada. Desde 1997, quando passou a ter cargo na Mesa Diretora, o PT experimentara dois hiatos: de 2005 a 2007, quando Severino Cavalcanti (PP-PE) foi eleito, alijando o partido do ent\u00e3o governo do comando, e de 2015 para c\u00e1, com as elei\u00e7\u00f5es de Eduardo Cunha (PMDB-RJ) e Maia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s tr\u00eas d\u00e9cadas ditando os rumos da pol\u00edtica no Pa\u00eds, MDB, PT e PSDB viram-se apeados n\u00e3o apenas da presid\u00eancia das duas Casas legislativas, mas tamb\u00e9m dos cargos da Mesa Diretora da C\u00e2mara. \u00c9 a primeira vez desde a redemocratiza\u00e7\u00e3o que as tr\u00eas siglas, que concentram o maior n\u00famero de filiados, ficam de fora dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202212"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202212\/revisions"}],"predecessor-version":[{"id":202215,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202212\/revisions\/202215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200120"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}