{"id":202293,"date":"2019-02-12T05:28:07","date_gmt":"2019-02-12T07:28:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202293"},"modified":"2019-02-12T08:30:43","modified_gmt":"2019-02-12T10:30:43","slug":"incendio-em-hotel-da-india-deixa-17-mortos","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/incendio-em-hotel-da-india-deixa-17-mortos\/","title":{"rendered":"Inc\u00eandio em hotel da \u00cdndia deixa 17 mortos"},"content":{"rendered":"<p>Dezessete pessoas morreram em um inc\u00eandio nesta ter\u00e7a-feira, 12, no hotel Arpit Palace, na regi\u00e3o central de Nova D\u00e9lhi, na \u00cdndia. De acordo com o vice-comiss\u00e1rio da pol\u00edcia local, Mandeep Singh Randhawa, pelo menos outras quatro pessoas ficaram feridas em raz\u00e3o das chamas.<\/p>\n<p>Cerca de 35 pessoas foram resgatadas pelos bombeiros. N\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a situa\u00e7\u00e3o de sa\u00fade dos feridos. O hotel est\u00e1 localizado no bairro Karol Bagh, uma \u00e1rea na capital da \u00cdndia onde ficam lojas e hot\u00e9is populares entre os turistas.<\/p>\n<p>Vinte e cinco carros de bombeiros atuaram contra o inc\u00eandio, que destruiu praticamente todo o pr\u00e9dio de cinco andares. Apenas o t\u00e9rreo foi preservado.<\/p>\n<p>Mais de cem pessoas morreram desde quinta-feira, dia 7, pelo consumo de \u00e1lcool adulterado no norte da \u00cdndia. A pol\u00edcia prendeu mais de 3 mil pessoas envolvidas com o contrabando de bebida. Autoridades indianas acreditam que um licor popular na regi\u00e3o pode ter sido misturado com metanol e pesticidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dezessete pessoas morreram em um inc\u00eandio nesta ter\u00e7a-feira, 12, no hotel Arpit Palace, na regi\u00e3o central de Nova D\u00e9lhi, na \u00cdndia. De acordo com o vice-comiss\u00e1rio da pol\u00edcia local, Mandeep Singh Randhawa, pelo menos outras quatro pessoas ficaram feridas em raz\u00e3o das chamas. Cerca de 35 pessoas foram resgatadas pelos bombeiros. N\u00e3o h\u00e1 informa\u00e7\u00f5es sobre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-202293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202293"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202293\/revisions"}],"predecessor-version":[{"id":202295,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202293\/revisions\/202295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202294"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}