{"id":202296,"date":"2019-02-12T08:38:23","date_gmt":"2019-02-12T10:38:23","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202296"},"modified":"2019-02-12T08:38:23","modified_gmt":"2019-02-12T10:38:23","slug":"bmg-abusa-e-fica-proibido-de-aliciar-aposentados","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bmg-abusa-e-fica-proibido-de-aliciar-aposentados\/","title":{"rendered":"BMG abusa e fica proibido de &#8216;aliciar&#8217; aposentados"},"content":{"rendered":"<p>Decis\u00e3o da justi\u00e7a de Minas Gerais suspendeu a comercializa\u00e7\u00e3o de cart\u00e3o de cr\u00e9dito consignado pelo Banco BMG porque a institui\u00e7\u00e3o estaria oferecendo o servi\u00e7o de forma irregular &#8211; via telefone &#8211; a idosos, aposentados e pensionistas.<\/p>\n<p>O caso, que tramita h\u00e1 mais de dez anos na Justi\u00e7a, voltou \u00e0 tona ap\u00f3s alega\u00e7\u00f5es de que a institui\u00e7\u00e3o estaria descumprindo uma determina\u00e7\u00e3o judicial que, em 2008, j\u00e1 a proibia de realizar esse tipo de contrata\u00e7\u00e3o por meio de telefonemas.<\/p>\n<p>A decis\u00e3o aumenta para R$ 200 mil a multa di\u00e1ria que pode ser imposta ao banco em rela\u00e7\u00e3o a qualquer produto relacionado ao cart\u00e3o de cr\u00e9dito consignado pelo telefone &#8211; com limite de R$ 100 milh\u00f5es. A suspens\u00e3o da comercializa\u00e7\u00e3o do servi\u00e7o vale at\u00e9 que o BMG comprove que n\u00e3o estava realizando a pr\u00e1tica vedada durante os \u00faltimos anos.<\/p>\n<p>O banco afirmou em nota que ir\u00e1 recorrer, e que houve &#8220;lament\u00e1vel equ\u00edvoco&#8221; na decis\u00e3o. Declarou ainda que o BMG &#8220;obedece criteriosamente ao que disp\u00f5e as normas aplic\u00e1veis \u00e0 contrata\u00e7\u00e3o dos empr\u00e9stimos&#8221;.<\/p>\n<p>N\u00e3o \u00e9 o mesmo entendimento da advogada Lillian Salgado, que atua no Instituto Defesa Coletiva, sociedade civil sem fins lucrativos respons\u00e1vel pelo pedido feito \u00e0 justi\u00e7a mineira contra o banco. Segundo Lilian, a determina\u00e7\u00e3o judicial vale para todo o territ\u00f3rio nacional. &#8220;Pelas regras do processo coletivo no Pa\u00eds, esta a\u00e7\u00e3o tem extens\u00e3o para todo Brasil&#8221;, diz<\/p>\n<p>Em nota, o Instituto Nacional do Seguro Social (INSS) afirma que, de nenhuma maneira, o consignado pode ser concedido por telefone, sem o comparecimento do segurado ao banco ou financeira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o da justi\u00e7a de Minas Gerais suspendeu a comercializa\u00e7\u00e3o de cart\u00e3o de cr\u00e9dito consignado pelo Banco BMG porque a institui\u00e7\u00e3o estaria oferecendo o servi\u00e7o de forma irregular &#8211; via telefone &#8211; a idosos, aposentados e pensionistas. O caso, que tramita h\u00e1 mais de dez anos na Justi\u00e7a, voltou \u00e0 tona ap\u00f3s alega\u00e7\u00f5es de que a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-202296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202296"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202296\/revisions"}],"predecessor-version":[{"id":202298,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202296\/revisions\/202298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202297"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}