{"id":202332,"date":"2019-02-12T15:08:10","date_gmt":"2019-02-12T17:08:10","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202332"},"modified":"2019-02-12T15:09:41","modified_gmt":"2019-02-12T17:09:41","slug":"aecio-mineirinho-levou-30-milhoes-diz-nova-delacao","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/aecio-mineirinho-levou-30-milhoes-diz-nova-delacao\/","title":{"rendered":"A\u00e9cio &#8216;Mineirinho&#8217; levou 30 milh\u00f5es, diz nova dela\u00e7\u00e3o"},"content":{"rendered":"<p>Em depoimento que citou o deputado federal A\u00e9cio Neves (PSDB-MG), o ex-gerente de Recursos Humanos da Odebrecht \u00canio Augusto Pereira e Silva, um dos delatores da Opera\u00e7\u00e3o Lava Jato, afirmou \u00e0 Pol\u00edcia Federal que o ex-presidente da Odebrecht Infraestrutura Henrique Valladares se reuniu com o ex-diretor de Furnas Dimas Toledo. Segundo o executivo, Henrique Valladares e Dimas Toledo se encontraram &#8220;para tratar a respeito de pagamentos&#8221; para &#8220;Mineirinho&#8221;.<\/p>\n<p>\u00canio Augusto Pereira e Silva falou \u00e0 PF em um inqu\u00e9rito que apura o suposto pagamento de R$ 30 milh\u00f5es da Odebrecht para o tucano &#8211; R$ 28,2 milh\u00f5es em dinheiro entregue em uma sala comercial em Ipanema, no Rio, e US$ 900 mil em pagamentos no exterior. O valor teria sido repassado para que A\u00e9cio Neves &#8220;influenciasse o andamento dos Projetos do Rio Madeira (Usinas Hidrel\u00e9tricas de Santo Ant\u00f4nio e Jirau, em Rond\u00f4nia) atendendo aos interesse do grupo e da Andrade Gutierrez&#8221;.<\/p>\n<p>Segundo os delatores da Odebrecht, Dimas Fabiano Toledo operou os pagamentos. Investigadores afirmam que &#8220;Mineirinho&#8221; \u00e9 o deputado A\u00e9cio.<\/p>\n<p>Os executivos da empreiteira narraram que Dimas Toledo &#8220;esteve no escrit\u00f3rio da Odebrecht no Rio de Janeiro e apresentou um cronograma de pagamentos referentes aos R$ 30 milh\u00f5es que cabiam \u00e0 empresa&#8221;.<\/p>\n<p>\u00canio Silva esteve em Bras\u00edlia em 4 de dezembro do ano passado para falar &#8220;sobre os fatos envolvendo pagamentos indevidos a pessoa de codinome Mineirinho, tendo em vista a homologa\u00e7\u00e3o da sua ades\u00e3o ao acordo de leni\u00eancia da empresa Odebrecht&#8221;.<\/p>\n<p>O delator contou \u00e0 PF que &#8220;al\u00e9m das atividades relacionadas \u00e0 ger\u00eancia de recursos humanos, recebeu a incumb\u00eancia de realizar a programa\u00e7\u00e3o dos pagamentos de &#8216;caixa 2&#8217; da \u00e1rea de energia da Odebrecht&#8221;.<\/p>\n<p>&#8220;Acerca do programa pagamentos realizados no Projeto Madeira, tendo como destinat\u00e1rio o senador A\u00e9cio Neves, afirma que ao chegar na \u00e1rea de energia, o declarante recebeu uma planilha de Jos\u00e9 Carlos Grossi contendo pagamentos relacionados ao Projeto Madeira, que estava em andamento&#8221;, contou.<\/p>\n<p>O delator disse que verificou a programa\u00e7\u00e3o de pagamentos de codinome &#8220;Mineirinho&#8221; na planilha. \u00canio Augusto Pereira e Silva disse \u00e0 Pol\u00edcia Federal que, em 2009, &#8220;j\u00e1 haviam feito pagamentos, mas que ainda restava uma parte&#8221;.<\/p>\n<p>&#8220;O declarante se recorda que, em pelo menos duas oportunidades, o sr. Henrique Valladares solicitou que o declarante verificasse a situa\u00e7\u00e3o dos saldos de pagamentos feitos a Mineirinho; que nestas oportunidades o sr. Henrique Valladares estava reunido com o sr. Dimas Toledo para tratar a respeito desses pagamentos&#8221;, afirmou.<\/p>\n<p><strong>Nota da defesa de Dimas<\/strong><br \/>\nO advogado Rog\u00e9rio Marcolini afirmou que Dimas Toledo &#8220;conheceu Henrique Valadares na qualidade de executivo da Odebrecht quando diretor de Furnas, com quem teve poucos contatos \u00e0 \u00e9poca&#8221;.<\/p>\n<p>&#8220;Depois que deixou a empresa, n\u00e3o tratou de qualquer neg\u00f3cio com referido senhor, com quem teve apenas encontros sociais. Dimas jamais esteve com Henrique Valadares para tratar de assuntos de interesse de A\u00e9cio Neves ou de &#8220;Mineirinho&#8221;, n\u00e3o tendo conhecimento do apelido ou de quem poderia ser chamado por tal alcunha&#8221;, afirmou.<\/p>\n<p><strong>Nota da defesa de A\u00e9cio<\/strong><br \/>\n&#8220;Em seu depoimento, o Sr. \u00canio Pereira, funcion\u00e1rio da Odebrecht, sequer cita o nome do deputado A\u00e9cio Neves, a quem n\u00e3o conhece, e tampouco faz qualquer liga\u00e7\u00e3o do deputado ao codinome apresentado. Registre-se que o delator foi chamado para depor sobre determinado codinome e n\u00e3o sobre acusa\u00e7\u00f5es ao deputado A\u00e9cio. Depois de mais de dois anos de investiga\u00e7\u00f5es n\u00e3o foi encontrado qualquer elemento que vinculasse o deputado \u00e0s den\u00fancias feitas. Raz\u00e3o pela qual a defesa confia no arquivamento do presente inqu\u00e9rito.<br \/>\nAlberto Zacharias Toron<br \/>\nAdvogado&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em depoimento que citou o deputado federal A\u00e9cio Neves (PSDB-MG), o ex-gerente de Recursos Humanos da Odebrecht \u00canio Augusto Pereira e Silva, um dos delatores da Opera\u00e7\u00e3o Lava Jato, afirmou \u00e0 Pol\u00edcia Federal que o ex-presidente da Odebrecht Infraestrutura Henrique Valladares se reuniu com o ex-diretor de Furnas Dimas Toledo. Segundo o executivo, Henrique Valladares [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-202332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202332"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202332\/revisions"}],"predecessor-version":[{"id":202335,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202332\/revisions\/202335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202333"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}