{"id":202483,"date":"2019-02-14T10:11:09","date_gmt":"2019-02-14T12:11:09","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202483"},"modified":"2019-02-14T10:11:51","modified_gmt":"2019-02-14T12:11:51","slug":"bolsonaro-volta-como-trator-para-aprovar-a-previdencia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-volta-como-trator-para-aprovar-a-previdencia\/","title":{"rendered":"Bolsonaro volta como trator para aprovar a Previd\u00eancia"},"content":{"rendered":"<p>Com o presidente Jair Bolsonaro liberado pelos m\u00e9dicos para o trabalho, nesta semana foram esclarecidas todas as d\u00favidas que ainda persistiam sobre o projeto de mudan\u00e7as nas regras da Previd\u00eancia. Finalmente, na pr\u00f3xima semana, a nova Previd\u00eancia seguir\u00e1 para o Congresso Nacional. \u00c9 o inicio da guerra para recolocar o Brasil na rota do crescimento.<\/p>\n<p>O presidente da C\u00e2mara, deputado Rodrigo Maia, alertou que agora caber\u00e1 ao Pal\u00e1cio do Planalto a estrutura\u00e7\u00e3o da base aliada de forma ela reunir pelo menos 320 deputados, para garantir os 308 votos necess\u00e1rios para aprova\u00e7\u00e3o da PEC da Previd\u00eancia.<\/p>\n<p>Isto ocorrendo, a mat\u00e9ria tramitar\u00e1 na C\u00e2mara com prioridade, podendo ser votada at\u00e9 maio. Para ter \u00eaxito nessa vota\u00e7\u00e3o, Bolsonaro ter\u00e1 de aproveitar a presente popularidade que ainda tem junto a popula\u00e7\u00e3o.<\/p>\n<p>Davi Alcolumbre, presidente do Senado, garantiu que os senadores ter\u00e3o condi\u00e7\u00f5es de sacramentar a nova Previd\u00eancia, se aprovada pela C\u00e2mara, at\u00e9 15 de julho, in\u00edcio do recesso parlamentar do meio de ano.<\/p>\n<p>O ministro da Economia, Paulo Guedes, afirmou que essa reforma representar\u00e1 uma economia nos cofres p\u00fablicos de R$ 1 trilh\u00e3o nos pr\u00f3ximos dez anos.<\/p>\n<p>Ele revelou que est\u00e3o em estudo medidas para desafogar financeiramente os Estados, em sua grande maioria quebrados. Paulo Guedes tem como estrat\u00e9gia o uso dos governadores para ajudar a convencer os deputados e senadores a votarem as mudan\u00e7as.<\/p>\n<p>O governo est\u00e1 articulando uma campanha de comunica\u00e7\u00e3o para esclarecer a popula\u00e7\u00e3o sobre as novas regras previdenci\u00e1rias, para, assim, se contrapor a decis\u00e3o da oposi\u00e7\u00e3o de combater a reforma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o presidente Jair Bolsonaro liberado pelos m\u00e9dicos para o trabalho, nesta semana foram esclarecidas todas as d\u00favidas que ainda persistiam sobre o projeto de mudan\u00e7as nas regras da Previd\u00eancia. Finalmente, na pr\u00f3xima semana, a nova Previd\u00eancia seguir\u00e1 para o Congresso Nacional. \u00c9 o inicio da guerra para recolocar o Brasil na rota do crescimento. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202483"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202483\/revisions"}],"predecessor-version":[{"id":202486,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202483\/revisions\/202486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202484"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}