{"id":202503,"date":"2019-02-14T14:21:25","date_gmt":"2019-02-14T16:21:25","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202503"},"modified":"2019-02-14T14:21:25","modified_gmt":"2019-02-14T16:21:25","slug":"moro-o-faz-tudo-e-chamado-para-socorrer-senado","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/moro-o-faz-tudo-e-chamado-para-socorrer-senado\/","title":{"rendered":"Moro, o faz tudo, \u00e9 chamado para socorrer Senado"},"content":{"rendered":"<p>A corregedoria do Senado pediu a ajuda do ministro da Justi\u00e7a, S\u00e9rgio Moro, para descobrir se houve fraude na vota\u00e7\u00e3o da presid\u00eancia da Casa, no dia 2 deste m\u00eas. Na ocasi\u00e3o, foram encontradas 82 c\u00e9dulas na urna de vota\u00e7\u00e3o, uma a mais do que o n\u00famero de senadores na Casa. Seis parlamentares s\u00e3o considerados suspeitos.<\/p>\n<p>O corregedor, senador Roberto Rocha (PSDB-MA), disse que ligou para o ministro para solicitar o aux\u00edlio da Pol\u00edcia Federal na avalia\u00e7\u00e3o de imagens capturadas. Al\u00e9m de v\u00eddeos, est\u00e3o sob an\u00e1lise mais de 11 mil fotografias. J\u00e1 o presidente do Senado, Davi Alcolumbre, afirmou que &#8220;o procedimento (da investiga\u00e7\u00e3o) \u00e9 delicado e requer paci\u00eancia&#8221;.<\/p>\n<p>Rocha afirmou que \u00e9 necess\u00e1rio equipamento de alta tecnologia para concluir a investiga\u00e7\u00e3o. Al\u00e9m da PF, o senador cogita tamb\u00e9m solicitar aux\u00edlio da Universidade Federal de Bras\u00edlia (UnB). Para o corregedor, &#8220;\u00e9 pouco prov\u00e1vel&#8221; que o voto duplo tenha sido um equ\u00edvoco.<\/p>\n<p>&#8220;Algu\u00e9m, por equ\u00edvoco ou m\u00e1-f\u00e9 n\u00e3o posso dizer ainda, embora seja muito pouco prov\u00e1vel que tenha sido um equ\u00edvoco, deixou de botar a c\u00e9dula dentro do envelope para colocar duas c\u00e9dulas dentro da urna, sem envelope&#8221;, disse Rocha. &#8220;Algu\u00e9m substituiu um envelope por uma segunda c\u00e9dula. Em que momento foi isso? \u00c9 o que estamos olhando nas imagens.&#8221;<\/p>\n<p>Pelo conte\u00fado analisado at\u00e9 agora, o corregedor disse que tamb\u00e9m \u00e9 poss\u00edvel que a c\u00e9dula a mais tenha sido colocada na urna durante os \u00faltimos votos, j\u00e1 no s\u00e1bado pela manh\u00e3. &#8220;Na primeira m\u00e3ozada j\u00e1 vieram os dois votos&#8221;, afirmou Rocha.<\/p>\n<p>Ainda de acordo com o corregedor, dos 81 senadores, n\u00e3o \u00e9 poss\u00edvel ver com clareza o momento da vota\u00e7\u00e3o de seis deles. Esses parlamentares n\u00e3o tiveram seus nomes revelados. &#8220;Tem uma meia d\u00fazia de casos que n\u00e3o d\u00e1 pra ver com os recursos que temos Estou tentando ver se conseguimos um recurso mais espec\u00edfico, da PF, da UnB ou dos dois.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A corregedoria do Senado pediu a ajuda do ministro da Justi\u00e7a, S\u00e9rgio Moro, para descobrir se houve fraude na vota\u00e7\u00e3o da presid\u00eancia da Casa, no dia 2 deste m\u00eas. Na ocasi\u00e3o, foram encontradas 82 c\u00e9dulas na urna de vota\u00e7\u00e3o, uma a mais do que o n\u00famero de senadores na Casa. Seis parlamentares s\u00e3o considerados suspeitos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-202503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202503"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202503\/revisions"}],"predecessor-version":[{"id":202505,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202503\/revisions\/202505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202504"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}