{"id":202622,"date":"2019-02-16T00:06:35","date_gmt":"2019-02-16T02:06:35","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202622"},"modified":"2019-02-16T09:08:32","modified_gmt":"2019-02-16T11:08:32","slug":"carro-de-prefeito-de-belfort-roxo-e-atingido-por-tiro-de-fuzil","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/carro-de-prefeito-de-belfort-roxo-e-atingido-por-tiro-de-fuzil\/","title":{"rendered":"Carro de prefeito de Belfort Roxo \u00e9 atingido por tiro de fuzil"},"content":{"rendered":"<p>O prefeito de Belford Roxo, na Baixada Fluminense, Wagner dos Santos Carneiro (MDB), o Waguinho, e a mulher dele, a deputada federal Daniela do Waguinho (MDB), sofreram nesta sexta-feira, 15, um atentado a tiros de fuzil no retorno da inaugura\u00e7\u00e3o da Creche Municipal Manoel da Silva Curty, no bairro Santa Tereza, no Rio. O carro da parlamentar ficou com as marcas de bala.<\/p>\n<p>De acordo com relatos na p\u00e1gina da prefeitura no Facebook, Waguinho e Daniela foram atacados na Avenida Autom\u00f3vel Clube, na altura da Rodovi\u00e1ria do Parque S\u00e3o Jos\u00e9. O carro, uma Hilux blindada, foi alvejado por um tiro de fuzil na porta do motorista. Foram v\u00e1rios tiros, que teriam sido disparados do Morro da Caixa D\u2019\u00e1gua.<\/p>\n<p>O munic\u00edpio de Belford Roxo fica na regi\u00e3o norte do Estado do Rio de Janeiro Foto: Divulga\u00e7\u00e3o<br \/>\n&#8220;Apesar dos v\u00e1rios disparos efetuados do alto do morro, apenas um tiro de fuzil atingiu a lataria do carro do prefeito que retornava com a mulher no banco do carona\u201d.<\/p>\n<p>A assessoria da Pol\u00edcia Militar confirmou a informa\u00e7\u00e3o relatada pela prefeitura nas redes sociais. A PM acrescentou que, no mesmo hor\u00e1rio, um homem foi atingido por estilha\u00e7os na perna, quando passava pela Avenida Autom\u00f3vel Clube. A v\u00edtima foi socorrida na Unidade Mista do Lote XV e est\u00e1 fora de perigo. O caso foi registrado na 54\u00aa delegacia policial (Belford Roxo).<\/p>\n<p>Em outubro de 2018, o prefeito Waguinho foi flagrado fazendo boca de urna no segundo turno da elei\u00e7\u00e3o do ano passado, no Ciep Monsenhor Solano Dantas, em Heli\u00f3polis, Belford Roxo, e fugiu. Segundo o Tribunal Regional Eleitoral do Rio, ele foi flagrado por uma promotora eleitoral. O caso foi registrado na 54\u00aa Delegacia Pol\u00edcia (Belford Roxo).<\/p>\n<p>Na \u00e9poca, a assessoria do prefeito informou que ele chegou ao local onde vota com adesivo exposto na roupa como manifesta\u00e7\u00e3o silenciosa e legal, cumprimentou eleitores, mas n\u00e3o pediu voto para nenhum candidato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Belford Roxo, na Baixada Fluminense, Wagner dos Santos Carneiro (MDB), o Waguinho, e a mulher dele, a deputada federal Daniela do Waguinho (MDB), sofreram nesta sexta-feira, 15, um atentado a tiros de fuzil no retorno da inaugura\u00e7\u00e3o da Creche Municipal Manoel da Silva Curty, no bairro Santa Tereza, no Rio. O carro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202622"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202622\/revisions"}],"predecessor-version":[{"id":202624,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202622\/revisions\/202624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202623"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}