{"id":202725,"date":"2019-02-17T09:16:29","date_gmt":"2019-02-17T12:16:29","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202725"},"modified":"2019-02-17T10:21:36","modified_gmt":"2019-02-17T13:21:36","slug":"alcolumbre-vai-passar-vassoura-em-aliados-de-renan-eunicio-e-sarney","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/alcolumbre-vai-passar-vassoura-em-aliados-de-renan-eunicio-e-sarney\/","title":{"rendered":"Alcolumbre vai passar vassoura em aliados de Renan, Eun\u00edcio e Sarney"},"content":{"rendered":"<p>Apesar do discurso de pacifica\u00e7\u00e3o adotado ap\u00f3s ser eleito presidente do Senado, Davi Alcolumbre (DEM-AP) prepara uma &#8220;faxina&#8221; em cargos de diretoria e coordenadoria da Casa controlados pelo MDB. O alvo s\u00e3o servidores apadrinhados por seus antecessores &#8211; Eun\u00edcio Oliveira (CE), Jos\u00e9 Sarney (AP) e Renan Calheiros (AL).<\/p>\n<p>O pr\u00f3prio Renan deve ser &#8220;demitido&#8221; por Alcolumbre do cargo de ouvidor do Senado. Respons\u00e1vel por receber a opini\u00e3o dos cidad\u00e3os sobre a Casa Legislativa, o mandato do senador alagoano n\u00e3o ser\u00e1 renovado.<\/p>\n<p>A lista de diretores, secret\u00e1rios e coordenadores de \u00e1reas que v\u00e3o passar pelo pente-fino tem 184 nomes. A avalia\u00e7\u00e3o do presidente do Senado e de pessoas do seu entorno \u00e9 de que, se quiser fazer uma renova\u00e7\u00e3o na Casa, como prometeu aos colegas, precisar\u00e1 acabar com o que considera &#8220;maus h\u00e1bitos&#8221; que estariam impregnados nos principais postos de comando. Na pr\u00e1tica, o controle vai passar para as m\u00e3os do novo grupo que comandar\u00e1 o Senado no bi\u00eanio 2019-2020.<\/p>\n<p>Foi com a promessa de cargos que Alcolumbre conseguiu votos suficientes para se eleger presidente e derrotar Renan. Senadores que atuaram como seus cabos eleitorais espalharam a mensagem de que, se Renan fosse eleito, os novatos n\u00e3o teriam chance de ocupar os postos da Casa. Ao todo, o Senado tem cerca de 2.500 cargos de livre nomea\u00e7\u00e3o. &#8220;A gente ia falando isso de orelha em orelha&#8221;, afirmou um senador que participou da campanha<\/p>\n<p>A primeira demiss\u00e3o foi do diretor da Pol\u00edcia Legislativa, Pedro Ricardo Ara\u00fajo Carvalho, que ocupava o cargo h\u00e1 14 anos. Ele chegou por indica\u00e7\u00e3o de Renan e permanecia no cargo. Em 2016 foi preso por quatro dias durante a Opera\u00e7\u00e3o M\u00e9tis, da Pol\u00edcia Federal. Motivo: suspeita de prestar servi\u00e7o de contraintelig\u00eancia para ajudar senadores investigados na Opera\u00e7\u00e3o Lava Jato. O diretor sempre negou as acusa\u00e7\u00f5es.<\/p>\n<p>O presidente do Senado ainda analisa a perman\u00eancia de outros ocupantes de cargos-chave que t\u00eam suas trajet\u00f3rias de ascens\u00e3o atreladas a emedebistas. Entre eles o secret\u00e1rio-geral do Senado, Luiz Fernando Bandeira de Mello, que chegou a ser destitu\u00eddo por Alcolumbre no dia da elei\u00e7\u00e3o ap\u00f3s manobra que favoreceu Renan, mas foi reconduzido ao posto.<\/p>\n<p>Uma resolu\u00e7\u00e3o elaborada pelo secret\u00e1rio favoreceria a t\u00e1tica de Renan para garantir que a elei\u00e7\u00e3o fosse secreta e n\u00e3o por meio de voto aberto, como defendia Alcolumbre. Alvo de campanha nas redes sociais, o emedebista acreditava que teria chance de vencer apenas com a elei\u00e7\u00e3o secreta. Ao final, prevaleceu o voto fechado, mas senadores protestaram mostrando suas c\u00e9dulas para o plen\u00e1rio.<\/p>\n<p>Segundo a reportagem apurou, Bandeira de Mello passa por uma esp\u00e9cie de &#8220;est\u00e1gio probat\u00f3rio&#8221;. Por enquanto, a ideia de Alcolumbre \u00e9 testar a confiabilidade do secret\u00e1rio-geral, pois o servidor \u00e9 tido como um dos mais brilhantes da Casa. Como exemplo, senadores costumam lembrar que ele chegou \u00e0 Secretaria-Geral do Senado quando tinha apenas 34 anos.<\/p>\n<p><strong>Jantar<\/strong> &#8211; A diretora-geral do Senado, Ilana Trombka, tamb\u00e9m nomeada quando Renan presidia a Casa, \u00e9 outra que deve ser substitu\u00edda. \u00c9 atribu\u00edda a ela a organiza\u00e7\u00e3o de um jantar para 200 pessoas na resid\u00eancia oficial, regado a whisky e espumante, no dia da elei\u00e7\u00e3o.<\/p>\n<p>Como nenhum dos demais candidatos foi avisado, a suspeita \u00e9 de que o convescote seria para Renan, at\u00e9 ent\u00e3o considerado favorito na disputa. A diretoria-geral justificou que se trata de uma praxe do Senado organizar o evento para o vencedor, seja ele quem for.<\/p>\n<p>Ilana chegou ao cargo pouco depois da queda de Agaciel Maia, o ent\u00e3o todo-poderoso diretor-geral do Senado, chamado de o 82.\u00ba senador. Agaciel foi demitido no rastro do esc\u00e2ndalo dos atos secretos no Senado, revelado pelo Estado, no qual ele omitia dos boletins do Senado nomea\u00e7\u00f5es de apadrinhados de senadores.<\/p>\n<p>As apostas na Casa s\u00e3o de que a caneta de Alcolumbre pode se voltar ainda contra aliados da ex-governadora do Maranh\u00e3o Roseana Sarney. \u00c9 o caso, por exemplo, da diretora de Transpar\u00eancia do Senado, Elga Maria Teixeira, que trabalhou em campanhas da filha de Jos\u00e9 Sarney.<\/p>\n<p>At\u00e9 mesmo interlocutores do ministro Gilmar Mendes, do Supremo Tribunal Federal, podem acabar perdendo espa\u00e7o. O diretor de Assuntos T\u00e9cnicos e Jur\u00eddicos do Senado, Luciano Fel\u00edcio Fuck, \u00e9 considerado um &#8220;bra\u00e7o direito&#8221; do magistrado por ter sido seu chefe de gabinete e secret\u00e1rio-geral do Tribunal Superior Eleitoral (TSE). Ele foi indicado para o posto em fevereiro de 2018, durante a gest\u00e3o de Eun\u00edcio Oliveira.<\/p>\n<p>O novo comando do Senado tamb\u00e9m vai passar um pente-fino em todos os atos assinados na gest\u00e3o anterior. No apagar das luzes, por exemplo, Eun\u00edcio, que n\u00e3o se reelegeu, estendeu a todos os ex-senadores a permiss\u00e3o para que fa\u00e7am tratamento de sa\u00fade sem limite de gastos. O benef\u00edcio valia at\u00e9 ent\u00e3o s\u00f3 para os com mandato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar do discurso de pacifica\u00e7\u00e3o adotado ap\u00f3s ser eleito presidente do Senado, Davi Alcolumbre (DEM-AP) prepara uma &#8220;faxina&#8221; em cargos de diretoria e coordenadoria da Casa controlados pelo MDB. O alvo s\u00e3o servidores apadrinhados por seus antecessores &#8211; Eun\u00edcio Oliveira (CE), Jos\u00e9 Sarney (AP) e Renan Calheiros (AL). O pr\u00f3prio Renan deve ser &#8220;demitido&#8221; por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202725"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202725\/revisions"}],"predecessor-version":[{"id":202728,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202725\/revisions\/202728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202726"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}