{"id":202755,"date":"2019-02-17T19:57:07","date_gmt":"2019-02-17T22:57:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202755"},"modified":"2019-02-18T06:32:59","modified_gmt":"2019-02-18T09:32:59","slug":"isso-e-uma-mentira-vou-recorrer-diz-lula-sobre-condenacao-no-sitio-de-atibaia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/isso-e-uma-mentira-vou-recorrer-diz-lula-sobre-condenacao-no-sitio-de-atibaia\/","title":{"rendered":"&#8216;Isso \u00e9 uma mentira. Vou recorrer&#8217;, diz Lula sobre nova condena\u00e7\u00e3o"},"content":{"rendered":"<p>&#8220;N\u00e3o reconhe\u00e7o a legitimidade dessa senten\u00e7a, sou inocente e, por isso, vou recorrer.&#8221; A declara\u00e7\u00e3o foi feita pelo ex-presidente Luiz In\u00e1cio Lula da Silva, ap\u00f3s ser intimado sobre sua nova condena\u00e7\u00e3o, a 12 anos e 11 meses de pris\u00e3o, na a\u00e7\u00e3o envolvendo o s\u00edtio em Atibaia. O petista assinou o documento \u00e0s 15h50 de sexta, 15.<\/p>\n<p>O ex-presidente foi sentenciado pelos crimes de corrup\u00e7\u00e3o ativa, passiva e lavagem de dinheiro por supostamente receber R$ 1 milh\u00e3o em propinas por meio de reformas no s\u00edtio, que est\u00e1 em nome de Fernando Bittar, filho do amigo de Lula e ex-prefeito de Campinas Jac\u00f3 Bittar. Segundo a senten\u00e7a, as obras foram custeadas pelas empreiteiras OAS, Odebrecht e Schahin.<\/p>\n<p>A pena, proferida pela ju\u00edza Gabriela Hardt \u00e9 maior do que a imposta pelo ex-juiz federal S\u00e9rgio Moro. Em julho de 2017, o ent\u00e3o magistrado da Lava Jato condenou o ex-presidente no caso triplex a 9 anos e seis meses de pris\u00e3o.<\/p>\n<p>Ao fim da senten\u00e7a, a magistrada mandou intimar os acusados sobre se queriam apresentar recurso. Lula afirmou que vai recorrer.<\/p>\n<p><strong>Propriedade<\/strong> &#8211; A ju\u00edza federal Gabriela Hardt afirmou que a fam\u00edlia do petista &#8220;usufruiu do im\u00f3vel como se dona fosse&#8221;. &#8220;Inclusive, em 2014, Fernando Bittar alegou que sua fam\u00edlia j\u00e1 n\u00e3o o frequentava com assiduidade, sendo este usado mais pela fam\u00edlia de Lula&#8221;, anotou a ju\u00edza. A magistrada afirmou, no entanto, que a a\u00e7\u00e3o penal n\u00e3o &#8220;passa pela propriedade formal do s\u00edtio&#8221;.<\/p>\n<p>Em senten\u00e7a, Hardt considerou que o valor de R$ 1 milh\u00e3o empregado por OAS, Schahine Odebrecht no S\u00edtio Santa B\u00e1rbara foram propinas em benef\u00edcio do ex-presidente. Ela ressalta que a den\u00fancia oferecida pela Opera\u00e7\u00e3o Lava Jato narra &#8220;reforma e decora\u00e7\u00e3o de instala\u00e7\u00f5es e benfeitorias&#8221; que teriam sido realizadas em benef\u00edcio de Luiz In\u00e1cio Lula da Silva e fam\u00edlia.<\/p>\n<p>&#8220;O registro da propriedade do im\u00f3vel em que realizadas tais reformas est\u00e1 em nome de Fernado Bittar, tamb\u00e9m r\u00e9u nos presentes autos, pois a ele imputado aux\u00edlio na oculta\u00e7\u00e3o e dissimula\u00e7\u00e3o do verdadeiro benefici\u00e1rio&#8221;, anotou.<\/p>\n<p>De acordo com a magistrada. &#8220;os propriet\u00e1rios dos dois im\u00f3veis s\u00e3o pessoas que possuem v\u00ednculo com a fam\u00edlia do ex-presidente, v\u00ednculo esse afirmado por todos os envolvidos&#8221;. &#8220;Ainda, as opera\u00e7\u00f5es contaram com a participa\u00e7\u00e3o do advogado Roberto Teixeira, pessoa tamb\u00e9m vinculada de forma pr\u00f3xima a Luiz In\u00e1cio Lula da Silva, sendo lavradas as duas escrituras pelo mesmo escrevente, em seu escrit\u00f3rio&#8221;.<\/p>\n<p>&#8220;Fato tamb\u00e9m incontroverso \u00e9 o uso frequente do s\u00edtio pela fam\u00edlia de Luiz In\u00e1cio Lula da Silva, sendo que, ao menos em alguns per\u00edodos, tamb\u00e9m resta incontroverso que a fam\u00edlia do ex-presidente chegou a us\u00e1-lo at\u00e9 mais do que a fam\u00edlia Bittar&#8221;, escreveu.<\/p>\n<p><strong>Depoimentos e alega\u00e7\u00f5es<\/strong> &#8211; Em interrogat\u00f3rio, Bumlai declarou n\u00e3o ter pago &#8220;nem um real&#8221;. O s\u00edtio de Atibaia est\u00e1 em nome do empres\u00e1rio Fernando Bittar, filho de Jac\u00f3 Bittar, amigo de longa data do ex-presidente.<\/p>\n<p>Em depoimento, Fernando Bittar negou que tenha pago a obra. &#8220;Eu n\u00e3o sei dizer se eles (Lula e Marisa) pagaram. Mas na minha cabe\u00e7a\u2026&#8221;<\/p>\n<p>Apontado por delatores como o homem de confian\u00e7a do ex-presidente que tocou a obra do s\u00edtio, o ex-seguran\u00e7a de Lula Rog\u00e9rio Aur\u00e9lio Pimentel afirmou ter sido o &#8220;capataz&#8221; das reformas no im\u00f3vel e confirmou os pagamentos da Odebrecht.<\/p>\n<p>Em alega\u00e7\u00f5es finais, a defesa do ex-assessor da Presid\u00eancia da Rep\u00fablica afirmou que se ele &#8220;n\u00e3o sabia sequer as quantias que continham nos envelopes, tampouco possa se esperar que soubesse de eventual origem il\u00edcita dos valores&#8221;.<\/p>\n<p>Na senten\u00e7a, Gabriela Hardt anotou que exige-se de um presidente da Rep\u00fablica &#8220;um comportamento exemplar&#8221;. &#8220;Luiz In\u00e1cio Lula da Silva responde a outras a\u00e7\u00f5es penais, inclusive perante este Ju\u00edzo, mas sem tr\u00e2nsito em julgado, motivo pelo qual deve ser considerado como sem antecedentes negativos. A culpabilidade \u00e9 elevada. O condenado recebeu vantagem indevida em decorr\u00eancia do cargo de Presidente da Rep\u00fablica, de quem se exige um comportamento exemplar enquanto maior mandat\u00e1rio da Rep\u00fablica&#8221;, afirmou.<\/p>\n<p>A ju\u00edza afirmou tamb\u00e9m &#8220;o esquema de corrup\u00e7\u00e3o sist\u00eamica criado tinha por objetivo tamb\u00e9m, de forma esp\u00faria, garantir a governabilidade e a manuten\u00e7\u00e3o&#8221; do PT no Poder.<\/p>\n<p>&#8220;O crime foi praticado em um esquema criminoso mais amplo no qual o pagamento de propinas havia se tornado rotina. Consequ\u00eancias tamb\u00e9m devem ser valoradas negativamente, pois o custo da propina foi repassado \u00e0 Petrobras, atrav\u00e9s da cobran\u00e7a de pre\u00e7o superior \u00e0 estimativa, ali\u00e1s propiciado pela corrup\u00e7\u00e3o, com o que a estatal ainda arcou com o preju\u00edzo no valor equivalente&#8221;, anotou.<\/p>\n<p>&#8220;Reputo pass\u00edvel de agravamento neste t\u00f3pico os motivos do crime, pois o esquema de corrup\u00e7\u00e3o sist\u00eamica criado tinha por objetivo tamb\u00e9m, de forma esp\u00faria, garantir a governabilidade e a manuten\u00e7\u00e3o do Partido no Poder.&#8221;<\/p>\n<p><strong>Petrobras<\/strong> &#8211; Ao sentenciar o ex-presidente Luiz In\u00e1cio Lula da Silva a 12 anos e 11 meses de pris\u00e3o por supostas propinas de R$ 1 milh\u00e3o referentes \u00e0s reformas do s\u00edtio em Atibaia, a ju\u00edza federal Gabriela Hardt afirmou que o petista tinha o papel de &#8220;dar suporte \u00e0 continuidade do esquema de corrup\u00e7\u00e3o havido na Petrobras&#8221;, ainda que n\u00e3o tenha sido &#8220;comprovada sua participa\u00e7\u00e3o espec\u00edfica em cada negocia\u00e7\u00e3o realizada nessas contrata\u00e7\u00f5es&#8221;.<\/p>\n<p>&#8220;Comprovado ainda que o r\u00e9u Luiz In\u00e1cio Lula da Silva teve participa\u00e7\u00e3o ativa neste esquema, tanto ao garantir o recebimento de valores para o caixa do partido ao qual vinculado, quanto recebendo parte deles em benef\u00edcio pr\u00f3prio. Tais verbas foram solicitadas e recebidas indevidamente em raz\u00e3o da fun\u00e7\u00e3o p\u00fablica por ele exercida, pouco importando pelo tipo penal se estas se deram parcialmente ap\u00f3s o final do exerc\u00edcio de seu mandato&#8221;, anotou.<\/p>\n<p>De acordo com a magistrada, o &#8220;fato de sua responsabilidade n\u00e3o ter sido apurada em auditorias internas ou externas da Petrobras, ou o fato das nomea\u00e7\u00f5es de Diretores passarem pelo crivo do Conselho da Administra\u00e7\u00e3o n\u00e3o afastam sua responsabilidade&#8221;. &#8220;Como j\u00e1 dito em outros julgamentos, auditorias s\u00e3o limitadas, e nem sequer identificaram \u00e0 \u00e9poca oportuna o grande esquema de corrup\u00e7\u00e3o j\u00e1 desvendado&#8221;.<\/p>\n<p><strong>A\u00e7\u00e3o<\/strong> &#8211; O s\u00edtio Santa B\u00e1rbara \u00e9 piv\u00f4 da terceira a\u00e7\u00e3o penal da Lava Jato, no Paran\u00e1, contra o ex-presidente &#8211; al\u00e9m de sua segunda condena\u00e7\u00e3o. O petista ainda \u00e9 acusado por corrup\u00e7\u00e3o e lavagem de dinheiro por supostas propinas da Odebrecht &#8211; um terreno que abrigaria o Instituto Lula e um apartamento vizinho ao que morava o ex-presidente em S\u00e3o Bernardo do Campo.<\/p>\n<p><strong>Pris\u00e3o<\/strong> &#8211; O ex-presidente j\u00e1 cumpre pena de 12 anos e um m\u00eas de pris\u00e3o no caso triplex, na sede da Pol\u00edcia Federal do Paran\u00e1, em Curitiba, desde 7 abril de 2018, por ordem do ent\u00e3o juiz federal S\u00e9rgio Moro.<\/p>\n<p>Lula foi sentenciado pelo Tribunal Regional Federal da 4\u00aa Regi\u00e3o pelos crimes de corrup\u00e7\u00e3o passiva e lavagem de dinheiro envolvendo suposta propina de R$ 2,2 milh\u00f5es da OAS referente \u00e0s reformas do im\u00f3vel.<\/p>\n<p><strong>Defesa de Lula<\/strong> &#8211; Com a palavra, o advogado Cristiano Zanin Martins, que defende o ex-presidente da Rep\u00fablica:<\/p>\n<p>&#8220;A defesa do ex-presidente Lula recorrer\u00e1 de mais uma decis\u00e3o condenat\u00f3ria proferida hoje (06\/02\/2019) pela 13\u00aa Justi\u00e7a Federal de Curitiba que atenta aos mais basilares par\u00e2metros jur\u00eddicos e refor\u00e7a o uso perverso das leis e dos procedimentos jur\u00eddicos para fins de persegui\u00e7\u00e3o pol\u00edtica, pr\u00e1tica que reputamos como &#8216;lawfare&#8217;.<\/p>\n<p>A senten\u00e7a segue a mesma linha da senten\u00e7a proferida pelo ex-juiz S\u00e9rgio Moro, que condenou Lula sem ele ter praticado qualquer ato de of\u00edcio vinculado ao recebimento de vantagens indevidas, vale dizer, sem ter praticado o crime de corrup\u00e7\u00e3o que lhe foi imputado. Uma vez mais a Justi\u00e7a Federal de Curitiba atribuiu responsabilidade criminal ao ex-presidente tendo por base uma acusa\u00e7\u00e3o que envolve um im\u00f3vel do qual ele n\u00e3o \u00e9 o propriet\u00e1rio, um &#8216;caixa geral&#8217; e outras narrativas acusat\u00f3rias referenciadas apenas por delatores generosamente beneficiados.<\/p>\n<p>A decis\u00e3o desconsiderou as provas de inoc\u00eancia apresentadas pela Defesa de Lula nas 1.643 p\u00e1ginas das alega\u00e7\u00f5es finais protocoladas h\u00e1 menos de um m\u00eas (07\/01\/2019) &#8211; com exaustivo exame dos 101 depoimentos prestados no curso da a\u00e7\u00e3o penal, laudos t\u00e9cnicos e documentos anexados aos autos. Chega-se ao ponto de a senten\u00e7a rebater genericamente a argumenta\u00e7\u00e3o da defesa de Lula fazendo refer\u00eancia a &#8216;depoimentos prestados por colaboradores e corr\u00e9us Leo Pinheiro e Jos\u00e9 Adelm\u00e1rio&#8217; (p. 114), como se fossem pessoas diferentes, o que evidencia o distanciamento dos fundamentos apresentados na senten\u00e7a da realidade.<\/p>\n<p>Ainda para evidenciar o absurdo da nova senten\u00e7a condenat\u00f3ria, registra-se que:<\/p>\n<p>&#8211; Lula foi condenado pelo &#8216;pelo recebimento de R$ 700 mil em vantagens indevidas da Odebrecht&#8217; mesmo a defesa tendo comprovado, por meio de laudo pericial elaborado a partir da an\u00e1lise do pr\u00f3prio sistema de contabilidade paralelo da Odebrecht, que tal valor foi sacado em proveito de um dos principais executivos do grupo Odebrecht (presidente do Conselho de Administra\u00e7\u00e3o); esse documento t\u00e9cnico (elaborado por auditor e perito com responsabilidade legal sobre o seu conte\u00fado) e comprovado por documentos do pr\u00f3prio sistema da Odebrecht foi descartado sob o censur\u00e1vel fundamento de que &#8216;esta \u00e9 uma an\u00e1lise contratada por parte da a\u00e7\u00e3o penal, buscando corroborar a tese defensiva&#8217; &#8211; como se toda demonstra\u00e7\u00e3o t\u00e9cnica apresentada no processo pela defesa n\u00e3o tivesse valor probat\u00f3rio;<\/p>\n<p>&#8211; Lula foi condenado pelo crime de corrup\u00e7\u00e3o passiva por afirmado &#8216;recebimento de R$ 170 mil em vantagens indevidas da OAS&#8217; no ano de 2014 quando ele n\u00e3o exercia qualquer fun\u00e7\u00e3o p\u00fablica e, a despeito do reconhecimento, j\u00e1 exposto, de que n\u00e3o foi identificado pela senten\u00e7a qualquer ato de of\u00edcio praticado pelo ex-presidente em benef\u00edcio das empreiteiras envolvidas no processo;<\/p>\n<p>&#8211; foi aplicada a Lula, uma vez mais, uma pena fora de qualquer par\u00e2metro das penas j\u00e1 aplicadas no \u00e2mbito da pr\u00f3pria Opera\u00e7\u00e3o Lava Jato &#8211; que segundo julgamento do TRF4 realizado em 2016, n\u00e3o precisa seguir as &#8216;regras gerais&#8217; &#8211; mediante fundamenta\u00e7\u00e3o ret\u00f3rica e sem a observ\u00e2ncia dos padr\u00f5es legalmente estabelecidos.<\/p>\n<p>Em 2016 a defesa demonstrou perante o Comit\u00ea de Direitos Humanos da ONU a ocorr\u00eancia de grosseiras viola\u00e7\u00f5es \u00e0s garantais fundamentais, inclusive no tocante \u00e0 aus\u00eancia de um julgamento justo, imparcial e independente. O conte\u00fado da senten\u00e7a condenat\u00f3ria proferida hoje somente confirma essa situa\u00e7\u00e3o e por isso ser\u00e1 levada ao conhecimento do Comit\u00ea, que poder\u00e1 julgar o comunicado ainda neste ano &#8211; e eventualmente auxiliar o pa\u00eds a restabelecer os direitos de Lula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;N\u00e3o reconhe\u00e7o a legitimidade dessa senten\u00e7a, sou inocente e, por isso, vou recorrer.&#8221; A declara\u00e7\u00e3o foi feita pelo ex-presidente Luiz In\u00e1cio Lula da Silva, ap\u00f3s ser intimado sobre sua nova condena\u00e7\u00e3o, a 12 anos e 11 meses de pris\u00e3o, na a\u00e7\u00e3o envolvendo o s\u00edtio em Atibaia. O petista assinou o documento \u00e0s 15h50 de sexta, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":190481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202755"}],"version-history":[{"count":8,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202755\/revisions"}],"predecessor-version":[{"id":202800,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202755\/revisions\/202800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/190481"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}