{"id":202764,"date":"2019-02-17T21:25:45","date_gmt":"2019-02-18T00:25:45","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202764"},"modified":"2019-02-17T21:29:55","modified_gmt":"2019-02-18T00:29:55","slug":"exercito-reage-usp-recua-e-aceita-alunos-militares","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/exercito-reage-usp-recua-e-aceita-alunos-militares\/","title":{"rendered":"Ex\u00e9rcito reage, USP recua e aceita alunos militares"},"content":{"rendered":"<p>A Universidade de S\u00e3o Paulo voltou atr\u00e1s e resolveu confirmar a matr\u00edcula de candidatos de col\u00e9gios militares efetivamente mantidos pelas For\u00e7as Armadas que foram aprovados no vestibular da institui\u00e7\u00e3o. A decis\u00e3o da USP de vetar estudantes de escolas militares aprovados por meio do Sisu mobilizou o Comando do Ex\u00e9rcito e o Minist\u00e9rio da Educa\u00e7\u00e3o. A corpora\u00e7\u00e3o identificou na medida da USP uma retalia\u00e7\u00e3o ao governo de Jair Bolsonaro.<\/p>\n<p>Em nota, a USP comunicou que, &#8220;face \u00e0s afirma\u00e7\u00f5es que se tornaram p\u00fablicas e para garantir a lisura de seu processo de matr\u00edcula, todos os candidatos aprovados oriundos de col\u00e9gios militares, vinculados e mantidos efetivamente pelas For\u00e7as Armadas, que se inscreveram no vestibular optando pela a\u00e7\u00e3o afirmativa para egressos de escolas p\u00fablicas, tiveram a sua matr\u00edcula aceita, uma vez que atendem plenamente ao regramento estabelecido para o concurso vestibular 2019&#8221;.<\/p>\n<p>A Universidade explicou ainda que este ano decidiu analisar &#8220;caso a caso&#8221; as matr\u00edculas relativas a este p\u00fablico em virtude de questionamentos recebidos pela Comiss\u00e3o de Acompanhamento do Vestibular da institui\u00e7\u00e3o. Segundo a nota, havia informa\u00e7\u00f5es que davam conta da exist\u00eancia de institui\u00e7\u00f5es denominadas militares, mas que, na verdade, seriam administradas por entidades privadas e mantidas por mensalidades.<\/p>\n<p>&#8220;Por essa raz\u00e3o, os candidatos aprovados no vestibular, oriundos de escolas militares, tiveram a sua matr\u00edcula analisada caso a caso. Os poucos casos de indeferimento de matr\u00edcula est\u00e3o em an\u00e1lise, em fun\u00e7\u00e3o de recursos apresentados&#8221;, diz a USP no comunicado. Quando da publica\u00e7\u00e3o da reportagem semana passada, a Pr\u00f3-Reitoria de Gradua\u00e7\u00e3o da USP havia alegado que as 12 escolas mantidas pelo Ex\u00e9rcito n\u00e3o se enquadrariam no sistema de cotas por serem mantidas por contribui\u00e7\u00f5es e quotas mensais pagas por pais de alunos.<\/p>\n<p>Na reuni\u00e3o fechada no campus que se estendeu ao longo da tarde da quinta, um representante do Comando do Sudeste, sediado em S\u00e3o Paulo, tentou convencer dirigentes da universidade a reverter a decis\u00e3o, que afeta mais de 20 alunos, nas contas do Ex\u00e9rcito, ou dez, na estimativa da USP.<\/p>\n<p>O governador de S\u00e3o Paulo, Jo\u00e3o Doria, foi acionado pelo Comando Militar do Sudeste, pois a universidade \u00e9 mantida pelo Estado. Ao mesmo tempo, os militares telefonaram para Bras\u00edlia. Uma opera\u00e7\u00e3o foi deflagrada \u00e0 noite na capital federal pelos militares. O ministro da Educa\u00e7\u00e3o, Ricardo V\u00e9lez Rodriguez, tamb\u00e9m foi chamado e entrou para interferir a favor dos alunos.<\/p>\n<p><strong>Matr\u00edcula<\/strong> &#8211; Na quinta-feira, a universidade enviou e-mail aos estudantes para informar sobre o cancelamento da matr\u00edcula dos aprovados no concurso de acesso da institui\u00e7\u00e3o por meio das cotas de escolas p\u00fablicas. Numa mensagem obtida pela reportagem, a universidade informa a um aluno aprovado no curso de Medicina que cancelou sua matr\u00edcula para n\u00e3o \u201cburlar\u201d a \u201cfinalidade das pol\u00edticas de inclus\u00e3o\u201d.<\/p>\n<p>O texto foi elaborado pela Comiss\u00e3o para o Monitoramento Operacional do Processo de Ingresso. O pr\u00f3-reitor de Gradua\u00e7\u00e3o, Edmund Chada Baracat, assinou a mensagem.<\/p>\n<p>Procurada na ocasi\u00e3o, a dire\u00e7\u00e3o da Universidade de S\u00e3o Paulo afirmou que o caso dos alunos ainda estava sob avalia\u00e7\u00e3o.<\/p>\n<p>Ainda durante a reuni\u00e3o, o representante do Ex\u00e9rcito lembrou que, em outubro do ano passado, o Supremo Tribunal Federal (STF) entendeu que os col\u00e9gios militares s\u00e3o escolas do ensino oficial. Um documento preparado pela dire\u00e7\u00e3o do Comando do Sudeste citou que o plen\u00e1rio do Supremo julgou, por unanimidade, improcedente uma A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 5082 contra a cobran\u00e7a de contribui\u00e7\u00e3o obrigat\u00f3ria nos col\u00e9gios militares.<\/p>\n<p>O relator, ministro Edson Fachin, considerou que essas contribui\u00e7\u00f5es n\u00e3o configuram ofensa \u00e0 regra constitucional da gratuidade do ensino e ratificou as escolas mantidas pelo Ex\u00e9rcito como estabelecimentos do ensino oficial.<\/p>\n<p>Os militares afirmam que a medida da USP se trata de uma atitude in\u00e9dita no Pa\u00eds, pois o Ex\u00e9rcito nunca encontrou barreira semelhante por parte de outras institui\u00e7\u00f5es.<\/p>\n<p>As aulas na universidade come\u00e7am nesta segunda, 18, e os alunos aprovados e &#8216;desmatriculados&#8217; estavam sendo prejudicados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Universidade de S\u00e3o Paulo voltou atr\u00e1s e resolveu confirmar a matr\u00edcula de candidatos de col\u00e9gios militares efetivamente mantidos pelas For\u00e7as Armadas que foram aprovados no vestibular da institui\u00e7\u00e3o. A decis\u00e3o da USP de vetar estudantes de escolas militares aprovados por meio do Sisu mobilizou o Comando do Ex\u00e9rcito e o Minist\u00e9rio da Educa\u00e7\u00e3o. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-202764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202764"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202764\/revisions"}],"predecessor-version":[{"id":202770,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202764\/revisions\/202770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202765"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}