{"id":202817,"date":"2019-02-18T06:55:57","date_gmt":"2019-02-18T09:55:57","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202817"},"modified":"2019-02-18T07:45:43","modified_gmt":"2019-02-18T10:45:43","slug":"seu-eu-sair-sera-uma-injustica-desabafa-bebianno","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/seu-eu-sair-sera-uma-injustica-desabafa-bebianno\/","title":{"rendered":"&#8216;Seu eu sair, ser\u00e1 uma injusti\u00e7a&#8217;, desabafa Bebianno"},"content":{"rendered":"<p>Era um homem abatido. O ministro da Secretaria-Geral da Presid\u00eancia, Gustavo Bebianno, deixou no come\u00e7o da tarde deste domingo, 17, o hotel em que reside e se isolou desde o in\u00edcio da crise pol\u00edtica para almo\u00e7ar. Ele passou uma hora e meia com amigos pr\u00f3ximos numa mesa do Tejo, restaurante de comida portuguesa na Asa Sul, no Plano Piloto.<\/p>\n<p>Na sa\u00edda, Bebianno relatou que ainda tenta \u201cequalizar\u201d todo o processo que dever\u00e1 resultar na sua exonera\u00e7\u00e3o do cargo. Cort\u00eas, tirou selfie com um eleitor e disse que n\u00e3o era hora de comentar o assunto.<\/p>\n<p><strong>Quais os pr\u00f3ximos passos do senhor?<\/strong><\/p>\n<p>O tempo \u00e9 o senhor da raz\u00e3o. Vou falar depois. Por ora, vou ficar quieto, acalmar minha cabe\u00e7a. Quem sofre uma injusti\u00e7a dessas n\u00e3o fica com a cabe\u00e7a boa. Antes dos meus interesses, pode parecer clich\u00ea, mas n\u00e3o \u00e9, estavam os interesses do Pa\u00eds. Trabalhei, fiz o que fiz por garra, n\u00e3o foi por emprego ou para ganhar dinheiro.<\/p>\n<p><strong>O senhor trabalhou nos \u00faltimos dois anos para eleger o presidente&#8230;<\/strong><\/p>\n<p>N\u00e3o sou perfeito, mas (abaixa a cabe\u00e7a)&#8230;<\/p>\n<p><strong>O senhor fez alguma coisa que tenha levado o presidente a optar pela sua sa\u00edda?<\/strong><\/p>\n<p>Absolutamente nada. Zero.<\/p>\n<p><strong>H\u00e1 uma injusti\u00e7a?<\/strong><\/p>\n<p>100%. O presidente sabe.<\/p>\n<p><strong>Sabe?<\/strong><\/p>\n<p>Sabe, n\u00e3o \u00e9 maluco.<\/p>\n<p><strong>Qual a posi\u00e7\u00e3o do senhor em rela\u00e7\u00e3o ao vereador Carlos Bolsonaro? Ele passou dos limites?<\/strong><\/p>\n<p>Vou falar depois que sair. Na hora certinha eu falo. Estou equalizando a minha cabe\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era um homem abatido. O ministro da Secretaria-Geral da Presid\u00eancia, Gustavo Bebianno, deixou no come\u00e7o da tarde deste domingo, 17, o hotel em que reside e se isolou desde o in\u00edcio da crise pol\u00edtica para almo\u00e7ar. Ele passou uma hora e meia com amigos pr\u00f3ximos numa mesa do Tejo, restaurante de comida portuguesa na Asa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202817"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202817\/revisions"}],"predecessor-version":[{"id":202819,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202817\/revisions\/202819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202818"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}