{"id":202847,"date":"2019-02-18T13:44:42","date_gmt":"2019-02-18T16:44:42","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202847"},"modified":"2019-02-18T14:08:53","modified_gmt":"2019-02-18T17:08:53","slug":"de-vargas-a-collor-parentes-criaram-crises-no-governo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/de-vargas-a-collor-parentes-criaram-crises-no-governo\/","title":{"rendered":"De Vargas a Collor, parentes criaram crises no governo"},"content":{"rendered":"<p>O envolvimento de um dos filhos do presidente Jair Bolsonaro em quest\u00f5es relacionadas ao governo federal n\u00e3o \u00e9 um epis\u00f3dio in\u00e9dito na recente pol\u00edtica brasileira. O vereador do Rio de Janeiro, Carlos Bolsonaro, deu in\u00edcio publicamente \u00e0 crise no Pal\u00e1cio do Planalto, ap\u00f3s acusar o ministro da Secretaria-Geral da Presid\u00eancia da Rep\u00fablica, Gustavo Bebianno, de mentir a respeito de sua rela\u00e7\u00e3o com o presidente.<\/p>\n<p>Bebianno deve ser exonerado nesta segunda, 18, contra a vontade de alas pol\u00edtica e militar do governo. Ele promete &#8220;n\u00e3o poupar&#8221; Carlos em seus pr\u00f3ximos relatos, garantindo que os fatos de que tem conhecimento devem respingar no presidente.<\/p>\n<p>Confira casos em que familiares de ex-presidentes brasileiros iniciaram uma crise no governo:<\/p>\n<p><strong>Get\u00falio e o irm\u00e3o Bejo<\/strong> &#8211; O fato que culminou na crise do segundo governo de Get\u00falio Vargas (1951-1954), e posteriormente no seu suic\u00eddio, em 24 de agosto de 1954, tem rela\u00e7\u00e3o direta com um de seus irm\u00e3os, Bejo (Benjamin) Vargas.<\/p>\n<p>O jornalista e ent\u00e3o vereador do Distrito Federal pela Uni\u00e3o Democr\u00e1tica Nacional (UDN), Carlos Lacerda, era um dos principais oposicionistas do governo, al\u00e9m de fazer uso do seu jornal, Tribuna da Imprensa, para criticar Get\u00falio Vargas. Em 5 de agosto de 1954, Lacerda foi uma das v\u00edtimas do atentado da rua Toneleros, local da sua resid\u00eancia no Rio de Janeiro. O major-aviador Rubens Vaz, que fazia a seguran\u00e7a de Lacerda, foi morto nessa data, enquanto o vereador levou um tiro no p\u00e9.<\/p>\n<p>Lacerda insinuou que o presidente estaria envolvido no atentado. Posteriormente, as investiga\u00e7\u00f5es apontaram que os mandantes do crime teriam sido o chefe da guarda pessoal de Vargas, Greg\u00f3rio Fortunato, e Bejo Vargas. O filho mais velho de Get\u00falio, Lutero Vargas, chegou a ser mencionado pelo atirador em um dos inqu\u00e9ritos, mas nunca foi indiciado. A crise no governo aumentou, levando o presidente a tirar a pr\u00f3pria vida.<\/p>\n<p><strong>Jango e Brizola<\/strong> &#8211; \u00c9 comum atribuir ao pol\u00edtico ga\u00facho Leonel Brizola um dos motivos pela ascens\u00e3o do regime militar em 1964. Casado com Neusa Goulart, seu cunhado na \u00e9poca, Jo\u00e3o Goulart, era presidente do Brasil. Desde a posse de Jango, em 1961, ap\u00f3s a ren\u00fancia de J\u00e2nio Quadros, ele era visto como uma &#8220;amea\u00e7a comunista&#8221; ao Pa\u00eds. Esse argumento quase impediu que Jango, eleito vice de J\u00e2nio, assumisse o cargo, como prev\u00ea a legisla\u00e7\u00e3o.<\/p>\n<p>Brizola rompeu rela\u00e7\u00f5es com Jango em 1963, quando tentava se candidatar para o cargo no Minist\u00e9rio da Economia, em meio a uma crise econ\u00f4mica. Ele acreditava que o governo federal deveria se alinhar somente com partidos de esquerda, a fim de evitar radicalmente a mobiliza\u00e7\u00e3o dos militares, enquanto Jango tentava articular rela\u00e7\u00f5es menos extremistas, com partidos n\u00e3o alinhados completamente \u00e0 pauta da esquerda.<\/p>\n<p>As declara\u00e7\u00f5es p\u00fablicas de Brizola defendendo tanto uma revolu\u00e7\u00e3o, quanto o fechamento do Congresso Nacional menos de um m\u00eas antes da derrubada de Jango, agravaram ainda mais a situa\u00e7\u00e3o. Jango e Brizola se exilaram no Uruguai ap\u00f3s a instaura\u00e7\u00e3o do governo militar.<\/p>\n<p><strong>Fernando e o irm\u00e3o Pedro<\/strong> &#8211; Em entrevista \u00e0 Revista Veja em maio de 1992, o irm\u00e3o do ent\u00e3o presidente Fernando Collor de Mello, Pedro Collor de Mello, revelou detalhes de um esquema de corrup\u00e7\u00e3o articulado pelo presidente e pelo ex-tesoureiro de sua campanha, Paulo C\u00e9sar Farias. Ele acusou o tesoureiro de ser o &#8220;testa de ferro&#8221; do presidente.<\/p>\n<p>Den\u00fancias de desvio de dinheiro p\u00fablico para beneficiamento pr\u00f3prio por parte do presidente j\u00e1 haviam sido iniciadas antes, mas foi a partir do depoimento de Pedro que o Congresso Nacional instalou uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) para apurar a rela\u00e7\u00e3o dos neg\u00f3cios de PC Farias com o governo federal. Contas fantasma sob o nome das empresas de PC Farias, relacionadas ao governo, eram utilizadas para os desvios e para pagamentos.<\/p>\n<p>A C\u00e2mara dos Deputados abre o processo de impeachment de Fernando Collor em setembro de 1992. Collor \u00e9 afastado do cargo, e antes do Senado votar o impeachment, ele renuncia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O envolvimento de um dos filhos do presidente Jair Bolsonaro em quest\u00f5es relacionadas ao governo federal n\u00e3o \u00e9 um epis\u00f3dio in\u00e9dito na recente pol\u00edtica brasileira. O vereador do Rio de Janeiro, Carlos Bolsonaro, deu in\u00edcio publicamente \u00e0 crise no Pal\u00e1cio do Planalto, ap\u00f3s acusar o ministro da Secretaria-Geral da Presid\u00eancia da Rep\u00fablica, Gustavo Bebianno, de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202847"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202847\/revisions"}],"predecessor-version":[{"id":202849,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202847\/revisions\/202849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202848"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}