{"id":202869,"date":"2019-02-18T17:23:38","date_gmt":"2019-02-18T20:23:38","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202869"},"modified":"2019-02-18T17:23:38","modified_gmt":"2019-02-18T20:23:38","slug":"bolsonaro-vai-atravessar-rua-para-entregar-reforma-ao-congresso","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-vai-atravessar-rua-para-entregar-reforma-ao-congresso\/","title":{"rendered":"Bolsonaro vai atravessar rua para entregar reforma ao Congresso"},"content":{"rendered":"<p>O secret\u00e1rio especial de Previd\u00eancia e Trabalho, Rog\u00e9rio Marinho, afirmou nesta segunda-feira, 18, que o presidente Jair Bolsonaro vai entregar pessoalmente a proposta de reforma da Previd\u00eancia ao Congresso Nacional na quarta-feira, 20, quando haver\u00e1 entrevista coletiva para detalhar os pontos do texto. O secret\u00e1rio n\u00e3o informou o hor\u00e1rio da entrevista nem quem estar\u00e1 presente. Marinho se reuniu nesta segunda com o ministro da Economia, Paulo Guedes.<\/p>\n<p>Questionado sobre a articula\u00e7\u00e3o pol\u00edtica para a aprova\u00e7\u00e3o da reforma, Marinho respondeu &#8220;isso \u00e9 com o Onyx&#8221;, em refer\u00eancia ao ministro-chefe da Casa Civil, Onyx Lorenzoni. O secret\u00e1rio especial tem tido reuni\u00f5es com diversos parlamentares nas \u00faltimas semanas, de acordo com sua agenda.<\/p>\n<p>Segundo a assessoria de imprensa do Pal\u00e1cio do Planalto, o presidente discutiu com o secret\u00e1rio de comunica\u00e7\u00e3o, Floriano Barbosa, a melhor forma de encaminhar o projeto ao Congresso.<\/p>\n<p>A ideia do Planalto \u00e9 que Bolsonaro &#8220;assuma&#8221; a defesa da proposta nas primeiras 48 horas ap\u00f3s apresent\u00e1-la ao Legislativo. Ele tamb\u00e9m deve fazer um pronunciamento \u00e0 na\u00e7\u00e3o sobre a mat\u00e9ria, mas ainda n\u00e3o est\u00e1 decidido se ser\u00e1 feito na TV aberta, que \u00e9 considerada a op\u00e7\u00e3o mais tradicional, ou atrav\u00e9s de uma transmiss\u00e3o ao vivo em redes sociais, como \u00e9 da prefer\u00eancia do presidente.<\/p>\n<p>Depois dos primeiros dois dias ap\u00f3s o texto chegar ao Congresso, a ideia \u00e9 que todos os pronunciamentos e esclarecimentos p\u00fablicos sobre o assunto sejam feitos exclusivamente pela equipe t\u00e9cnica do Minist\u00e9rio da Economia para n\u00e3o haver d\u00favidas. Neste caso, foram escalados o secret\u00e1rio de Previd\u00eancia, Rog\u00e9rio Marinho, e o secret\u00e1rio-ajunto, Leonardo Rolim, para a fun\u00e7\u00e3o.<\/p>\n<p>Na quarta-feira, 20, Bolsonaro tamb\u00e9m tem marcado um caf\u00e9 da manh\u00e3 com o PSL para tratar do assunto. O presidente ainda pode se reunir com governadores para discutir a proposta de reforma. O objetivo do Planalto \u00e9 que as tratativas sejam finalizadas at\u00e9 abril. Al\u00e9m disso, o governo pretende adotar um modelo de comunica\u00e7\u00e3o diferente do que foi feito pelo ex-presidente Michel Temer durante a sua gest\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio especial de Previd\u00eancia e Trabalho, Rog\u00e9rio Marinho, afirmou nesta segunda-feira, 18, que o presidente Jair Bolsonaro vai entregar pessoalmente a proposta de reforma da Previd\u00eancia ao Congresso Nacional na quarta-feira, 20, quando haver\u00e1 entrevista coletiva para detalhar os pontos do texto. O secret\u00e1rio n\u00e3o informou o hor\u00e1rio da entrevista nem quem estar\u00e1 presente. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":123707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202869"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202869\/revisions"}],"predecessor-version":[{"id":202870,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202869\/revisions\/202870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/123707"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}