{"id":202886,"date":"2019-02-19T02:23:43","date_gmt":"2019-02-19T05:23:43","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=202886"},"modified":"2019-02-19T06:28:37","modified_gmt":"2019-02-19T09:28:37","slug":"bolsonaro-segura-video-e-rompe-acordo-com-bebianno","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-segura-video-e-rompe-acordo-com-bebianno\/","title":{"rendered":"Bolsonaro &#8216;segura&#8217; v\u00eddeo e rompe acordo com Bebianno"},"content":{"rendered":"<p>A divulga\u00e7\u00e3o de um v\u00eddeo em que o presidente Jair Bolsonaro faz elogios p\u00fablicos a Gustavo Bebianno, demitido nesta segunda-feira, 18, do cargo de ministro da Secretaria-Geral da Presid\u00eancia atendeu, em parte, o acordo costurado para tentar apaziguar os \u00e2nimos. At\u00e9 o in\u00edcio da madrugada desta ter\u00e7a-feira, 19, a mensagem n\u00e3o havia sido publicada nas redes sociais do presidente, seu principal canal de comunica\u00e7\u00e3o, o que irritou o agora ex-ministro, segundo uma pessoa pr\u00f3xima.<\/p>\n<p>O combinado seria Bolsonaro post\u00e1-lo em suas redes sociais, agradecendo a \u201cdedica\u00e7\u00e3o e o comprometimento do senhor Bebianno\u201d. Foi uma estrat\u00e9gia acertada na \u00faltima hora, para evitar que o ex-auxiliar sa\u00edsse \u201catirando\u201d. O v\u00eddeo, por\u00e9m, foi distribu\u00eddo \u00e0 imprensa e a aliados do presidente por meio do WhatsApp.<\/p>\n<p>Para Bebianno, a divulga\u00e7\u00e3o no Twitter de Bolsonaro, que re\u00fane 3,3 milh\u00f5es de seguidores, era uma &#8220;quest\u00e3o de honra&#8221;, segundo este interlocutor. Foi pelo mesmo Twitter que o ent\u00e3o chefe da Secretaria-Geral da Presid\u00eancia foi chamado de &#8220;mentiroso&#8221; por Carlos Bolsonaro, filho do presidente. A acusa\u00e7\u00e3o foi endossada pelo pr\u00f3prio pai, que compartilhou a postagem de Carlos mais tarde.<\/p>\n<p>No v\u00eddeo divulgado a aliados, Bolsonaro usou um tom apaziguador, de tr\u00e9gua, para se referir ao ex-auxiliar, a quem chamou de \u201csenhor Gustavo Bebianno\u201d. \u201cComunico que desde a semana passada diferentes pontos de vista sobre quest\u00f5es relevantes trouxeram a necessidade de uma reavalia\u00e7\u00e3o\u201d, afirmou o presidente, sem especificar as diverg\u00eancias. \u201cAvalio que pode ter havido incompreens\u00f5es e quest\u00f5es mal entendidas de parte a parte, n\u00e3o sendo adequado prejulgamentos de qualquer natureza\u201d, completou ele, ao desejar a Bebianno \u201csucesso em sua nova jornada\u201d. Antes, o porta-voz da Presid\u00eancia, Ot\u00e1vio do R\u00eago Barros, disse que a exonera\u00e7\u00e3o do ministro ocorrera por \u201craz\u00f5es de foro \u00edntimo.\u201d<\/p>\n<p>Ex-coordenador da campanha de Bolsonaro e respons\u00e1vel por lev\u00e1-lo para o PSL, Bebianno caiu ap\u00f3s um ruidoso embate p\u00fablico com Carlos Bolsonaro. Na semana passada, o filho do presidente chamou o ent\u00e3o chefe da Secretaria-Geral de \u201cmentiroso\u201d por ele ter dito que havia conversado tr\u00eas vezes com Bolsonaro. Bebianno tentava com isso negar que estivesse isolado por causa de uma crise, mas foi desmentido por Carlos e pelo pr\u00f3prio presidente.<\/p>\n<p>O clima azedou de vez ap\u00f3s Bolsonaro ser informado de que o ministro deixara vazar para interlocutores mensagens de \u00e1udio com conversas privadas entre os dois. Antes disso, o nome de Bebianno tamb\u00e9m havia sido citado em den\u00fancias sobre um esquema de desvio de dinheiro do Fundo Eleitoral do PSL para patrocinar candidaturas laranjas, em 2018.<\/p>\n<p>\u201cAcho que a quest\u00e3o entre o presidente e o ministro Bebianno tem mais problemas do que a quest\u00e3o dos laranjas\u201d, afirmou nesta segunda-feira, 18, o vice-presidente Hamilton Mour\u00e3o. \u201cAgora vamos ver como colocar uma gaze \u00famida nessa queimadura de terceiro grau (no governo)\u201d, emendou a deputada Joice Hasselmann (PSL-SP), mostrando preocupa\u00e7\u00e3o com o impacto da crise sobre o Congresso.<\/p>\n<p>A \u201cfritura\u201d de um dos homens fortes do governo se arrastou por dias. Para evitar que a instabilidade contaminasse vota\u00e7\u00f5es priorit\u00e1rias para o governo no Congresso, como a reforma da Previd\u00eancia, ministros do n\u00facleo pol\u00edtico, militares e at\u00e9 Maia tentaram convencer Bolsonaro a manter Bebianno no cargo.<\/p>\n<p>O plano n\u00e3o surtiu efeito e os \u201cbombeiros\u201d pol\u00edticos fizeram de tudo para construir uma \u201csa\u00edda negociada\u201d, que n\u00e3o deixasse o ex-ministro na \u201cchuva\u201d. Emiss\u00e1rios do presidente chegaram a oferecer a Bebianno \u2013 que comandou o PSL em 2018 \u2013 uma diretoria de Itaipu Binacional e at\u00e9 uma embaixada em Roma ou em Portugal, para que ele sa\u00edsse do Brasil. Bebianno, por\u00e9m, n\u00e3o aceitou. \u201cTudo o que fiz foi por garra, n\u00e3o foi por emprego ou para ganhar dinheiro\u201d, disse o ex-ministro ao Estado. \u201cO tempo \u00e9 o senhor da raz\u00e3o\u201d.<\/p>\n<p>O receio de auxiliares de Bolsonaro \u00e9 de que, mesmo com os agradecimentos feitos pelo presidente, Bebianno seja o que no jarg\u00e3o pol\u00edtico se chama de \u201chomem-bomba\u201d e aja para detonar o governo e o filho do presidente. A oposi\u00e7\u00e3o, por exemplo, vai convid\u00e1-lo para prestar depoimento.<\/p>\n<p>\u201cPreciso pedir desculpas ao Brasil por ter viabilizado a candidatura de Bolsonaro. Nunca imaginei que ele seria um presidente t\u00e3o fraco\u201d, afirmou Bebianno a interlocutores.<\/p>\n<p><strong>\u00c1udio<\/strong> &#8211; Na pr\u00e1tica, a gota d\u2019\u00e1gua que levou \u00e0 demiss\u00e3o do ministro \u2013 assinada no fim de semana, mas s\u00f3 anunciada ontem \u2013 foi a divulga\u00e7\u00e3o de um \u00e1udio de WhatsApp no qual o presidente dizia a ele que n\u00e3o queria \u201caproxima\u00e7\u00e3o\u201d com a TV Globo.<\/p>\n<p>O epis\u00f3dio ocorreu na \u00faltima ter\u00e7a-feira, quando Bolsonaro, ainda internado no Hospital Albert Einstein, mandou o ent\u00e3o ministro suspender uma audi\u00eancia que teria com o vice-presidente de Rela\u00e7\u00f5es Institucionais do Grupo Globo, Paulo Tonet Carvalho.<\/p>\n<p>\u201cComo voc\u00ea coloca nossos inimigos dentro de casa?\u201d, perguntou ele a Bebianno, segundo o site Poder 360. Para Bolsonaro, a divulga\u00e7\u00e3o do \u00e1udio foi uma \u201cdeslealdade\u201d. Um interlocutor do presidente confirmou o teor da mensagem ao Estado.<\/p>\n<p>Bebianno deve ficar ainda em Bras\u00edlia nos pr\u00f3ximos dias. A um interlocutor, o ex-ministro teria dito que teme por sua seguran\u00e7a. Ele continua recebendo amea\u00e7as pelo seu n\u00famero de WhatsApp e disse que j\u00e1 identificou algumas pessoas. Nesta ter\u00e7a-feira, ele ainda deve se encontrar com o atual presidente do PSL, Luciano Bivar (PE).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A divulga\u00e7\u00e3o de um v\u00eddeo em que o presidente Jair Bolsonaro faz elogios p\u00fablicos a Gustavo Bebianno, demitido nesta segunda-feira, 18, do cargo de ministro da Secretaria-Geral da Presid\u00eancia atendeu, em parte, o acordo costurado para tentar apaziguar os \u00e2nimos. At\u00e9 o in\u00edcio da madrugada desta ter\u00e7a-feira, 19, a mensagem n\u00e3o havia sido publicada nas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-202886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=202886"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202886\/revisions"}],"predecessor-version":[{"id":202890,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/202886\/revisions\/202890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202887"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=202886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=202886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=202886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}