{"id":203275,"date":"2019-02-22T12:11:00","date_gmt":"2019-02-22T15:11:00","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203275"},"modified":"2019-02-22T12:33:03","modified_gmt":"2019-02-22T15:33:03","slug":"nova-previdencia-fica-parada-ate-entrada-dos-militares","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/nova-previdencia-fica-parada-ate-entrada-dos-militares\/","title":{"rendered":"Nova Previd\u00eancia fica parada at\u00e9 entrada dos militares"},"content":{"rendered":"<p>Um dia ap\u00f3s chegar ao Congresso, a proposta de reforma da Previd\u00eancia de Jair Bolsonaro j\u00e1 enfrenta resist\u00eancias e pode ficar em banho-maria caso o governo n\u00e3o envie logo o projeto de lei que endurece as regras dos militares.<\/p>\n<p>A decis\u00e3o de deixar o encaminhamento do projeto para daqui a um m\u00eas desagradou aos deputados. &#8220;\u00c9 preocupante. O governo tem de enviar o mais r\u00e1pido poss\u00edvel para n\u00e3o atrapalhar a reforma&#8221;, afirmou Mauro Benevides Filho (PDT-CE). Segundo o deputado, um dos cotados para presidir a comiss\u00e3o especial que vai discutir e votar o texto, h\u00e1 um movimento geral para segurar a tramita\u00e7\u00e3o na espera das novas regras para os militares. Entre os pontos que devem ser alterados, est\u00e1 o aumento do tempo m\u00ednimo de contribui\u00e7\u00e3o de 30 anos para 35 anos.<\/p>\n<p>Para o l\u00edder do PSL na C\u00e2mara, Delegado Waldir (GO), o governo ter\u00e1 de ser r\u00e1pido para n\u00e3o deixar a impress\u00e3o de que os militares ter\u00e3o tratamento diferenciado. &#8220;Eu defendo essa mesma tese (de agilizar para n\u00e3o ter resist\u00eancia). Tem de trazer todos juntos, n\u00e3o podemos tratar de forma separada. Independentemente de o qu\u00f3rum ser menor (para militares), temos de conhecer os dois textos para saber que o tratamento est\u00e1 sendo igualit\u00e1rio.&#8221;<\/p>\n<p>&#8220;Os deputados est\u00e3o curiosos para ver de que forma o governo vai tratar os militares, j\u00e1 que ele foi t\u00e3o duro com o trabalhador rural e o benef\u00edcio para idosos&#8221;, criticou o l\u00edder do DEM na C\u00e2mara, o deputado Elmar Nascimento (BA). Na sua avalia\u00e7\u00e3o, a mudan\u00e7a no benef\u00edcio para idosos de baixa renda n\u00e3o passa no Congresso do jeito que est\u00e1.<\/p>\n<p>Press\u00e3o &#8216;em casa&#8217;. O campo minado da proposta elaborada pela equipe do ministro da Economia, Paulo Guedes, tamb\u00e9m come\u00e7ou a ser formado entre os aliados mais pr\u00f3ximos do governo. O filho mais velho do presidente, senador Fl\u00e1vio Bolsonaro (PSL-RJ), postou no Twitter a necessidade de inclus\u00e3o dos guardas municipais nas mesmas regras de policiais, que t\u00eam aposentadoria diferenciada dos demais servidores. Segundo Fl\u00e1vio, guardas municipais tamb\u00e9m s\u00e3o agentes de seguran\u00e7a e exercem profiss\u00e3o de risco.<\/p>\n<p>O deputado Delegado Waldir tamb\u00e9m \u00e9 a favor da inclus\u00e3o. O l\u00edder do PSL na C\u00e2mara adiantou que vai trabalhar no recolhimento de assinaturas para apresentar uma emenda que inclua os guardas municipais na regra especial de policiais, que permite aposentadoria com 55 anos. Sem serem inclu\u00eddos na categoria especial, precisam cumprir as idades de 65 anos (homens) e 62 anos (mulheres).<\/p>\n<p>&#8220;\u00c9 um lapso que foi cometido&#8221;, afirmou o Delegado Waldir. O deputado argumenta que os guardas municipais andam armados e, por isso, precisam de tratamento diferenciado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dia ap\u00f3s chegar ao Congresso, a proposta de reforma da Previd\u00eancia de Jair Bolsonaro j\u00e1 enfrenta resist\u00eancias e pode ficar em banho-maria caso o governo n\u00e3o envie logo o projeto de lei que endurece as regras dos militares. A decis\u00e3o de deixar o encaminhamento do projeto para daqui a um m\u00eas desagradou aos deputados. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":155821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-203275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203275"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203275\/revisions"}],"predecessor-version":[{"id":203276,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203275\/revisions\/203276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/155821"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}