{"id":203352,"date":"2019-02-23T16:23:58","date_gmt":"2019-02-23T19:23:58","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203352"},"modified":"2019-02-23T17:57:54","modified_gmt":"2019-02-23T20:57:54","slug":"maduro-rompe-com-colombia-e-expulsa-corpo-diplomatico","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/maduro-rompe-com-colombia-e-expulsa-corpo-diplomatico\/","title":{"rendered":"Maduro rompe com Col\u00f4mbia e expulsa corpo diplom\u00e1tico"},"content":{"rendered":"<p>O presidente da Venezuela, Nicolas Maduro, divulgou um comunicado neste s\u00e1bado, 22, em meio aos protestos em curso na fronteira venezuelano-colombiana, dizendo que &#8220;governa a Venezuela e continuar\u00e1 governando&#8221;.<\/p>\n<p>&#8220;Estou firme como nunca antes, firme como esta \u00e1rvore, governando este pa\u00eds agora e em muitos anos [pr\u00f3ximos]&#8221;, disse Maduro dirigindo-se a seus seguidores.<\/p>\n<p>Maduro tamb\u00e9m afirmou que a Venezuela cortou rela\u00e7\u00f5es diplom\u00e1ticas com a Col\u00f4mbia e expulsou todos os diplomatas de sua embaixada.<\/p>\n<p>A oposi\u00e7\u00e3o venezuelana tenta garantir a entrega de ajuda humanit\u00e1ria, o que resulta em confrontos com a pol\u00edcia nas fronteiras do pa\u00eds com a Col\u00f4mbia e o Brasil.<\/p>\n<p>As for\u00e7as de seguran\u00e7a venezuelanas montaram guarda na cidade fronteiri\u00e7a de Ure\u00f1a depois que o governo de Maduro ordenou o fechamento tempor\u00e1rio da fronteira com a Col\u00f4mbia.<\/p>\n<p>Nos \u00faltimos dias, o governo venezuelano adotou uma s\u00e9rie de medidas para impedir que a ajuda humanit\u00e1ria chegue ao pa\u00eds. Segundo Maduro, os EUA e seus aliados usavam &#8220;o pretexto de fornecer ajuda humanit\u00e1ria&#8221; para tentar &#8220;destruir a independ\u00eancia e a soberania do pa\u00eds&#8221;.<\/p>\n<p>Caracas n\u00e3o permitiria tal ajuda ao pa\u00eds, disse Maduro, dizendo que o pa\u00eds estava lidando com suas dificuldades e que as &#8220;preocupa\u00e7\u00f5es&#8221; dos EUA com a crise humanit\u00e1ria da Venezuela foram &#8220;fabricadas por Washington nos \u00faltimos quatro anos para justificar a interven\u00e7\u00e3o em nosso pa\u00eds&#8221;.<\/p>\n<p>Al\u00e9m de fechar a fronteira com o Brasil e tr\u00eas pontes que ligam a Col\u00f4mbia e a Venezuela, o vice-presidente do pa\u00eds, Delcy Rodriguez, disse que o pa\u00eds latino-americano fecharia a fronteira com na\u00e7\u00f5es insulares vizinhas, suspenderia o tr\u00e1fego a\u00e9reo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Venezuela, Nicolas Maduro, divulgou um comunicado neste s\u00e1bado, 22, em meio aos protestos em curso na fronteira venezuelano-colombiana, dizendo que &#8220;governa a Venezuela e continuar\u00e1 governando&#8221;. &#8220;Estou firme como nunca antes, firme como esta \u00e1rvore, governando este pa\u00eds agora e em muitos anos [pr\u00f3ximos]&#8221;, disse Maduro dirigindo-se a seus seguidores. Maduro tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[95],"class_list":["post-203352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203352"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203352\/revisions"}],"predecessor-version":[{"id":203358,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203352\/revisions\/203358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/203353"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}