{"id":203479,"date":"2019-02-25T12:43:41","date_gmt":"2019-02-25T15:43:41","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203479"},"modified":"2019-02-25T12:45:49","modified_gmt":"2019-02-25T15:45:49","slug":"bolsonaro-esta-seguro-a-aguia-pousou-no-palacio","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/","title":{"rendered":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio"},"content":{"rendered":"<p>Uma ave desperta preocupa\u00e7\u00e3o na capital federal. \u201c\u00c1guia se aproxima\u201d, diz um seguran\u00e7a do Planalto para os colegas pelo sistema de r\u00e1dio. \u201c\u00c1guia vai sair agora\u201d, informa outro. O grupo de agentes que faz a escolta do presidente Jair Bolsonaro s\u00f3 relaxa quando ele entra no Alvorada, resid\u00eancia oficial, para descansar: \u201c\u00c1guia no ninho. Miss\u00e3o cumprida. Ok?\u201d<\/p>\n<p>Codinome de Bolsonaro usado pelos seguran\u00e7as, a \u00e1guia j\u00e1 foi s\u00edmbolo da Presid\u00eancia quando os chefes do Executivo despachavam no Pal\u00e1cio do Catete, no Rio, uma constru\u00e7\u00e3o com est\u00e1tuas da ave no telhado.<\/p>\n<p>Uma foto de Juscelino Kubitschek (1956-1961) no heliponto do pr\u00e9dio e na frente das asas de uma das aves do telhado do pal\u00e1cio marcou o governo do presidente \u201cvoador\u201d. Com a transfer\u00eancia da capital para Bras\u00edlia, as emas do Alvorada desbancaram a temida ave de rapina. Depois de generais \u201csisudos\u201d e civis \u201cespont\u00e2neos\u201d ocuparem o poder, a \u00e1guia est\u00e1 de volta \u00e0 simbologia da Presid\u00eancia da Rep\u00fablica.<\/p>\n<p>N\u00e3o h\u00e1 uma regra para a escolha do apelido pelos seguran\u00e7as do pal\u00e1cio. O ex-presidente Luiz In\u00e1cio Lula da Silva era o \u201cEclipse\u201d \u2013 \u201co tempo fechava sempre\u201d, relataram antigos agentes que atuam no Planalto. J\u00e1 a presidente cassada Dilma Rousseff era chamada de \u201cCristal\u201d \u2013 \u201cse cair, quebra\u201d, lembraram.<\/p>\n<p>No Planalto, o comportamento da \u201c\u00c1guia\u201d tem sido motivo de apreens\u00e3o. A preocupa\u00e7\u00e3o, segundo auxiliares, \u00e9 com o que consideram \u201cexcesso de informalidade\u201d do presidente e com quest\u00f5es de seguran\u00e7a.<\/p>\n<p>Embora seja oriundo do Ex\u00e9rcito e tenha redobrado o cuidado com sua prote\u00e7\u00e3o pessoal ap\u00f3s o atentado a faca que sofreu durante ato de campanha em Juiz de Fora (MG), em setembro passado, Bolsonaro n\u00e3o suportou muitos dias o ostensivo sistema de seguran\u00e7a ao chegar a Bras\u00edlia.<\/p>\n<p>Ainda no governo de transi\u00e7\u00e3o, ele mandou dispensar os batedores da Pol\u00edcia Militar que abriam o tr\u00e2nsito para sua comitiva e diminuir o n\u00famero de agentes da Pol\u00edcia Federal na sua escolta. Assim que assumiu o poder, a guarda dele, por norma antiga, passou para o Gabinete de Seguran\u00e7a Institucional (GSI), sendo feita por militares do Ex\u00e9rcito.<\/p>\n<p>Um amigo do presidente disse \u00e0 reportagem que a equipe de seguran\u00e7a n\u00e3o esconde a preocupa\u00e7\u00e3o quando Bolsonaro para na portaria do Alvorada para cumprimentar simpatizantes ou, nos aeroportos, ao entrar ou sair do carro, dar a m\u00e3o para os batedores ou para o \u201ccara do tratorzinho do avi\u00e3o\u201d. \u201cEle est\u00e1 tentando manter a autenticidade dele\u201d, avaliou. \u201cVai acabar entendendo que ter\u00e1 de chegar a um meio-termo, mas n\u00e3o vai ser amarrado.\u201d<\/p>\n<p>As quebras de protocolo na Presid\u00eancia, comuns nos governos de Itamar Franco (1992-1994) e, principalmente, de Lula, foram interpretadas neste in\u00edcio de governo \u2013 at\u00e9 por aliados pr\u00f3ximos de Bolsonaro \u2013 como quebra da \u201cliturgia do cargo\u201d, termo usado por Jos\u00e9 Sarney (1985-1990) para se referir \u00e0s regras do cerimonial e do comportamento de um titular da Presid\u00eancia da Rep\u00fablica.<\/p>\n<p><strong>Chinelo e camiseta<\/strong> &#8211; Na semana passada, auxiliares pediram \u00e0 exaust\u00e3o que Bolsonaro \u201creavaliasse\u201d sua postura. Ele foi aconselhado a evitar o uso de chinelo e camisa de futebol em cerim\u00f4nia oficial \u2013 o presidente vestiu uma camisa do Palmeiras no evento de apresenta\u00e7\u00e3o da reforma da Previd\u00eancia \u2013, a abandonar de vez o Twitter e a separar quest\u00f5es familiares de assuntos de governo.<\/p>\n<p>Para esses auxiliares, Bolsonaro \u201c\u00e9 um presidente que insiste em n\u00e3o se adaptar \u00e0 estrutura do pal\u00e1cio\u201d \u2013 batizada por pol\u00edticos e jornalistas, ainda nos anos 1970, como a \u201cm\u00e1quina de fazer presidentes\u201d. Ao ocupar nos primeiros dias de janeiro o gabinete do terceiro andar do Planalto, Bolsonaro n\u00e3o aceitou, por exemplo, o telefone criptografado entregue pelo GSI. Quando tentou us\u00e1-lo, percebeu que o modelo s\u00f3 permitia liga\u00e7\u00f5es para quem tinha um outro igual.<\/p>\n<p>At\u00e9 agora, ele tamb\u00e9m reluta em deixar as redes sociais. H\u00e1 poucas semanas, assinou decreto que passa a movimenta\u00e7\u00e3o de suas contas no Twitter e no Facebook para uma Assessoria Especial do pal\u00e1cio. O grupo, como mostrou o Estado, era formado por indicados de seu filho Carlos Bolsonaro, que, na campanha, foi respons\u00e1vel pela \u00e1rea digital e, agora, exerce influ\u00eancia na Secretaria de Comunica\u00e7\u00e3o (Secom), dirigida pelo publicit\u00e1rio Floriano Barbosa de Amorim, homem de confian\u00e7a da fam\u00edlia.<\/p>\n<p><strong>Telefone<\/strong> &#8211; Intercepta\u00e7\u00f5es e divulga\u00e7\u00e3o de conversas telef\u00f4nicas causam temor no governo. As primeiras crises do mandato de Bolsonaro ocorreram ap\u00f3s telefonemas particulares virem a p\u00fablico. A equipe do general Augusto Heleno, chefe do GSI, pouco poderia fazer, observaram assessores do Planalto, j\u00e1 que, em um dos epis\u00f3dios, foi Carlos quem divulgou \u00e1udio da conversa do pai com o ent\u00e3o ministro da Secretaria-Geral, Gustavo Bebianno. Depois da exonera\u00e7\u00e3o de Bebianno, outros \u00e1udios vazaram.<\/p>\n<p>Nos \u00faltimos dias, Bolsonaro indicou que vai usar apenas o telefone criptografado cedido pela Ag\u00eancia Brasileira de Intelig\u00eancia (Abin) para conversar com alguns ministros e o entorno palaciano. Mas continuar\u00e1, vez ou outra, recorrendo ao telefone aberto.<\/p>\n<p>O esfor\u00e7o de tentar \u201cmoldar\u201d o presidente op\u00f5e assessores que conhecem a estrutura do Planalto e a fam\u00edlia Bolsonaro. O que \u00e9 considerado defeito para os conhecedores da vida palaciana \u00e9 \u201ccompromisso de campanha\u201d para o deputado Eduardo Bolsonaro (PSL-SP). \u201cOs \u00e1udios vazados s\u00f3 comprovaram que @jairbolsonaro \u00e9 o mesmo em p\u00fablico e na vida particular\u201d, escreveu no Twitter na sexta-feira passada.<\/p>\n<p>Depois que um \u00e1udio de uma conversa entre Bolsonaro e o ministro-chefe da Casa Civil, Onyx Lorenzoni, foi ouvido por um jornalista, segundo o Pal\u00e1cio do Planalto, por \u201cacidente\u201d, assessores avaliam como \u201caperfei\u00e7oar o sistema de comunica\u00e7\u00e3o\u201d do governo.<\/p>\n<p>Questionada sobre que medidas de seguran\u00e7a seriam adotadas, a assessoria do GSI afirmou que \u201ca vulnerabilidade ser\u00e1 apurada e corrigida\u201d. \u201cPor motivos \u00f3bvios, n\u00e3o \u00e9 o caso de divulgar as medidas que ser\u00e3o tomadas e a rotina de comunica\u00e7\u00e3o do presidente da Rep\u00fablica e demais autoridades\u201d, informou o gabinete.<\/p>\n<p>Al\u00e9m de aprimorar a comunica\u00e7\u00e3o, auxiliares tentam conter o que consideram \u201cexcesso de informalidade\u201d de Bolsonaro em conversas. Palavr\u00f5es, dizem, lembram o ex-presidente Lula e irrita\u00e7\u00e3o remete a Fernando Collor e a Dilma Rousseff.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma ave desperta preocupa\u00e7\u00e3o na capital federal. \u201c\u00c1guia se aproxima\u201d, diz um seguran\u00e7a do Planalto para os colegas pelo sistema de r\u00e1dio. \u201c\u00c1guia vai sair agora\u201d, informa outro. O grupo de agentes que faz a escolta do presidente Jair Bolsonaro s\u00f3 relaxa quando ele entra no Alvorada, resid\u00eancia oficial, para descansar: \u201c\u00c1guia no ninho. Miss\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"tmauthors":[],"class_list":["post-203479","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","tag-capa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras\" \/>\n<meta property=\"og:description\" content=\"Uma ave desperta preocupa\u00e7\u00e3o na capital federal. \u201c\u00c1guia se aproxima\u201d, diz um seguran\u00e7a do Planalto para os colegas pelo sistema de r\u00e1dio. \u201c\u00c1guia vai sair agora\u201d, informa outro. O grupo de agentes que faz a escolta do presidente Jair Bolsonaro s\u00f3 relaxa quando ele entra no Alvorada, resid\u00eancia oficial, para descansar: \u201c\u00c1guia no ninho. Miss\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-25T15:43:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-25T15:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"932\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio\",\"datePublished\":\"2019-02-25T15:43:41+00:00\",\"dateModified\":\"2019-02-25T15:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/\"},\"wordCount\":1070,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/aguia-bolsonaro.jpg\",\"keywords\":[\"capa\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/\",\"name\":\"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/aguia-bolsonaro.jpg\",\"datePublished\":\"2019-02-25T15:43:41+00:00\",\"dateModified\":\"2019-02-25T15:45:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/aguia-bolsonaro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/aguia-bolsonaro.jpg\",\"width\":932,\"height\":621},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/","og_locale":"pt_BR","og_type":"article","og_title":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras","og_description":"Uma ave desperta preocupa\u00e7\u00e3o na capital federal. \u201c\u00c1guia se aproxima\u201d, diz um seguran\u00e7a do Planalto para os colegas pelo sistema de r\u00e1dio. \u201c\u00c1guia vai sair agora\u201d, informa outro. O grupo de agentes que faz a escolta do presidente Jair Bolsonaro s\u00f3 relaxa quando ele entra no Alvorada, resid\u00eancia oficial, para descansar: \u201c\u00c1guia no ninho. Miss\u00e3o [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-02-25T15:43:41+00:00","article_modified_time":"2019-02-25T15:45:49+00:00","og_image":[{"width":932,"height":621,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio","datePublished":"2019-02-25T15:43:41+00:00","dateModified":"2019-02-25T15:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/"},"wordCount":1070,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg","keywords":["capa"],"articleSection":["Brasil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/","url":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/","name":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg","datePublished":"2019-02-25T15:43:41+00:00","dateModified":"2019-02-25T15:45:49+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/02\/aguia-bolsonaro.jpg","width":932,"height":621},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-esta-seguro-a-aguia-pousou-no-palacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Bolsonaro est\u00e1 seguro. A \u00e1guia pousou no Pal\u00e1cio"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203479"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203479\/revisions"}],"predecessor-version":[{"id":203483,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203479\/revisions\/203483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/203480"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203479"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=203479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}