{"id":203491,"date":"2019-02-25T16:29:28","date_gmt":"2019-02-25T19:29:28","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203491"},"modified":"2019-02-25T16:51:16","modified_gmt":"2019-02-25T19:51:16","slug":"bolsonaro-reune-militares-para-discutir-crise-na-venezuela","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-reune-militares-para-discutir-crise-na-venezuela\/","title":{"rendered":"Bolsonaro re\u00fane militares para discutir crise na Venezuela"},"content":{"rendered":"<p>A situa\u00e7\u00e3o na fronteira do Brasil com a Venezuela foi assunto de reuni\u00e3o hoje (25), no Pal\u00e1cio do Planalto, entre o presidente Jair Bolsonaro, o ministro da Defesa, Fernando Azevedo e Silva, e os quatro comandantes das For\u00e7as Armadas.<\/p>\n<p>O encontro ocorreu ap\u00f3s um fim de semana de tens\u00e3o e conflitos em Pacaraima, Roraima, na fronteira\u200b do Brasil\u200b com a Venezuela, e a tentativa frustrada de envio de ajuda humanit\u00e1ria do governo federal ao pa\u00eds vizinho, que enfrenta crise de abastecimento.<\/p>\n<p>\u200bAo deixar o Pal\u00e1cio do Planalto\u200b, o\u200b chefe de Log\u00edstica e Mobiliza\u00e7\u00e3o do Ex\u00e9rcito, general Laerte de Souza Santos, \u200bdisse que a ajuda humanit\u00e1ria do Brasil pro\u200bssegue na fronteira, por meio da Opera\u00e7\u00e3o Acolhida\u200b.<\/p>\n<p>Al\u00e9m de Azevedo, estiveram na reuni\u00e3o os comandantes da Marinha, almirante Ilques Barbosa J\u00fanior; do Ex\u00e9rcito, general Edson Leal Pujol; da Aeron\u00e1utica, tenente-brigadeiro Antonio Carlos Moretti Bermudez; e do Estado-Maior Conjunto das For\u00e7as Armadas, interino, almirante Cl\u00e1udio Portugal de Viveiros.<\/p>\n<p>Enquanto isso, o vice-presidente da Rep\u00fablica, Hamilton Mour\u00e3o, e o ministro das Rela\u00e7\u00f5es Exteriores, Ernesto Ara\u00fajo, est\u00e3o em Bogot\u00e1, na Col\u00f4mbia. Eles participam de encontro do Grupo de Lima, formado por pa\u00edses das Am\u00e9ricas para tratar do acirramento da crise na Venezuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A situa\u00e7\u00e3o na fronteira do Brasil com a Venezuela foi assunto de reuni\u00e3o hoje (25), no Pal\u00e1cio do Planalto, entre o presidente Jair Bolsonaro, o ministro da Defesa, Fernando Azevedo e Silva, e os quatro comandantes das For\u00e7as Armadas. O encontro ocorreu ap\u00f3s um fim de semana de tens\u00e3o e conflitos em Pacaraima, Roraima, na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203492,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-203491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203491"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203491\/revisions"}],"predecessor-version":[{"id":203493,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203491\/revisions\/203493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/203492"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}